{"id":737,"date":"2024-03-06T00:17:00","date_gmt":"2024-03-05T23:17:00","guid":{"rendered":"https:\/\/expoflamenco.com\/revistanew\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/"},"modified":"2024-03-06T00:17:00","modified_gmt":"2024-03-05T23:17:00","slug":"con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas","status":"publish","type":"post","link":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/","title":{"rendered":"Con una copla de m\u00e1s (XIII): el cautiverio en las coplas flamencas","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<p>En la historia de la Literatura es constante el uso del s\u00edmbolo, especialmente en poes\u00eda. Con este, las palabras parecen no significar lo que aparentan a primera vista. As\u00ed, una c\u00e1rcel o estar preso puede no querer decir estar efectivamente entre rejas, sin libertad f\u00edsica, sino metaf\u00f3rica, simb\u00f3lica, figuradamente, s\u00f3lo estar enamorado. Qu\u00e9 gracia rebosan estos versos, alt\u00edsimo piropo, ingenioso como pocos \u2013recogidos por Dem\u00f3filo (sic)\u2013:<\/p>\n<p>&nbsp;<\/p>\n<p><em>Tengo de ti mir agrabios,<\/em><br \/>\n<em>Y te he de mandar prend\u00e9\u2026<\/em><br \/>\n<em>En la carse e mis brasos,<\/em><br \/>\n<em>Que en otra no pu\u00e9e s\u00e9.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>La que sigue, sole\u00e1 de tres versos, reitera el s\u00edmbolo de la c\u00e1rcel de amor. Es una copla o letra tambi\u00e9n muy ingeniosa, y otro piropo, claro. En el fondo, una declaraci\u00f3n solemne de amor, fina como pocas:<\/p>\n<p>&nbsp;<\/p>\n<p><em>Tu ventana es una c\u00e1rcel<\/em><br \/>\n<em>con el carcelero dentro<\/em><br \/>\n<em>y el prisionero en la calle.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>En algunas aparece el t\u00e9rmino \u201ccautivo\u201d para referirse a una determinada situaci\u00f3n. El diccionario nos dice que este t\u00e9rmino, \u201ccautivo\u201d, procede del lat\u00edn \u201ccapt\u012bvus\u201d y significa: 1. adj. Dicho de una persona: Hecha prisionera en la guerra. U. t. c. s. Era usado referido especialmente al cristiano apresado por los infieles. 2. adj. Dicho de un animal: Privado de libertad. 3. adj. desus. cativo (\u2016 infeliz, desgraciado).<\/p>\n<p>&nbsp;<\/p>\n<p>Tom\u00f3 este \u00faltimo sentido de \u201cdesdichado\u201d en el siglo XIII, y de ah\u00ed, en el <strong>Quijote<\/strong>, el de \u201cmalvado\u201d. Su acepci\u00f3n m\u00e1s com\u00fan es la de \u201caprisionado en la guerra\u201d, aplicado sobre todo o particularmente a los cristianos hechos prisioneros por los infieles. El t\u00e9rmino \u201ccautivo\u201d se us\u00f3 much\u00edsimo en la literatura morisca de los siglos XV al XVII, con este sentido comentado. El mismo Cervantes fue cautivo en Argel (por cierto, parece que pronto tendremos una pel\u00edcula sobre Cervantes basada en su per\u00edodo de cautiverio, titulada precisamente <em>El Cautivo<\/em>, dirigida por el magistral <strong>Alejandro Amen\u00e1bar<\/strong>. Ojal\u00e1 le apeteciera hacer alguna otra sobre los flamencos y flamencas de post\u00edn y con una buena historia detr\u00e1s. Hoy cautivo o cautivar es inusual, apenas usado en contextos cultos o en expresiones concretas con un sentido figurado, como \u201ccautivar o atraer la atenci\u00f3n\u201d. Estas explicaciones creo que permiten entender mejor esta copla:<\/p>\n<p>&nbsp;<\/p>\n<p><em>Los lamentos de un cautivo<\/em><br \/>\n<em>no pueden llegar a Espa\u00f1a,<\/em><br \/>\n<em>porque est\u00e1 la mar por medio<\/em><br \/>\n<em>y se ahogan en el agua.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>En este enlace la canta <strong>Pepe Marchena<\/strong> por soleares con la guitarra de <strong>Ram\u00f3n Montoya<\/strong>, dos grandes del flamenco:<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"jeg_video_container jeg_video_content\"><iframe title=\"Los Lamentos de un Cautivo \/ Que Delante Me la Pongan (feat. Ram\u00f3n Montoya) (Soleares)\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/qGGxO5ODisY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p>O esta otra recogida por Dem\u00f3filo con esta ortograf\u00eda, una tremenda maldici\u00f3n:<\/p>\n<p>&nbsp;<\/p>\n<p><em>Aquer que tiene la curpa&nbsp;<\/em><br \/>\n<em>E que yo fatigas pase,<\/em><br \/>\n<em>Se bea en Arg\u00e9 cautibo<\/em><br \/>\n<em>Sin ten\u00e9 ning\u00fan rescate.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Se parece a esta otra que escuchamos en la voz de <strong>Antonio Mairena<\/strong> por sole\u00e1, del canal de YouTube \u201cAntonio Mairena oficial\u201d, donde comentan: \u201cEstas dos soleares son los dos estilos m\u00e1s conocidos del gran m\u00fasico gaditano que fue <strong>Enrique El Mellizo<\/strong>. En esta ocasi\u00f3n Mairena se inspira en los modos de <strong>Manuel Torre<\/strong>. La primera letra ya la grab\u00f3, adem\u00e1s por el mismo estilo, el propio Manuel Torre (1929). Dicha copla viene as\u00ed en <em>Cantares de Castilla<\/em> (n\u00ba 220): \u201cAquel que tuvo la culpa \/ de nuestra separaci\u00f3n \/ ojal\u00e1 se le cayeran \/ las alas del coraz\u00f3n\u201d. Y de forma similar en la Colecci\u00f3n de cantes flamencos, que edit\u00f3 Dem\u00f3filo en 1881: \u201cAquer que la curpa tiene \/ que fatigas pase yo \/ er coras\u00f3n por la boca \/ se le sarga de dol\u00f3\u201d. Como ton\u00e1 se rese\u00f1a en el n\u00famero del 15 de enero de 1887 de la revista El Cante\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"jeg_video_container jeg_video_content\"><iframe title=\"Antonio Mairena por soleares. Grabaci\u00f3n en T\u00e1nger, 1944\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/qjzmd7vqzRw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p>Precisamente cautivo, o Cautivo, es la palabra que se usa asociada a <strong>Cristo<\/strong>, a <strong>Jes\u00fas<\/strong>, en las saetas, un palo a palo seco, a capella, del flamenco, circunscrito a un tiempo concreto, la Semana Santa, que adquiere en la calle, frente a las im\u00e1genes de los pasos, su verdadero sentido. Escuchamos una saeta en este enlace, <strong>Manuel Mairena<\/strong>, premio Saeta de Oro, gran cantaor de la casa de los Mairena, canta en la iglesia de San Juan de Palma (Sevilla), en el programa de la Exaltaci\u00f3n de la Saeta de 1996:<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"jeg_video_container jeg_video_content\"><iframe title=\"Saeta. Manuel Mairena. 1996\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/4M_u_vONBSQ?start=2&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p>El gran investigador <strong>Jos\u00e9 Luis Ortiz Nuevo<\/strong>, el Poeta de Archidona, recoge varias letras de tema carcelario en su imprescindible libro <em>Pensamiento pol\u00edtico en el cante flamenco<\/em> (1985). En alguna se usa el t\u00e9rmino que comentamos:<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00bfDe qu\u00e9 le sirve al cautivo<\/em><br \/>\n<em>Tener los grillos de plata,<\/em><br \/>\n<em>Y las cadenitas de oro,<\/em><br \/>\n<em>Si la libertad le falta?<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Seguiremos acerc\u00e1ndonos a estos asuntos del cautiverio, del encarcelamiento, la privaci\u00f3n de libertad que en las letras del cante aparece como una de las mayores calamidades.<\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>\u2192&nbsp;&nbsp;<a href=\"https:\/\/expoflamenco.com\/prensa\/author\/josecenizo\/\" target=\"_blank\" rel=\"noopener\">Ver aqu\u00ed los art\u00edculos anteriores&nbsp;de Jos\u00e9 Cenizo.<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>Una c\u00e1rcel o estar preso puede no querer decir estar efectivamente entre rejas, sin libertad f\u00edsica, sino metaf\u00f3rica, simb\u00f3lica, figuradamente, s\u00f3lo estar enamorado.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":24,"featured_media":738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"footnotes":""},"categories":[162,94],"tags":[224,225,195,226],"class_list":["post-737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-con-una-copla-de-mas","category-firmas","tag-cautiverio-en-el-flamenco","tag-coplas-flamencas","tag-flamenco","tag-letras-flamencas-sobre-carcel","pmpro-has-access"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Una c\u00e1rcel o estar preso puede no querer decir estar efectivamente entre rejas, sin libertad f\u00edsica, sino metaf\u00f3rica, simb\u00f3lica, figuradamente, s\u00f3lo estar enamorado.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Jos\u00e9 Cenizo\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\\\/#blogposting\",\"name\":\"Con una copla de m\\u00e1s (XIII): el cautiverio en las coplas flamencas - Revista ExpoFlamenco\",\"headline\":\"Con una copla de m\\u00e1s (XIII): el cautiverio en las coplas flamencas\",\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/josecenizo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2026\\\/01\\\/expoflamenco-coplas-de-carcel-o-prision-foto-ye-jinghan-unsplash.jpg\",\"width\":1300,\"height\":800},\"datePublished\":\"2024-03-06T00:17:00+01:00\",\"dateModified\":\"2024-03-06T00:17:00+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\\\/#webpage\"},\"articleSection\":\"Con una copla de m\\u00e1s, Firmas, cautiverio en el flamenco, coplas flamencas, flamenco, letras flamencas sobre carcel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista#listItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/#listItem\",\"name\":\"Firmas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/#listItem\",\"position\":2,\"name\":\"Firmas\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/con-una-copla-de-mas\\\/#listItem\",\"name\":\"Con una copla de m\\u00e1s\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista#listItem\",\"name\":\"Hogar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/con-una-copla-de-mas\\\/#listItem\",\"position\":3,\"name\":\"Con una copla de m\\u00e1s\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/con-una-copla-de-mas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\\\/#listItem\",\"name\":\"Con una copla de m\\u00e1s (XIII): el cautiverio en las coplas flamencas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/#listItem\",\"name\":\"Firmas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\\\/#listItem\",\"position\":4,\"name\":\"Con una copla de m\\u00e1s (XIII): el cautiverio en las coplas flamencas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/con-una-copla-de-mas\\\/#listItem\",\"name\":\"Con una copla de m\\u00e1s\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\",\"name\":\"Revista ExpoFlamenco\",\"description\":\"Revista ExpoFlamenco\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/josecenizo\\\/#author\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/josecenizo\\\/\",\"name\":\"Jos\\u00e9 Cenizo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\\\/#authorImage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/jose-cenizo-120px.jpg\",\"width\":96,\"height\":96,\"caption\":\"Jos\\u00e9 Cenizo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\\\/#webpage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\\\/\",\"name\":\"Con una copla de m\\u00e1s (XIII): el cautiverio en las coplas flamencas - Revista ExpoFlamenco\",\"description\":\"Una c\\u00e1rcel o estar preso puede no querer decir estar efectivamente entre rejas, sin libertad f\\u00edsica, sino metaf\\u00f3rica, simb\\u00f3lica, figuradamente, s\\u00f3lo estar enamorado.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/josecenizo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/josecenizo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2026\\\/01\\\/expoflamenco-coplas-de-carcel-o-prision-foto-ye-jinghan-unsplash.jpg\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\\\/#mainImage\",\"width\":1300,\"height\":800},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\\\/#mainImage\"},\"datePublished\":\"2024-03-06T00:17:00+01:00\",\"dateModified\":\"2024-03-06T00:17:00+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/\",\"name\":\"Revista ExpoFlamenco\",\"description\":\"Revista ExpoFlamenco\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script>(function(w,d,s,l,i){w[l]=w[l]||[];w[l].push({'gtm.start': new Date().getTime(),event:'gtm.js'});var f=d.getElementsByTagName(s)[0], j=d.createElement(s),dl=l!='dataLayer'?'&l='+l:'';j.async=true;j.src='https:\/\/www.googletagmanager.com\/gtm.js?id='+i+dl;f.parentNode.insertBefore(j,f);})(window,document,'script','dataLayer',\"GTM-N28N9JJ\");<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Con una copla de m\u00e1s (XIII): el cautiverio en las coplas flamencas - Revista ExpoFlamenco<\/title>\n\n","aioseo_head_json":{"title":"Con una copla de m\u00e1s (XIII): el cautiverio en las coplas flamencas - Revista ExpoFlamenco","description":"Una c\u00e1rcel o estar preso puede no querer decir estar efectivamente entre rejas, sin libertad f\u00edsica, sino metaf\u00f3rica, simb\u00f3lica, figuradamente, s\u00f3lo estar enamorado.","canonical_url":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/#blogposting","name":"Con una copla de m\u00e1s (XIII): el cautiverio en las coplas flamencas - Revista ExpoFlamenco","headline":"Con una copla de m\u00e1s (XIII): el cautiverio en las coplas flamencas","author":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/josecenizo\/#author"},"publisher":{"@id":"https:\/\/expoflamenco.com\/revista\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/expoflamenco-coplas-de-carcel-o-prision-foto-ye-jinghan-unsplash.jpg","width":1300,"height":800},"datePublished":"2024-03-06T00:17:00+01:00","dateModified":"2024-03-06T00:17:00+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/#webpage"},"isPartOf":{"@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/#webpage"},"articleSection":"Con una copla de m\u00e1s, Firmas, cautiverio en el flamenco, coplas flamencas, flamenco, letras flamencas sobre carcel"},{"@type":"BreadcrumbList","@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista#listItem","position":1,"name":"Hogar","item":"https:\/\/expoflamenco.com\/revista","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/#listItem","name":"Firmas"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/#listItem","position":2,"name":"Firmas","item":"https:\/\/expoflamenco.com\/revista\/firmas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/con-una-copla-de-mas\/#listItem","name":"Con una copla de m\u00e1s"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista#listItem","name":"Hogar"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/con-una-copla-de-mas\/#listItem","position":3,"name":"Con una copla de m\u00e1s","item":"https:\/\/expoflamenco.com\/revista\/firmas\/con-una-copla-de-mas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/#listItem","name":"Con una copla de m\u00e1s (XIII): el cautiverio en las coplas flamencas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/#listItem","name":"Firmas"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/#listItem","position":4,"name":"Con una copla de m\u00e1s (XIII): el cautiverio en las coplas flamencas","previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/con-una-copla-de-mas\/#listItem","name":"Con una copla de m\u00e1s"}}]},{"@type":"Organization","@id":"https:\/\/expoflamenco.com\/revista\/#organization","name":"Revista ExpoFlamenco","description":"Revista ExpoFlamenco","url":"https:\/\/expoflamenco.com\/revista\/"},{"@type":"Person","@id":"https:\/\/expoflamenco.com\/revista\/author\/josecenizo\/#author","url":"https:\/\/expoflamenco.com\/revista\/author\/josecenizo\/","name":"Jos\u00e9 Cenizo","image":{"@type":"ImageObject","@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/#authorImage","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/2025\/01\/jose-cenizo-120px.jpg","width":96,"height":96,"caption":"Jos\u00e9 Cenizo"}},{"@type":"WebPage","@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/#webpage","url":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/","name":"Con una copla de m\u00e1s (XIII): el cautiverio en las coplas flamencas - Revista ExpoFlamenco","description":"Una c\u00e1rcel o estar preso puede no querer decir estar efectivamente entre rejas, sin libertad f\u00edsica, sino metaf\u00f3rica, simb\u00f3lica, figuradamente, s\u00f3lo estar enamorado.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/expoflamenco.com\/revista\/#website"},"breadcrumb":{"@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/#breadcrumblist"},"author":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/josecenizo\/#author"},"creator":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/josecenizo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/expoflamenco-coplas-de-carcel-o-prision-foto-ye-jinghan-unsplash.jpg","@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/#mainImage","width":1300,"height":800},"primaryImageOfPage":{"@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/#mainImage"},"datePublished":"2024-03-06T00:17:00+01:00","dateModified":"2024-03-06T00:17:00+01:00"},{"@type":"WebSite","@id":"https:\/\/expoflamenco.com\/revista\/#website","url":"https:\/\/expoflamenco.com\/revista\/","name":"Revista ExpoFlamenco","description":"Revista ExpoFlamenco","inLanguage":"es-ES","publisher":{"@id":"https:\/\/expoflamenco.com\/revista\/#organization"}}]}},"aioseo_meta_data":{"post_id":"737","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-07-14 16:25:43","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2026-01-15 15:32:17","updated":"2026-07-14 16:25:43"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\" title=\"Hogar\">Hogar<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\/firmas\/\" title=\"Firmas\">Firmas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\/firmas\/con-una-copla-de-mas\/\" title=\"Con una copla de m\u00e1s\">Con una copla de m\u00e1s<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tCon una copla de m\u00e1s (XIII): el cautiverio en las coplas flamencas\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Hogar","link":"https:\/\/expoflamenco.com\/revista"},{"label":"Firmas","link":"https:\/\/expoflamenco.com\/revista\/firmas\/"},{"label":"Con una copla de m\u00e1s","link":"https:\/\/expoflamenco.com\/revista\/firmas\/con-una-copla-de-mas\/"},{"label":"Con una copla de m\u00e1s (XIII): el cautiverio en las coplas flamencas","link":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xiii-el-cautiverio-en-las-coplas-flamencas\/"}],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/comments?post=737"}],"version-history":[{"count":0,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/737\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media\/738"}],"wp:attachment":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media?parent=737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/categories?post=737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/tags?post=737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}