{"id":5957,"date":"2026-03-13T10:59:06","date_gmt":"2026-03-13T09:59:06","guid":{"rendered":"https:\/\/expoflamenco.com\/revista\/?p=5957"},"modified":"2026-03-13T10:59:06","modified_gmt":"2026-03-13T09:59:06","slug":"diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente","status":"publish","type":"post","link":"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/","title":{"rendered":"Diez mil euros para la mejor saeta por seguiriyas en la Pe\u00f1a Buena Gente","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<p>No se recuerda un premio tan jugoso en lo que lleva de historia el <strong>Concurso Nacional de Saetas<\/strong> de la <strong>Pe\u00f1a Buena Gente<\/strong> como el de esta edici\u00f3n: <strong>diez mil euros para el Primer Premio<\/strong>, adem\u00e1s de otras dotaciones para los finalistas. La final se celebrar\u00e1 en la sede de la <a href=\"https:\/\/fundacioncajasol.com\/tag\/jerez\/\" target=\"_blank\" rel=\"noopener\">Fundaci\u00f3n Cajasol en Jerez<\/a>, el 28 de marzo a partir de las ocho y media de la tarde. \u201cY el fallo del jurado se dar\u00e1 a conocer luego en la propia pe\u00f1a, nos vendremos para ac\u00e1 a tomar algo y aqu\u00ed se anunciar\u00e1 entrada la madrugada\u201d, coment\u00f3 el presidente de la asociaci\u00f3n, <strong>Javier Mej\u00edas<\/strong>. \u201cHabr\u00e9is contratado seguridad, \u00bfno?\u201d, dijo en tono jocoso alguno de los que acudieron a la rueda de prensa de presentaci\u00f3n.<\/p>\n<p>Es una de las actividades m\u00e1s esperadas de cada Cuaresma y esta edici\u00f3n, la 47\u00aa, estar\u00e1 dedicada a <strong>la memoria del Ni\u00f1o Gloria<\/strong>. Los que deseen participar deben inscribirse en el correo <em>pfbuenagente@gmail.com<\/em> o en los tel\u00e9fonos 670 360 098 o 685 191 560, y la pe\u00f1a se reserva el derecho de pedir un v\u00eddeo que le permita hacer una criba para la fase de semifinales, que se presentar\u00e1n ante el jurado y ante el p\u00fablico que lo desee los d\u00edas 20 y 21 de marzo, en la propia pe\u00f1a de Plaza Basurto, a partir de las ocho y media de la tarde.<\/p>\n<p>El Segundo Premio est\u00e1 dotado con <strong>1.300 euros y placa<\/strong>, habr\u00e1 cuatro acc\u00e9sits (para cada finalista) de 800 euros y placa, y se premiar\u00e1 con 500 euros a <strong>la Saeta Joven<\/strong> de un int\u00e9rprete igual o menor a 25 a\u00f1os. Es importante resaltar la ausencia esta edici\u00f3n del premio Manuel Torre, uno de los grandes valores de este concurso, y esto es debido a que \u201cse valorar\u00e1 en general la mejor saeta por seguiriyas para el Primer Premio\u201d, por lo que ya carece de sentido. La noticia ha causado sensaci\u00f3n en gran parte del flamenco, ya que son muchos los saeteros de fuera de Jerez los que se han interesado por participar. En cambio, otros, m\u00e1s habituales, se plantean no formar parte del mismo por la gran expectaci\u00f3n causada y \u201clo mal que se pasa\u201d.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><em>\u00abNo se recuerda un premio tan jugoso en lo que lleva de historia el Concurso Nacional de Saetas de la Pe\u00f1a Buena Gente como el de esta edici\u00f3n: diez mil euros para el Primer Premio, adem\u00e1s de otras dotaciones para los finalistas. La final se celebra el 28 de marzo en la sede de la Fundaci\u00f3n Cajasol en Jerez\u00bb<\/em><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xlvii-concurso-nacional-de-saetas-pena-flamenca-buena-gente-2026.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-5960\" src=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xlvii-concurso-nacional-de-saetas-pena-flamenca-buena-gente-2026.jpeg\" alt=\"\" width=\"1280\" height=\"1600\" srcset=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xlvii-concurso-nacional-de-saetas-pena-flamenca-buena-gente-2026.jpeg 1280w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xlvii-concurso-nacional-de-saetas-pena-flamenca-buena-gente-2026-240x300.jpeg 240w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xlvii-concurso-nacional-de-saetas-pena-flamenca-buena-gente-2026-819x1024.jpeg 819w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xlvii-concurso-nacional-de-saetas-pena-flamenca-buena-gente-2026-768x960.jpeg 768w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xlvii-concurso-nacional-de-saetas-pena-flamenca-buena-gente-2026-1229x1536.jpeg 1229w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xlvii-concurso-nacional-de-saetas-pena-flamenca-buena-gente-2026-750x938.jpeg 750w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xlvii-concurso-nacional-de-saetas-pena-flamenca-buena-gente-2026-1140x1425.jpeg 1140w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>La pe\u00f1a tambi\u00e9n dio a conocer al <strong>Exaltador de la Saeta<\/strong> en la trig\u00e9simo s\u00e9ptima edici\u00f3n con dedicatoria especial al Pueblo Gitano. Ser\u00e1 nuevamente en la Iglesia de San Mateo, el viernes 13 de marzo, a las ocho y media de la tarde, y el encargado de la disertaci\u00f3n ser\u00e1 <strong>Pedro P\u00e9rez<\/strong>, actual hermano mayor de la Hermandad de Jes\u00fas de las Tres Ca\u00eddas, una de las grandes devociones de Jerez y vecinos hist\u00f3ricos de la pe\u00f1a en la Plaza de San Lucas. \u00c9l ser\u00e1 presentado por <strong>\u00c1ngel Rodr\u00edguez Aguilocho<\/strong>, cofrade y pregonero de la Semana Santa de Jerez, entre otros pregones. Y las saetas no faltar\u00e1n con la presencia de <strong>Dolores Agujetas, Juan Lara y Manuel Monje<\/strong>, adem\u00e1s de la Banda de Cornetas y Tambores Caridad.<\/p>\n<p>Como \u00faltima convocatoria, la pe\u00f1a ha animado nuevamente a la participaci\u00f3n al sexto <strong>Concurso de Letras por Saetas<\/strong> que otorgar\u00e1 a las cinco mejores saetas presentadas por un mismo autor la cantidad de 500 euros y diploma, seguidamente de un segundo premio de 300 euros y diploma, y un tercero de 150 euros y diploma. Deber\u00e1n mandarse al correo anteriormente se\u00f1alado antes del 23 de marzo. Para todos los detalles de la participaci\u00f3n de ambos concursos ser\u00e1 conveniente revisar las bases que ofrece la entidad en sus redes sociales.<\/p>\n<p>Una vez se conozcan los finalistas y ganador del Concurso Nacional de Saetas, la pe\u00f1a publicar\u00e1 un cartel que recoja los datos del ciclo <strong><em>Saeta Flamenca al Paso<\/em><\/strong>, en el que los saeteros cantar\u00e1n a determinadas cofrad\u00edas durante la Semana Santa. Los carteles son obra del artista jerezano <strong>Gonzalo L\u00f3pez<\/strong>, incluyendo el retrato de Ni\u00f1o Gloria. \u2666<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xxxvii-exaltacion-de-la-saeta-pena-flamenca-buena-gente-jerez-2026.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-5961\" src=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xxxvii-exaltacion-de-la-saeta-pena-flamenca-buena-gente-jerez-2026.jpeg\" alt=\"\" width=\"1639\" height=\"2048\" srcset=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xxxvii-exaltacion-de-la-saeta-pena-flamenca-buena-gente-jerez-2026.jpeg 1639w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xxxvii-exaltacion-de-la-saeta-pena-flamenca-buena-gente-jerez-2026-240x300.jpeg 240w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xxxvii-exaltacion-de-la-saeta-pena-flamenca-buena-gente-jerez-2026-820x1024.jpeg 820w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xxxvii-exaltacion-de-la-saeta-pena-flamenca-buena-gente-jerez-2026-768x960.jpeg 768w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xxxvii-exaltacion-de-la-saeta-pena-flamenca-buena-gente-jerez-2026-1229x1536.jpeg 1229w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xxxvii-exaltacion-de-la-saeta-pena-flamenca-buena-gente-jerez-2026-750x937.jpeg 750w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/xxxvii-exaltacion-de-la-saeta-pena-flamenca-buena-gente-jerez-2026-1140x1424.jpeg 1140w\" sizes=\"(max-width: 1639px) 100vw, 1639px\" \/><\/a> <a href=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/vi-concurso-de-letras-de-saeta-pena-flamenca-buena-gente-jerez-2026.jpeg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-5959\" src=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/vi-concurso-de-letras-de-saeta-pena-flamenca-buena-gente-jerez-2026.jpeg\" alt=\"\" width=\"1280\" height=\"1600\" srcset=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/vi-concurso-de-letras-de-saeta-pena-flamenca-buena-gente-jerez-2026.jpeg 1280w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/vi-concurso-de-letras-de-saeta-pena-flamenca-buena-gente-jerez-2026-240x300.jpeg 240w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/vi-concurso-de-letras-de-saeta-pena-flamenca-buena-gente-jerez-2026-819x1024.jpeg 819w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/vi-concurso-de-letras-de-saeta-pena-flamenca-buena-gente-jerez-2026-768x960.jpeg 768w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/vi-concurso-de-letras-de-saeta-pena-flamenca-buena-gente-jerez-2026-1229x1536.jpeg 1229w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/vi-concurso-de-letras-de-saeta-pena-flamenca-buena-gente-jerez-2026-750x938.jpeg 750w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/vi-concurso-de-letras-de-saeta-pena-flamenca-buena-gente-jerez-2026-1140x1425.jpeg 1140w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>La entidad jerezana ha presentado toda la programaci\u00f3n cuaresmal con la Exaltaci\u00f3n de la Saeta, el Concurso de cante y de letras con suculentos premios.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":34,"featured_media":5958,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","override":[{"template":"3","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_reading_time":"1","post_reading_time_wpm":"250","post_calculate_word_method":"str_word_count","show_zoom_button":"1","zoom_button_out_step":"2","zoom_button_in_step":"3","show_popup_post":"1","show_comment_section":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"1","show_inline_post_related":"1"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","subtitle":"La entidad jerezana ha presentado toda la programaci\u00f3n cuaresmal con la Exaltaci\u00f3n de la Saeta, el Concurso de cante y de letras con suculentos premios."},"jnews_primary_category":{"id":"37"},"jnews_override_bookmark_settings":{"override_bookmark_button":"0","override_show_bookmark_button":"0"},"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[37,38],"tags":[2996,418,7296,7295],"class_list":["post-5957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-en-portada","tag-pena-buena-gente","tag-concurso-flamenco","tag-concurso-nacional-de-saetas","tag-exaltacion-de-la-saeta","pmpro-has-access"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La entidad jerezana ha presentado toda la programaci\u00f3n cuaresmal con la Exaltaci\u00f3n de la Saeta, el Concurso de cante y de letras con suculentos premios.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juan Garrido\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\\\/#blogposting\",\"name\":\"Diez mil euros para la mejor saeta por seguiriyas en la Pe\\u00f1a Buena Gente - Revista ExpoFlamenco\",\"headline\":\"Diez mil euros para la mejor saeta por seguiriyas en la Pe\\u00f1a Buena Gente\",\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/juan-garrido\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2026\\\/03\\\/presentacion-concurso-nacional-de-saetas-1-pena-flamenca-buena-gente-jerez-mar26.jpg\",\"width\":1800,\"height\":900,\"caption\":\"Javi Mej\\u00edas, Francisco Zurita, Jesus L\\u00f3pez y Gonzalo Lopez. Presentaci\\u00f3n del Concurso Nacional de Saetas. Pe\\u00f1a Flamenca Buena Gente, Jerez. Marzo 2026. Foto: Juan Garrido\"},\"datePublished\":\"2026-03-13T10:59:06+01:00\",\"dateModified\":\"2026-03-13T10:59:06+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\\\/#webpage\"},\"articleSection\":\"Actualidad, En Portada, \\\"Pe\\u00f1a Buena Gente\\\", concurso flamenco, Concurso Nacional de Saetas, Exaltaci\\u00f3n de la Saeta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista#listItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\\\/#listItem\",\"name\":\"Diez mil euros para la mejor saeta por seguiriyas en la Pe\\u00f1a Buena Gente\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista#listItem\",\"name\":\"Hogar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\\\/#listItem\",\"position\":3,\"name\":\"Diez mil euros para la mejor saeta por seguiriyas en la Pe\\u00f1a Buena Gente\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\",\"name\":\"Revista ExpoFlamenco\",\"description\":\"Revista ExpoFlamenco\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/juan-garrido\\\/#author\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/juan-garrido\\\/\",\"name\":\"Juan Garrido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\\\/#authorImage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/juan-garrido-150x150.jpg\",\"width\":96,\"height\":96,\"caption\":\"Juan Garrido\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\\\/#webpage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\\\/\",\"name\":\"Diez mil euros para la mejor saeta por seguiriyas en la Pe\\u00f1a Buena Gente - Revista ExpoFlamenco\",\"description\":\"La entidad jerezana ha presentado toda la programaci\\u00f3n cuaresmal con la Exaltaci\\u00f3n de la Saeta, el Concurso de cante y de letras con suculentos premios.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/juan-garrido\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/juan-garrido\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2026\\\/03\\\/presentacion-concurso-nacional-de-saetas-1-pena-flamenca-buena-gente-jerez-mar26.jpg\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\\\/#mainImage\",\"width\":1800,\"height\":900,\"caption\":\"Javi Mej\\u00edas, Francisco Zurita, Jesus L\\u00f3pez y Gonzalo Lopez. Presentaci\\u00f3n del Concurso Nacional de Saetas. Pe\\u00f1a Flamenca Buena Gente, Jerez. Marzo 2026. Foto: Juan Garrido\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\\\/#mainImage\"},\"datePublished\":\"2026-03-13T10:59:06+01:00\",\"dateModified\":\"2026-03-13T10:59:06+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/\",\"name\":\"Revista ExpoFlamenco\",\"description\":\"Revista ExpoFlamenco\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script>(function(w,d,s,l,i){w[l]=w[l]||[];w[l].push({'gtm.start': new Date().getTime(),event:'gtm.js'});var f=d.getElementsByTagName(s)[0], j=d.createElement(s),dl=l!='dataLayer'?'&l='+l:'';j.async=true;j.src='https:\/\/www.googletagmanager.com\/gtm.js?id='+i+dl;f.parentNode.insertBefore(j,f);})(window,document,'script','dataLayer',\"GTM-N28N9JJ\");<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Diez mil euros para la mejor saeta por seguiriyas en la Pe\u00f1a Buena Gente - Revista ExpoFlamenco<\/title>\n\n","aioseo_head_json":{"title":"Diez mil euros para la mejor saeta por seguiriyas en la Pe\u00f1a Buena Gente - Revista ExpoFlamenco","description":"La entidad jerezana ha presentado toda la programaci\u00f3n cuaresmal con la Exaltaci\u00f3n de la Saeta, el Concurso de cante y de letras con suculentos premios.","canonical_url":"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/#blogposting","name":"Diez mil euros para la mejor saeta por seguiriyas en la Pe\u00f1a Buena Gente - Revista ExpoFlamenco","headline":"Diez mil euros para la mejor saeta por seguiriyas en la Pe\u00f1a Buena Gente","author":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/juan-garrido\/#author"},"publisher":{"@id":"https:\/\/expoflamenco.com\/revista\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/presentacion-concurso-nacional-de-saetas-1-pena-flamenca-buena-gente-jerez-mar26.jpg","width":1800,"height":900,"caption":"Javi Mej\u00edas, Francisco Zurita, Jesus L\u00f3pez y Gonzalo Lopez. Presentaci\u00f3n del Concurso Nacional de Saetas. Pe\u00f1a Flamenca Buena Gente, Jerez. Marzo 2026. Foto: Juan Garrido"},"datePublished":"2026-03-13T10:59:06+01:00","dateModified":"2026-03-13T10:59:06+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/#webpage"},"isPartOf":{"@id":"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/#webpage"},"articleSection":"Actualidad, En Portada, \"Pe\u00f1a Buena Gente\", concurso flamenco, Concurso Nacional de Saetas, Exaltaci\u00f3n de la Saeta"},{"@type":"BreadcrumbList","@id":"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista#listItem","position":1,"name":"Hogar","item":"https:\/\/expoflamenco.com\/revista","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/expoflamenco.com\/revista\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/#listItem","name":"Diez mil euros para la mejor saeta por seguiriyas en la Pe\u00f1a Buena Gente"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista#listItem","name":"Hogar"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/#listItem","position":3,"name":"Diez mil euros para la mejor saeta por seguiriyas en la Pe\u00f1a Buena Gente","previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/expoflamenco.com\/revista\/#organization","name":"Revista ExpoFlamenco","description":"Revista ExpoFlamenco","url":"https:\/\/expoflamenco.com\/revista\/"},{"@type":"Person","@id":"https:\/\/expoflamenco.com\/revista\/author\/juan-garrido\/#author","url":"https:\/\/expoflamenco.com\/revista\/author\/juan-garrido\/","name":"Juan Garrido","image":{"@type":"ImageObject","@id":"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/#authorImage","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/2026\/06\/juan-garrido-150x150.jpg","width":96,"height":96,"caption":"Juan Garrido"}},{"@type":"WebPage","@id":"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/#webpage","url":"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/","name":"Diez mil euros para la mejor saeta por seguiriyas en la Pe\u00f1a Buena Gente - Revista ExpoFlamenco","description":"La entidad jerezana ha presentado toda la programaci\u00f3n cuaresmal con la Exaltaci\u00f3n de la Saeta, el Concurso de cante y de letras con suculentos premios.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/expoflamenco.com\/revista\/#website"},"breadcrumb":{"@id":"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/#breadcrumblist"},"author":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/juan-garrido\/#author"},"creator":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/juan-garrido\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/03\/presentacion-concurso-nacional-de-saetas-1-pena-flamenca-buena-gente-jerez-mar26.jpg","@id":"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/#mainImage","width":1800,"height":900,"caption":"Javi Mej\u00edas, Francisco Zurita, Jesus L\u00f3pez y Gonzalo Lopez. Presentaci\u00f3n del Concurso Nacional de Saetas. Pe\u00f1a Flamenca Buena Gente, Jerez. Marzo 2026. Foto: Juan Garrido"},"primaryImageOfPage":{"@id":"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/#mainImage"},"datePublished":"2026-03-13T10:59:06+01:00","dateModified":"2026-03-13T10:59:06+01:00"},{"@type":"WebSite","@id":"https:\/\/expoflamenco.com\/revista\/#website","url":"https:\/\/expoflamenco.com\/revista\/","name":"Revista ExpoFlamenco","description":"Revista ExpoFlamenco","inLanguage":"es-ES","publisher":{"@id":"https:\/\/expoflamenco.com\/revista\/#organization"}}]}},"aioseo_meta_data":{"post_id":"5957","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-03-13 10:45:36","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2026-03-13 09:35:27","updated":"2026-03-13 10:45:36"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\" title=\"Hogar\">Hogar<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tDiez mil euros para la mejor saeta por seguiriyas en la Pe\u00f1a Buena Gente\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Hogar","link":"https:\/\/expoflamenco.com\/revista"},{"label":"Actualidad","link":"https:\/\/expoflamenco.com\/revista\/actualidad\/"},{"label":"Diez mil euros para la mejor saeta por seguiriyas en la Pe\u00f1a Buena Gente","link":"https:\/\/expoflamenco.com\/revista\/diez-mil-euros-para-la-mejor-saeta-por-seguiriyas-en-la-pena-buena-gente\/"}],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/5957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/comments?post=5957"}],"version-history":[{"count":1,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/5957\/revisions"}],"predecessor-version":[{"id":5962,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/5957\/revisions\/5962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media\/5958"}],"wp:attachment":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media?parent=5957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/categories?post=5957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/tags?post=5957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}