{"id":4347,"date":"2026-01-29T11:48:28","date_gmt":"2026-01-29T10:48:28","guid":{"rendered":"https:\/\/expoflamenco.com\/revista\/?p=4347"},"modified":"2026-02-18T18:41:32","modified_gmt":"2026-02-18T17:41:32","slug":"margit-frenk-una-luz-que-no-se-apago","status":"publish","type":"post","link":"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/","title":{"rendered":"Margit Frenk, una luz que no se apag\u00f3","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<p>El pasado 21 de noviembre de 2025 falleci\u00f3, ya centenaria, la hispanista y fil\u00f3loga <strong>Margit Frenk<\/strong>. Su \u00f3bito lo han recogido muy pocas publicaciones espa\u00f1olas, entre ellas, la revista <em><strong>Letras libres<\/strong>,<\/em> que se edita en formato digital e impreso en M\u00e9xico y Espa\u00f1a, y tambi\u00e9n en dos digitales, <em><strong>CTXT<\/strong> <strong>(Contexto)<\/strong><\/em>, con redacci\u00f3n en Madrid, y <strong><em>AISO (Asociaci\u00f3n Internacional Siglo de Oro)<\/em><\/strong>. Hay que agradecer a quienes escriben los respectivos art\u00edculos que se acordaran de la maestra. Son <strong>Luis Fernando Lara, Miguel Mart\u00ednez<\/strong> y <strong>Jos\u00e9 Manuel Pedrosa<\/strong>.<\/p>\n<p>Que sepamos, nada se ha dicho en medios generalistas nacionales, donde suelen informar del m\u00e1s leve resfriado de cualquier astro del f\u00fatbol o de la \u00faltima salida de tono del pol\u00edtico de turno. Ya nada sorprende de la desconexi\u00f3n existente entre Espa\u00f1a y los pa\u00edses hermanos del otro lado del Atl\u00e1ntico. Por poner un ejemplo, un libro que se edite en Espa\u00f1a y se distribuya en Hispanoam\u00e9rica lleva unas trabas burocr\u00e1ticas que lo encarecen notablemente, cosa que no ocurr\u00eda desde hace tres d\u00e9cadas para atr\u00e1s, cuando el mercado editorial entre ambas orillas circulaba con suma fluidez. Fruto de ese extra\u00f1amiento es <strong>el silencio casi total respecto a la muerte de Frenk<\/strong>.<\/p>\n<p>Estamos en un portal de flamenco y por eso cabe formular una pregunta: \u00bfqu\u00e9 hace que la desaparici\u00f3n de la eminente fil\u00f3loga mexicana merezca aqu\u00ed unas l\u00edneas? Este art\u00edculo trata de responder a ello.<\/p>\n<p>Empecemos con unas brev\u00edsimas notas biogr\u00e1ficas que cualquiera puede ampliar sin demasiado esfuerzo (los tres obituarios citados son muy recomendables). Margit Frenk Freund naci\u00f3 en Hamburgo el 21 de agosto de 1925, hija del doctor <strong>Ernst Frenk<\/strong> y la escritora y traductora <strong>Marianne Helen Freund Frenk-Westheim<\/strong>, ambos jud\u00edos \u2013el verdadero apellido de <strong>Ernst era Cohn<\/strong>\u2013 que no profesaban religi\u00f3n alguna. El matrimonio pronto se da cuenta de lo que se avecinaba y, gracias a esa clarividencia, se exiliaron antes de que los nazis llegaran al poder. As\u00ed, marchan a M\u00e9xico, donde desembarcan en Veracruz, el 22 de abril de 1930. All\u00ed desarrollar\u00e1n sus respectivas carreras profesionales y tambi\u00e9n pueden darles a sus dos hijos una esmerada educaci\u00f3n. El mayor, <strong>Silvestre<\/strong>, seguir\u00eda los pasos de su padre, y Margit, los de su madre. \u201cSoy rencorosa. No puedo olvidar lo que pas\u00f3\u201d, recordaba no hace mucho nuestra protagonista.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_4349\" aria-describedby=\"caption-attachment-4349\" style=\"width: 874px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Familia-Frenk.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-4349\" src=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Familia-Frenk.png\" alt=\"Margit Frenk con su hermano y sus padres. Archivo REFORMA.\" width=\"874\" height=\"571\" srcset=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Familia-Frenk.png 874w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Familia-Frenk-300x196.png 300w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Familia-Frenk-768x502.png 768w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Familia-Frenk-750x490.png 750w\" sizes=\"(max-width: 874px) 100vw, 874px\" \/><\/a><figcaption id=\"caption-attachment-4349\" class=\"wp-caption-text\">Margit Frenk con su hermano y sus padres. Archivo REFORMA.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Margit Frenk estudi\u00f3 en la Facultad de Filosof\u00eda de la UNAM y curs\u00f3 su maestr\u00eda en la Universidad de Berkeley. En 1972 se doctor\u00f3 en ling\u00fc\u00edstica y literaturas hisp\u00e1nicas en el <strong>Colegio de M\u00e9xico<\/strong>, con la tesis <em>Las jarchas moz\u00e1rabes y los comienzos de la l\u00edrica rom\u00e1nica<\/em>. Siempre consider\u00f3 como uno de sus principales maestros al profesor granadino <strong>Jos\u00e9 Fern\u00e1ndez-Montesinos Lustau<\/strong>, tambi\u00e9n exiliado en M\u00e9xico (su hermano Manuel, que fue alcalde de Granada, fue fusilado dos d\u00edas antes que <strong>Federico Garc\u00eda Lorca<\/strong>, su cu\u00f1ado).<\/p>\n<p>La bibliograf\u00eda de Frenk es muy amplia y una parte importante se ocupa de la l\u00edrica tradicional. Sus primeros libros los firma como <strong>Margit Frenk Alatorre<\/strong>, a ra\u00edz de su matrimonio con el tambi\u00e9n fil\u00f3logo mexicano <strong>Antonio Alatorre Ch\u00e1vez<\/strong>. Tras su separaci\u00f3n usar\u00e1 solo el primer apellido. La precisi\u00f3n sin petulancia, la agudeza y la vasta cultura de que hac\u00eda gala Frenk no estaban re\u00f1idas en absoluto con el sentido del humor y la amenidad de sus escritos. Leer cualquiera de ellos supone una bocanada de aire fresco y un gran goce para el lector.<\/p>\n<p>No es sitio para detenernos en su extensa obra pero quisiera destacar tres t\u00edtulos. Uno es el delicioso <strong><em>L\u00edrica hisp\u00e1nica de tipo popular: Edad Media y Renacimiento <\/em><\/strong>(M\u00e9xico: Universidad Nacional Aut\u00f3noma de M\u00e9xico, 1966). Otro es el que recopila diversos art\u00edculos que estaban dispersos, <strong><em>Poes\u00eda popular hisp\u00e1nica: 44 estudios<\/em><\/strong> (M\u00e9xico: Fondo de Cultura Econ\u00f3mica, 2006).\u00a0Lo abra uno por donde lo abra encontrar\u00e1 una lectura estimulante y alejada de cualquier pesadez acad\u00e9mica sin renunciar al rigor.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><em>\u00abEsto abona la teor\u00eda que sostiene que el flamenco es un decantado iniciado en los siglos \u00e1ureos y que empieza a cristalizar en el siglo XIX, en pleno romanticismo. Si en lo referente a la m\u00fasica sabemos que los ritmos, tonos y armon\u00edas de danzas como fol\u00edas, canarios, j\u00e1caras, zarabandas y chaconas, entre otras, sustentar\u00e1n estilos posteriores como fandangos, tanguillos, peteneras, guajiras y soleares, en lo tocante a las letras ocurrir\u00e1 algo similar\u00bb<\/em><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>Dejo para el final la obra en la que me quiero centrar. Se trata del monumental <strong><em>Nuevo corpus de la antigua l\u00edrica popular hisp\u00e1nica: Siglos XV a XVII <\/em><\/strong>(M\u00e9xico: Universidad Nacional Aut\u00f3noma de M\u00e9xico \/ El Colegio de M\u00e9xico \/ Fondo de Cultura Econ\u00f3mica, 2003), m\u00e1s de dos mil p\u00e1ginas repartidas en dos tomos que ampl\u00edan de manera sustancial su <em>Corpus de la antigua l\u00edrica popular hisp\u00e1nica. Siglos XV a XVII<\/em>\u00a0(Madrid: Castalia, 1987).<\/p>\n<p>La autora mexicana da cuenta ah\u00ed de 2.685 letras para las que cita variantes, contextos, correspondencias y paralelos con otras lenguas romances as\u00ed como supervivencias. Informa adem\u00e1s de las distintas fuentes en que aparecen. Huelga decir que es un trabajo absolutamente fundamental para cualquier interesado \u2013ya sea estudioso o simple aficionado\u2013 en la l\u00edrica tradicional, que completa otros anteriores de <strong>Julio Cejador, Men\u00e9ndez Pidal, S\u00e1nchez Romeralo, D\u00e1maso Alonso, Galm\u00e9s de Fuentes, Jos\u00e9 Manuel Blecua, Jos\u00e9 Mar\u00eda Al\u00edn, Vicente Beltr\u00e1n<\/strong> y un largo etc\u00e9tera.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_4350\" aria-describedby=\"caption-attachment-4350\" style=\"width: 1800px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/margit-frenk-nuevo-corpus-de-la-antigua-lirica-popular-hispanica-siglos-xv-a-xvii.webp\"><img decoding=\"async\" class=\"size-full wp-image-4350\" src=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/margit-frenk-nuevo-corpus-de-la-antigua-lirica-popular-hispanica-siglos-xv-a-xvii.webp\" alt=\"Portadas de los tomos I y II de la obra 'Nuevo corpus de la antigua l\u00edrica popular hisp\u00e1nica (siglos XV a XVII)', de Margit Frenk. Foto: Ram\u00f3n Soler\" width=\"1800\" height=\"1268\" srcset=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/margit-frenk-nuevo-corpus-de-la-antigua-lirica-popular-hispanica-siglos-xv-a-xvii.webp 1800w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/margit-frenk-nuevo-corpus-de-la-antigua-lirica-popular-hispanica-siglos-xv-a-xvii-300x211.webp 300w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/margit-frenk-nuevo-corpus-de-la-antigua-lirica-popular-hispanica-siglos-xv-a-xvii-1024x721.webp 1024w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/margit-frenk-nuevo-corpus-de-la-antigua-lirica-popular-hispanica-siglos-xv-a-xvii-768x541.webp 768w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/margit-frenk-nuevo-corpus-de-la-antigua-lirica-popular-hispanica-siglos-xv-a-xvii-1536x1082.webp 1536w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/margit-frenk-nuevo-corpus-de-la-antigua-lirica-popular-hispanica-siglos-xv-a-xvii-120x86.webp 120w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/margit-frenk-nuevo-corpus-de-la-antigua-lirica-popular-hispanica-siglos-xv-a-xvii-750x528.webp 750w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/margit-frenk-nuevo-corpus-de-la-antigua-lirica-popular-hispanica-siglos-xv-a-xvii-1140x803.webp 1140w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><figcaption id=\"caption-attachment-4350\" class=\"wp-caption-text\">Portadas de los tomos I y II de la obra &#8216;Nuevo corpus de la antigua l\u00edrica popular hisp\u00e1nica (siglos XV a XVII)&#8217;, de Margit Frenk. Foto: Ram\u00f3n Soler<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Muchas letras que se hallan en este corpus tratan de temas frecuentes en el cante. Algunas, incluso, han llegado con pocas variaciones a la actualidad. Esto abona la teor\u00eda \u2013cada vez m\u00e1s aceptada\u2013 que sostiene que el flamenco es un decantado iniciado en los siglos \u00e1ureos y que empieza a cristalizar en el siglo XIX, en pleno romanticismo. Si en lo referente a la m\u00fasica sabemos que los ritmos, tonos y armon\u00edas de danzas como fol\u00edas, canarios, j\u00e1caras, zarabandas y chaconas, entre otras, sustentar\u00e1n estilos posteriores como fandangos, tanguillos, peteneras, guajiras y soleares, en lo tocante a las letras ocurrir\u00e1 algo similar. La irrupci\u00f3n de seguidillas y coplas octos\u00edlabas a finales del siglo XVI y su asentamiento definitivo en el siglo XVIII fue determinante para el nacimiento de una nueva est\u00e9tica de la que se nutrir\u00e1 el cante flamenco que, como es bien sabido, usa tales metros de manera profusa. Frenk lo explicaba con meridiana claridad en <em>L\u00edrica espa\u00f1ola de tipo popular<\/em> (Madrid: C\u00e1tedra, 1992, p\u00e1g. 23):<\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 40px\">\u00abFue tal la fuerza de la moda, que la seguidilla, generalizada por toda Espa\u00f1a, \u00a0desplaz\u00f3 a las formas antiguas del folklore l\u00edrico musical. Junto con la cuarteta octosil\u00e1bica, igualmente antigua en cuanto a su forma y moderna en su esp\u00edritu, la seguidilla se ense\u00f1ore\u00f3 de la poes\u00eda popular de los siglos subsiguientes. En el seno mismo de la literatura que dio acogida a la canci\u00f3n folkl\u00f3rica medieval naci\u00f3, pues, la \u00a0poes\u00eda que acab\u00f3 con ella. Y acab\u00f3 radicalmente, sin dejar de ella m\u00e1s que alg\u00fan vago recuerdo, alguna reliquia excepcional\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>Recomiendo a los aficionados al flamenco que se zambullan en estos dos tomos para pescar \u2013la palabra es adecuada\u2013 coplas que remitan al flamenco. Ese gratificante ejercicio es lo que voy a hacer a continuaci\u00f3n ci\u00f1\u00e9ndome solo a las primeras doscientas del <em>Nuevo corpus<\/em> de Margit Frenk. Vamos all\u00e1.<\/p>\n<p>En la <strong><em>Recopilaci\u00f3n de Sonetos y villancicos a quatro y a cinco de Juan Vasquez<\/em><\/strong>, de 1560, hallamos una preciosa letra inspirada en un dicho que recogi\u00f3 antes el <strong>Marqu\u00e9s de Santillana<\/strong> en <em>Refranes que dizen las viejas tras el fuego<\/em> (\u201cLa una mano a la otra lava y todas dos a la cara\u201d). \u00a0Es la n\u00ba 2 del <em>Nuevo corpus<\/em> de Frenk:<\/p>\n<p>&nbsp;<\/p>\n<p><em>En la fuente del rosel<\/em><br \/>\n<em>lavan la ni\u00f1a y el donzel.<\/em><\/p>\n<p><em>En la fuente de agua clara<\/em><br \/>\n<em>con sus manos lavan la cara.<\/em><\/p>\n<p><em>\u00c9l a ella y ella a \u00e9l<\/em><br \/>\n<em>[lavan la ni\u00f1a y el donzel].<\/em><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_4351\" aria-describedby=\"caption-attachment-4351\" style=\"width: 1003px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Juan-Vasquez.jpg\"><img decoding=\"async\" class=\"size-full wp-image-4351\" src=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Juan-Vasquez.jpg\" alt=\"Juan Vasquez\" width=\"1003\" height=\"282\" srcset=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Juan-Vasquez.jpg 1003w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Juan-Vasquez-300x84.jpg 300w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Juan-Vasquez-768x216.jpg 768w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Juan-Vasquez-750x211.jpg 750w\" sizes=\"(max-width: 1003px) 100vw, 1003px\" \/><\/a><figcaption id=\"caption-attachment-4351\" class=\"wp-caption-text\">Juan Vasquez<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>El mismo refr\u00e1n lo encontramos en una buler\u00eda que cantaba el utrerano <strong>Manuel de Angustias<\/strong> (<em>Cantes de Utrera y Alcal\u00e1<\/em>, Ariola, 1971):<\/p>\n<p>&nbsp;<\/p>\n<p><em>Vaya qu\u00e9 cosa m\u00e1s rara,<\/em><br \/>\n<em>una manita lava la otra,<\/em><br \/>\n<em>las dos lavaban la cara.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>La n\u00ba 30 de Frenk est\u00e1 incluida en el manuscrito ms. \u03b1.Q.8.21 de la Biblioteca Estense Universitaria de M\u00f3dena, que data de finales del siglo XVI y principios del XVII:<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00a1Viva, viva la gra\u00e7ia, viva!<\/em><br \/>\n<em>\u00a1Viva, viva el ciego amor!<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Modernamente, en el villancico tradicional de <em>La Virgen y el Ciego<\/em>, se canta el estribillo \u201c\u00a1Viva el amor!\u201d, que se alterna con \u201c\u00a1Viva el laurel!\u201d. Pero la letrilla antigua recuerda m\u00e1s a un remate que grab\u00f3 <strong>Mairena<\/strong> en el disco <em>Sevilla por buler\u00edas<\/em> (Columbia, 1967), quiz\u00e1s de su autor\u00eda:<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00a1Viva la gracia, viva el salero,<\/em><br \/>\n<em>te enamoraste de un canastero!<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>En el mismo cancionero se halla la redondilla (n\u00ba 44 de Frenk):<\/p>\n<p>&nbsp;<\/p>\n<p><em>Contra\u2019l amor nada vale,<\/em><br \/>\n<em>que si en el cora\u00e7\u00f3n toca,<\/em><br \/>\n<em>aunque le sierren la boca,<\/em><br \/>\n<em>\u00e9l por los ojos se sale.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Es un t\u00f3pico presente en una sole\u00e1 que grab\u00f3 <strong>T\u00edo Borrico<\/strong> con su sobrino Parrilla (RCA, 1974):<\/p>\n<p>&nbsp;<\/p>\n<p><em>Hazme con los ojos se\u00f1as,<\/em><br \/>\n<em>que en algunas ocasiones<\/em><br \/>\n<em>los ojos sirven de lengua.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>En el <em>Vocabulario de refranes y frases proverbiales<\/em> de <strong>Gonzalo Correas<\/strong> (1627) se encuentra esta cuarteta (n\u00ba 64 de Frenk):<\/p>\n<p>&nbsp;<\/p>\n<p><em>Est\u00e1vame io en mi estudio<\/em><br \/>\n<em>estudiando la lizi\u00f3n,<\/em><br \/>\n<em>i akord\u00e9me de mis amores:<\/em><br \/>\n<em>no pod\u00eda estudiar, non.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Tal incapacidad para la concentraci\u00f3n causada por el amor se entrev\u00e9 en una sole\u00e1 que cantaba <strong>Fernanda<\/strong> (<em>Cante flamenco: Fernanda et Bernarda de Utrera en concert \u00e0 Paris<\/em>, Ocora, 1987):<\/p>\n<p>&nbsp;<\/p>\n<p><em>No quiero que vayas a misa<\/em><br \/>\n<em>ni a la misa que iba yo,<\/em><br \/>\n<em>ni t\u00fa rezas ni yo rezaba<\/em><br \/>\n<em>ni tenemos devoci\u00f3n.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>En <strong><em>Flor de varios romances nuevos y canciones recopiladas por Pedro de Moncayo<\/em><\/strong>, fechado en Huesca en 1589, leemos (n\u00ba 92 de Frenk):<\/p>\n<p>&nbsp;<\/p>\n<p><em>Un sospiro dio Luc\u00eda<\/em><br \/>\n<em>ayer estando lavando:<\/em><br \/>\n<em>\u00a1qui\u00e9n fuera tras \u00e9l bolando,<\/em><br \/>\n<em>por saber d\u00f3nde le emb\u00eda!<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Son los mismos suspiros de una quintilla que cantaba <strong>Fosforito<\/strong>, por alegr\u00edas, y <strong>Rafael el Tuerto<\/strong>, por tientos (ninguno de los dos la grab\u00f3 en disco), y que registr\u00f3 <strong>Joaqu\u00edn el Canastero<\/strong> por fandangos (Emi, 1972):<\/p>\n<p>&nbsp;<\/p>\n<p><em>Si a media noche en tu cama<\/em><br \/>\n<em>te despierta un sudor fr\u00edo,<\/em><br \/>\n<em>por Dios, no te d\u00e9 jindama<\/em><br \/>\n<em>que son los suspiros m\u00edos<\/em><br \/>\n<em>que a media noche te llaman.<\/em><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_4352\" aria-describedby=\"caption-attachment-4352\" style=\"width: 423px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Margit-Frenk-de-joven.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4352\" src=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Margit-Frenk-de-joven.png\" alt=\"Margit Frenk, de joven. Homenaje de la UNAM.\" width=\"423\" height=\"531\" srcset=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Margit-Frenk-de-joven.png 423w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Margit-Frenk-de-joven-239x300.png 239w\" sizes=\"(max-width: 423px) 100vw, 423px\" \/><\/a><figcaption id=\"caption-attachment-4352\" class=\"wp-caption-text\">Margit Frenk, de joven. Homenaje de la UNAM.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>La comparaci\u00f3n de la amada con elementos naturales en la l\u00edrica tradicional es cosa frecuente. Ejemplo de ello es esta letra (n\u00ba 100 bis de Frenk) recogida en el <strong><em>Cancionero musical valenciano<\/em><\/strong> (copiado entre 1560 y 1582):<\/p>\n<p>&nbsp;<\/p>\n<p><em>Qu\u00e9 bonica eres, zagala,<\/em><br \/>\n<em>sino que me das vida penada.<\/em><\/p>\n<p><em>Eres m\u00e1s linda qu\u2019el prado<\/em><br \/>\n<em>verde, florido y granado;<\/em><br \/>\n<em>m\u00e1s que a todo mi ganado<\/em><br \/>\n<em>te quiero y que a mi majada.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Una construcci\u00f3n similar tienen los primeros versos de otra que suele cantarse en la fiesta de verdiales y que grab\u00f3 <strong>El Lebrijano<\/strong> por sole\u00e1 (<em>De casta le viene\u2026 El Lebrijano presenta a su madre La Perrata<\/em>, Philips, 1970):<\/p>\n<p>&nbsp;<\/p>\n<p><em>M\u00e1s hermosa eres que el sol<\/em><br \/>\n<em>y que la nieve en el desierto,<\/em><br \/>\n<em>que la rosa en el rosal<\/em><br \/>\n<em>que la azucena en el huerto.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>\u00bfQui\u00e9n no recuerda la seguiriya cabal que grab\u00f3 el viejo <strong>Tenazas de Mor\u00f3n<\/strong> tras ganar el Concurso de Cante Jondo de Granada (<em>Seguidilla de Silverio<\/em>, Odeon, 1922)?:<\/p>\n<p>&nbsp;<\/p>\n<p><em>Yo he anda\u00edto la Francia,<\/em><br \/>\n<em>Sevilla y Portugal<\/em><br \/>\n<em>y una carita como t\u00fa la tienes<\/em><br \/>\n<em>no he po\u00edo encontrar.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Tenemos una correspondencia con la letra n\u00ba 111 del <em>Nuevo corpus<\/em> de Margit Frenk, que viene en la ya citada la <em>Recopilaci\u00f3n\u2026 de Juan Vasquez<\/em>, de 1560:<\/p>\n<p>&nbsp;<\/p>\n<p><em>Tales ollos como los vosos<\/em><br \/>\n<em>nan os ay en Portugal.<\/em><\/p>\n<p><em>Todo Portugal andey,<\/em><br \/>\n<em>nunca tales ollos achey.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Una letra por buler\u00eda que grab\u00f3 <strong>Pansequito<\/strong> y que firman el propio cantaor, <strong>Jos\u00e9 Ruiz Venegas<\/strong> y <strong>P. Carrasco<\/strong> tuvo bastante difusi\u00f3n en su \u00e9poca (<em>Pansequito<\/em>, Movieplay, 1978):<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00bfC\u00f3mo me puedes querer<\/em><br \/>\n<em>con quince a\u00f1os que tienes,<\/em><br \/>\n<em>si antiguamente las ni\u00f1as<\/em><br \/>\n<em>con los a\u00f1os que t\u00fa tienes<\/em><br \/>\n<em>jugaban al esconder?<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Esa precocidad de la ni\u00f1a en el amor tiene su correspondencia con otra del <strong><em>Qvinto qvaderno de varios Romances<\/em><\/strong>, fechado en Valencia en 1593 (n\u00ba 118 de Frenk):<\/p>\n<p>&nbsp;<\/p>\n<p><em>Ni\u00f1a de quinze a\u00f1os<\/em><br \/>\n<em>que cautiva y prende<\/em><br \/>\n<em>\u00a1qu\u00e9 har\u00e1, Dios m\u00edo,<\/em><br \/>\n<em>cuando tenga veynte!<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Una sole\u00e1 que grab\u00f3 <strong>Pepe el de la Matrona<\/strong> en 1947 para la colecci\u00f3n privada de <strong>Garc\u00eda Matos<\/strong> y publicada a\u00f1os despu\u00e9s (<em>Homenaje a Pepe de La Matrona<\/em>, A&amp;B Master Records, 1990) es:<\/p>\n<p>&nbsp;<\/p>\n<p><em>(Dicen que) La villa vale,<\/em><br \/>\n<em>la villa vale dinero<\/em><br \/>\n<em>y tus ojos son dos caudales.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>La podemos vincular con una antigua que se recoge en el <strong><em>Cancionero de galanes<\/em><\/strong>, de 1520 (n\u00ba 128 de Frenk):<\/p>\n<p>&nbsp;<\/p>\n<p><em>Mis ojuelos, madre,<\/em><br \/>\n<em>valen una ciudade.<\/em><\/p>\n<p><em>Mis ojuelos, madre,<\/em><br \/>\n<em>tanto son de claros,<\/em><br \/>\n<em>cada vez que los al\u00e7o<\/em><br \/>\n<em>merescen ducados.<\/em><br \/>\n<em>Ducados, mi madre.<\/em><br \/>\n<em>Valen una ciudade.<\/em><\/p>\n<p><em>Mis ojuelos, madre,<\/em><br \/>\n<em>tanto son de veros,<\/em><br \/>\n<em>cada vez que los al\u00e7o<\/em><br \/>\n<em>merescen dineros.<\/em><br \/>\n<em>Dineros, mi madre.<\/em><br \/>\n<em>Valen una ciudade.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Dos seguidillas antiguas tienen tem\u00e1tica similar. Una la emplea <strong>Lope de Vega<\/strong> en su comedia <strong><em>Servir a se\u00f1or discreto<\/em><\/strong>, publicada en 1618 (n\u00ba 176 de Frenk), y otra se halla en el <strong><em>Cancionero de Jacinto L\u00f3pez<\/em><\/strong>, manuscrito fechado en 1620 en Madrid (n\u00ba 179 de Frenk). Respectivamente son:<\/p>\n<p>&nbsp;<\/p>\n<p><em>Mariquita me llaman<\/em><br \/>\n<em>los arrieros;<\/em><br \/>\n<em>Mariquita me llaman,<\/em><br \/>\n<em>voyme con ellos.<\/em><\/p>\n<p><em>Qui\u00e9rome ir, mi bida,<\/em><br \/>\n<em>qui\u00e9rome ir con \u00e9l,<\/em><br \/>\n<em>una temporadita<\/em><br \/>\n<em>con el mercader.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Nos recuerdan algunas letras flamencas, como la de un c\u00e9lebre tango registrado por <strong>la Ni\u00f1a de los Peines<\/strong> (<em>Del color de cera, mare<\/em>, La Voz de Su Amo, 1950) y una sole\u00e1 que cantaba <strong>Perrate de Utrera<\/strong> pero que no lleg\u00f3 a grabar. Son, respectivamente, estas dos:<\/p>\n<p>&nbsp;<\/p>\n<p><em>Pasa un encajero,<\/em><br \/>\n<em>mare, yo me voy con \u00e9l<\/em><br \/>\n<em>que tiene mucho salero.<\/em><\/p>\n<p><em>Mare que yo me voy con \u00e9l<\/em><br \/>\n<em>que si no tiene dinero<\/em><br \/>\n<em>tiene pa\u00f1o que vender.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Esta \u00faltima tambi\u00e9n la cantaba Perrate por buler\u00edas y primer verso <em>La voz de un pa\u00f1ero suena<\/em>.<\/p>\n<p>En la ensalada de <strong>Pedro de Padilla<\/strong> <em>Sal\u00edme paseando<\/em>, que se recoge en su <em>Thesoro de varias poes\u00edas<\/em> (Madrid, 1580), encontramos esta letrilla (n\u00ba 190 A):<\/p>\n<p>&nbsp;<\/p>\n<p><em>Si me llaman, a m\u00ed llaman:<\/em><br \/>\n<em>cuydo que me llaman a m\u00ed.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Se parece bastante a otras dos que grab\u00f3 Mairena en sendas tandas de buler\u00edas en <em>La Gran Historia del Cante Gitano Andaluz<\/em> (Columbia, 1966):<\/p>\n<p>&nbsp;<\/p>\n<p><em>Si me llama, me llama mi mare,<\/em><br \/>\n<em>d\u00e9jala t\u00fa que me llame, me llame.<\/em><\/p>\n<p><em>Que me llaman, me llaman a m\u00ed,<\/em><br \/>\n<em>con un pa\u00f1uelo de la nariz.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Desde muy joven la Ni\u00f1a de los Peines cantaba un juguetillo por buler\u00edas. Lo grab\u00f3 por primera vez con <strong>Ram\u00f3n Montoya<\/strong> (<em>Buler\u00edas n\u00ba1<\/em>, 1909):<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00a1Ay mam\u00e1, ay mam\u00e1!<\/em><br \/>\n<em>como Periquito me quiere pegar.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Se asemeja mucho a esta otra (n\u00ba 196 de Frenk), con igual m\u00e9trica, que se encuentra en varias fuentes, entre ellas en <strong><em>Refranes, o proverbios en romance que nvevamente colligio y glosso el Comendador Hern\u00e1n N\u00fa\u00f1ez<\/em><\/strong> (Salamanca, 1555):<\/p>\n<p>&nbsp;<\/p>\n<p><em>Madre, casar, casar,<\/em><br \/>\n<em>que \u00c7arapico me quiere llevar.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>En las primeras 200 letras del corpus de Frenk se podr\u00edan haber espigado unas cuantas m\u00e1s pero no es lugar para extendernos demasiado. No obstante, cito dos m\u00e1s que aparecen m\u00e1s adelante y que han llegado hasta nosotros con pocos cambios. Una es conocid\u00edsima y la recoge en 1626 <strong>Luis de Brice\u00f1o<\/strong> en su <strong><em>Metodo mui facilissimo para aprender a ta\u00f1er la guitarra a lo espa\u00f1ol<\/em><\/strong> (n\u00ba 2.285 de Frenk):<\/p>\n<p>&nbsp;<\/p>\n<p><em>Por la calle abaxo<\/em><br \/>\n<em>ba el que m\u00e1s quiero;<\/em><br \/>\n<em>no le beo la cara<\/em><br \/>\n<em>con el sombrero.<\/em><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_4353\" aria-describedby=\"caption-attachment-4353\" style=\"width: 1354px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Metodo_mui_facilissimo_para_aprender-_-Briceno_Luis.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4353\" src=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Metodo_mui_facilissimo_para_aprender-_-Briceno_Luis.jpeg\" alt=\"Metodo mui facilissimo para aprender a ta\u00f1er la guitarra..., Bricen\u0303o Luis. Biblioth\u00e8que Nationale de France.\" width=\"1354\" height=\"1054\" srcset=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Metodo_mui_facilissimo_para_aprender-_-Briceno_Luis.jpeg 1354w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Metodo_mui_facilissimo_para_aprender-_-Briceno_Luis-300x234.jpeg 300w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Metodo_mui_facilissimo_para_aprender-_-Briceno_Luis-1024x797.jpeg 1024w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Metodo_mui_facilissimo_para_aprender-_-Briceno_Luis-768x598.jpeg 768w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Metodo_mui_facilissimo_para_aprender-_-Briceno_Luis-750x584.jpeg 750w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Metodo_mui_facilissimo_para_aprender-_-Briceno_Luis-1140x887.jpeg 1140w\" sizes=\"(max-width: 1354px) 100vw, 1354px\" \/><\/a><figcaption id=\"caption-attachment-4353\" class=\"wp-caption-text\">Metodo mui facilissimo para aprender a ta\u00f1er la guitarra&#8230;, Bricen\u0303o Luis. Biblioth\u00e8que Nationale de France.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Son muchos los cantaores que la han interpretado por buler\u00edas, como <strong>Manolo Caracol<\/strong> (<em>Fiesta jerezana<\/em>, Columbia, 1945) y <strong>Chano Lobato<\/strong> (<em>Aromo<\/em>, Pasarela, 1987).<\/p>\n<p>Esta otra copla es de autor conocido y pas\u00f3 al caudal tradicional sin apenas cambios (n 2.595 de Frenk). Es del poeta <strong>Antonio Hurtado de Mendoza<\/strong> (1586-1644):<\/p>\n<p>&nbsp;<\/p>\n<p><em>No corras, arroyo, ufano,<\/em><br \/>\n<em>que no es tu caudal eterno,<\/em><br \/>\n<em>que si te le dio el invierno,<\/em><br \/>\n<em>te le quitar\u00e1 el verano.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>As\u00ed la cantaba por fandangos el genial <strong>Antonio de la Calz\u00e1<\/strong> (<em>Fandangos<\/em>, Sonoplay, 1968):<\/p>\n<p>&nbsp;<\/p>\n<p><em>Arroyo, no corras tanto,<\/em><br \/>\n<em>mira que t\u00fa no eres eterno,<\/em><br \/>\n<em>llega el verano y te quita<\/em><br \/>\n<em>lo que te dio ese hermoso invierno,<\/em><br \/>\n<em>el agua tuya era maldita.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Terminamos con un ejemplo de una frase que ha llegado hasta nosotros inserta en una copla flamenca. En el ya mentado <em>Cancionero<\/em> del m\u00fasico cortesano <strong>Jacinto L\u00f3pez<\/strong> est\u00e1 (n\u00ba 2.181 de Frenk):<\/p>\n<p>&nbsp;<\/p>\n<p><em>H\u00e9chale la capa a la baca<\/em><br \/>\n<em>el mosito enamorado,<\/em><br \/>\n<em>\u00e9chale la capa a la baca;<\/em><br \/>\n<em>la baca la capa le \u00e1 rasgado.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>En 1908 <strong>El Garrido de Jerez<\/strong> grab\u00f3 como tango-chufla una letra con ese mismo juego onomatop\u00e9yico. M\u00e1s accesible es la versi\u00f3n de <strong>Pepe el de la Matrona<\/strong>, que tambi\u00e9n la interpret\u00f3 por tangos (en el citado disco de 1947 y tambi\u00e9n en <em>Tesoros del flamenco antiguo<\/em>, Hispavox, 1969):<\/p>\n<p>&nbsp;<\/p>\n<p><em>Al pasar por la calle Nueva<\/em><br \/>\n<em>y una vaquita a m\u00ed me agarr\u00f3,<\/em><br \/>\n<em>por tirarle la capa a la vaca,<\/em><br \/>\n<em>la capa la vaca me la desgarr\u00f3.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Todo lo expuesto es una peque\u00f1\u00edsima muestra de los tesoros que podemos hallar en esta colosal obra de Margit Frenk, una mujer ejemplar que debemos recordar siempre. Como le pasaba a <strong>la Graciana<\/strong>, la abuela de mi amigo <strong>Enrique Navarro<\/strong>, que tambi\u00e9n con cien a\u00f1os ten\u00edan sus ojos un brillo especial. Val\u00edan caudales. \u2666<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_4354\" aria-describedby=\"caption-attachment-4354\" style=\"width: 960px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Margit-Frenk-Retrato-de-Uriel-Santiago-Velasco-23-mayo-2025.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4354\" src=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Margit-Frenk-Retrato-de-Uriel-Santiago-Velasco-23-mayo-2025.jpg\" alt=\"Margit Frenk. Fotograf\u00eda tomada por Uriel Santiago Velasco el 23 de mayo de 2025, a tres meses de cumplir 100 a\u00f1os.\" width=\"960\" height=\"1017\" srcset=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Margit-Frenk-Retrato-de-Uriel-Santiago-Velasco-23-mayo-2025.jpg 960w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Margit-Frenk-Retrato-de-Uriel-Santiago-Velasco-23-mayo-2025-283x300.jpg 283w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Margit-Frenk-Retrato-de-Uriel-Santiago-Velasco-23-mayo-2025-768x814.jpg 768w, https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/Margit-Frenk-Retrato-de-Uriel-Santiago-Velasco-23-mayo-2025-750x795.jpg 750w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><figcaption id=\"caption-attachment-4354\" class=\"wp-caption-text\">Margit Frenk. Fotograf\u00eda tomada por Uriel Santiago Velasco el 23 de mayo de 2025, a tres meses de cumplir 100 a\u00f1os.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>Repasamos los tesoros que podemos hallar en &#8216;Nuevo corpus de la antigua l\u00edrica popular hisp\u00e1nica: Siglos XV a XVII&#8217;, colosal obra de la hispanista y fil\u00f3loga Margit Frenk (Hamburgo, 1925 &#8211; Ciudad de M\u00e9xico, 2025) que re\u00fane letras frecuentes en el cante flamenco. Una mujer ejemplar que debemos recordar siempre.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":19,"featured_media":4348,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","override":[{"template":"3","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_reading_time":"1","post_reading_time_wpm":"250","post_calculate_word_method":"str_word_count","show_zoom_button":"1","zoom_button_out_step":"2","zoom_button_in_step":"3","show_popup_post":"1","show_comment_section":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"1","show_inline_post_related":"1"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","subtitle":"Repasamos los tesoros que podemos hallar en 'Nuevo corpus de la antigua l\u00edrica popular hisp\u00e1nica: Siglos XV a XVII', colosal obra de la hispanista y fil\u00f3loga Margit Frenk (Hamburgo, 1925 - Ciudad de M\u00e9xico, 2025) que re\u00fane letras frecuentes en el cante flamenco. Una mujer ejemplar que debemos recordar siempre."},"jnews_primary_category":{"id":"73"},"jnews_override_bookmark_settings":{"override_bookmark_button":"0","override_show_bookmark_button":"0"},"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[38,72,73],"tags":[7024,76,7026,7028,6894],"class_list":["post-4347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-portada","category-investigaciones","category-opinion","tag-hispanista-y-filologa","tag-investigacion-flamenca","tag-margit-frenk","tag-nuevo-corpus-de-la-antigua-lirica-popular-hispanica-siglos-xv-a-xvii","tag-obituario","pmpro-has-access"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Repasamos los tesoros que podemos hallar en &#039;Nuevo corpus de la antigua l\u00edrica popular hisp\u00e1nica: Siglos XV a XVII&#039;, colosal obra de la hispanista y fil\u00f3loga Margit Frenk (Hamburgo, 1925 - Ciudad de M\u00e9xico, 2025) que re\u00fane letras frecuentes en el cante flamenco. Una mujer ejemplar que debemos recordar siempre.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Ram\u00f3n Soler\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/margit-frenk-una-luz-que-no-se-apago\\\/#blogposting\",\"name\":\"Margit Frenk, una luz que no se apag\\u00f3 - Revista ExpoFlamenco\",\"headline\":\"Margit Frenk, una luz que no se apag\\u00f3\",\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/ramonsoler\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2026\\\/01\\\/margit-frenk-fotograma-documental-el-colegio-de-mexico-y-el-68.webp\",\"width\":1140,\"height\":569,\"caption\":\"Margit Frenk. Fotograma del documental 'El Colegio de M\\u00e9xico y el 68'. Producci\\u00f3n: Coordinaci\\u00f3n de Educaci\\u00f3n Digital \\\/ Colmex Digital.\"},\"datePublished\":\"2026-01-29T11:48:28+01:00\",\"dateModified\":\"2026-02-18T18:41:32+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/margit-frenk-una-luz-que-no-se-apago\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/margit-frenk-una-luz-que-no-se-apago\\\/#webpage\"},\"articleSection\":\"En Portada, Investigaciones, Opini\\u00f3n, hispanista y fil\\u00f3loga, investigacion flamenca, Margit Frenk, Nuevo corpus de la antigua l\\u00edrica popular hisp\\u00e1nica: Siglos XV a XVII, obituario\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/margit-frenk-una-luz-que-no-se-apago\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista#listItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/en-portada\\\/#listItem\",\"name\":\"En Portada\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/en-portada\\\/#listItem\",\"position\":2,\"name\":\"En Portada\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/en-portada\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/margit-frenk-una-luz-que-no-se-apago\\\/#listItem\",\"name\":\"Margit Frenk, una luz que no se apag\\u00f3\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista#listItem\",\"name\":\"Hogar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/margit-frenk-una-luz-que-no-se-apago\\\/#listItem\",\"position\":3,\"name\":\"Margit Frenk, una luz que no se apag\\u00f3\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/en-portada\\\/#listItem\",\"name\":\"En Portada\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\",\"name\":\"Revista ExpoFlamenco\",\"description\":\"Revista ExpoFlamenco\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/ramonsoler\\\/#author\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/ramonsoler\\\/\",\"name\":\"Ram\\u00f3n Soler\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/margit-frenk-una-luz-que-no-se-apago\\\/#authorImage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/ramon-soler-new-1-150x150.jpg\",\"width\":96,\"height\":96,\"caption\":\"Ram\\u00f3n Soler\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/margit-frenk-una-luz-que-no-se-apago\\\/#webpage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/margit-frenk-una-luz-que-no-se-apago\\\/\",\"name\":\"Margit Frenk, una luz que no se apag\\u00f3 - Revista ExpoFlamenco\",\"description\":\"Repasamos los tesoros que podemos hallar en 'Nuevo corpus de la antigua l\\u00edrica popular hisp\\u00e1nica: Siglos XV a XVII', colosal obra de la hispanista y fil\\u00f3loga Margit Frenk (Hamburgo, 1925 - Ciudad de M\\u00e9xico, 2025) que re\\u00fane letras frecuentes en el cante flamenco. Una mujer ejemplar que debemos recordar siempre.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/margit-frenk-una-luz-que-no-se-apago\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/ramonsoler\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/ramonsoler\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2026\\\/01\\\/margit-frenk-fotograma-documental-el-colegio-de-mexico-y-el-68.webp\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/margit-frenk-una-luz-que-no-se-apago\\\/#mainImage\",\"width\":1140,\"height\":569,\"caption\":\"Margit Frenk. Fotograma del documental 'El Colegio de M\\u00e9xico y el 68'. Producci\\u00f3n: Coordinaci\\u00f3n de Educaci\\u00f3n Digital \\\/ Colmex Digital.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/margit-frenk-una-luz-que-no-se-apago\\\/#mainImage\"},\"datePublished\":\"2026-01-29T11:48:28+01:00\",\"dateModified\":\"2026-02-18T18:41:32+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/\",\"name\":\"Revista ExpoFlamenco\",\"description\":\"Revista ExpoFlamenco\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script>(function(w,d,s,l,i){w[l]=w[l]||[];w[l].push({'gtm.start': new Date().getTime(),event:'gtm.js'});var f=d.getElementsByTagName(s)[0], j=d.createElement(s),dl=l!='dataLayer'?'&l='+l:'';j.async=true;j.src='https:\/\/www.googletagmanager.com\/gtm.js?id='+i+dl;f.parentNode.insertBefore(j,f);})(window,document,'script','dataLayer',\"GTM-N28N9JJ\");<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Margit Frenk, una luz que no se apag\u00f3 - Revista ExpoFlamenco<\/title>\n\n","aioseo_head_json":{"title":"Margit Frenk, una luz que no se apag\u00f3 - Revista ExpoFlamenco","description":"Repasamos los tesoros que podemos hallar en 'Nuevo corpus de la antigua l\u00edrica popular hisp\u00e1nica: Siglos XV a XVII', colosal obra de la hispanista y fil\u00f3loga Margit Frenk (Hamburgo, 1925 - Ciudad de M\u00e9xico, 2025) que re\u00fane letras frecuentes en el cante flamenco. Una mujer ejemplar que debemos recordar siempre.","canonical_url":"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/#blogposting","name":"Margit Frenk, una luz que no se apag\u00f3 - Revista ExpoFlamenco","headline":"Margit Frenk, una luz que no se apag\u00f3","author":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/ramonsoler\/#author"},"publisher":{"@id":"https:\/\/expoflamenco.com\/revista\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/margit-frenk-fotograma-documental-el-colegio-de-mexico-y-el-68.webp","width":1140,"height":569,"caption":"Margit Frenk. Fotograma del documental 'El Colegio de M\u00e9xico y el 68'. Producci\u00f3n: Coordinaci\u00f3n de Educaci\u00f3n Digital \/ Colmex Digital."},"datePublished":"2026-01-29T11:48:28+01:00","dateModified":"2026-02-18T18:41:32+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/#webpage"},"isPartOf":{"@id":"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/#webpage"},"articleSection":"En Portada, Investigaciones, Opini\u00f3n, hispanista y fil\u00f3loga, investigacion flamenca, Margit Frenk, Nuevo corpus de la antigua l\u00edrica popular hisp\u00e1nica: Siglos XV a XVII, obituario"},{"@type":"BreadcrumbList","@id":"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista#listItem","position":1,"name":"Hogar","item":"https:\/\/expoflamenco.com\/revista","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/en-portada\/#listItem","name":"En Portada"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/en-portada\/#listItem","position":2,"name":"En Portada","item":"https:\/\/expoflamenco.com\/revista\/en-portada\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/#listItem","name":"Margit Frenk, una luz que no se apag\u00f3"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista#listItem","name":"Hogar"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/#listItem","position":3,"name":"Margit Frenk, una luz que no se apag\u00f3","previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/en-portada\/#listItem","name":"En Portada"}}]},{"@type":"Organization","@id":"https:\/\/expoflamenco.com\/revista\/#organization","name":"Revista ExpoFlamenco","description":"Revista ExpoFlamenco","url":"https:\/\/expoflamenco.com\/revista\/"},{"@type":"Person","@id":"https:\/\/expoflamenco.com\/revista\/author\/ramonsoler\/#author","url":"https:\/\/expoflamenco.com\/revista\/author\/ramonsoler\/","name":"Ram\u00f3n Soler","image":{"@type":"ImageObject","@id":"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/#authorImage","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/2026\/06\/ramon-soler-new-1-150x150.jpg","width":96,"height":96,"caption":"Ram\u00f3n Soler"}},{"@type":"WebPage","@id":"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/#webpage","url":"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/","name":"Margit Frenk, una luz que no se apag\u00f3 - Revista ExpoFlamenco","description":"Repasamos los tesoros que podemos hallar en 'Nuevo corpus de la antigua l\u00edrica popular hisp\u00e1nica: Siglos XV a XVII', colosal obra de la hispanista y fil\u00f3loga Margit Frenk (Hamburgo, 1925 - Ciudad de M\u00e9xico, 2025) que re\u00fane letras frecuentes en el cante flamenco. Una mujer ejemplar que debemos recordar siempre.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/expoflamenco.com\/revista\/#website"},"breadcrumb":{"@id":"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/#breadcrumblist"},"author":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/ramonsoler\/#author"},"creator":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/ramonsoler\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/margit-frenk-fotograma-documental-el-colegio-de-mexico-y-el-68.webp","@id":"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/#mainImage","width":1140,"height":569,"caption":"Margit Frenk. Fotograma del documental 'El Colegio de M\u00e9xico y el 68'. Producci\u00f3n: Coordinaci\u00f3n de Educaci\u00f3n Digital \/ Colmex Digital."},"primaryImageOfPage":{"@id":"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/#mainImage"},"datePublished":"2026-01-29T11:48:28+01:00","dateModified":"2026-02-18T18:41:32+01:00"},{"@type":"WebSite","@id":"https:\/\/expoflamenco.com\/revista\/#website","url":"https:\/\/expoflamenco.com\/revista\/","name":"Revista ExpoFlamenco","description":"Revista ExpoFlamenco","inLanguage":"es-ES","publisher":{"@id":"https:\/\/expoflamenco.com\/revista\/#organization"}}]}},"aioseo_meta_data":{"post_id":"4347","title":"#post_title #separator_sa #site_title","description":"#post_excerpt","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-02-18 17:44:25","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2026-01-29 09:52:16","updated":"2026-02-18 17:44:30"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\" title=\"Hogar\">Hogar<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\/en-portada\/\" title=\"En Portada\">En Portada<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tMargit Frenk, una luz que no se apag\u00f3\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Hogar","link":"https:\/\/expoflamenco.com\/revista"},{"label":"En Portada","link":"https:\/\/expoflamenco.com\/revista\/en-portada\/"},{"label":"Margit Frenk, una luz que no se apag\u00f3","link":"https:\/\/expoflamenco.com\/revista\/margit-frenk-una-luz-que-no-se-apago\/"}],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/4347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/comments?post=4347"}],"version-history":[{"count":2,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/4347\/revisions"}],"predecessor-version":[{"id":4361,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/4347\/revisions\/4361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media\/4348"}],"wp:attachment":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media?parent=4347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/categories?post=4347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/tags?post=4347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}