{"id":3804,"date":"2025-11-04T15:42:10","date_gmt":"2025-11-04T14:42:10","guid":{"rendered":"https:\/\/expoflamenco.com\/revistanew\/miguel-poveda-presenta-el-arbol-de-la-alegria-nuevo-album-y-gira\/"},"modified":"2025-11-04T15:42:10","modified_gmt":"2025-11-04T14:42:10","slug":"miguel-poveda-presenta-el-arbol-de-la-alegria-nuevo-album-y-gira","status":"publish","type":"post","link":"https:\/\/expoflamenco.com\/revista\/miguel-poveda-presenta-el-arbol-de-la-alegria-nuevo-album-y-gira\/","title":{"rendered":"Miguel Poveda presenta &#8216;El \u00e1rbol de la alegr\u00eda&#8217;: nuevo \u00e1lbum y gira","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<p style=\"font-weight: 400\">El cantaor <strong>Miguel Poveda<\/strong> presenta <strong><em>El \u00c1rbol de La Alegr\u00eda<\/em><\/strong>, su nuevo \u00e1lbum de estudio, que ve la luz el <strong>7 de noviembre<\/strong> y que lleva a los escenarios en una gira hom\u00f3nima. \u201cM\u00e1s que un disco de villancicos, <em>El \u00e1rbol de la alegr\u00eda<\/em> es un abrazo sonoro que re\u00fane el esp\u00edritu de la Navidad en todas sus formas: la risa compartida, el eco de las voces familiares, las sillas vac\u00edas que siguen ocupadas en el coraz\u00f3n y esa chispa de esperanza que nunca se apaga\u201d, afirma el artista.<\/p>\n<p style=\"font-weight: 400\">El artista firma gran parte de la composici\u00f3n imprimiendo su sello personal a cada tema y convirtiendo cada pieza en una creaci\u00f3n \u00fanica que respira ra\u00edz, amor y verdad, con <strong>Jes\u00fas Guerrero<\/strong> a la guitarra, arreglos y producci\u00f3n.<\/p>\n<p style=\"font-weight: 400\"><em>El \u00c1rbol de La Alegr\u00eda<\/em> invita a <strong>recordar, celebrar y sentir<\/strong> una Navidad jubilosa. Poveda abre las puertas de su casa y su memoria para presentarnos a su familia y llevarnos a su <strong>infancia en Badalona<\/strong>, a un barrio humilde que, pese a los tiempos dif\u00edciles, conservaba un esp\u00edritu alegre y esperanzado, en un proyecto que subraya la versatilidad del artista que se adentra en una tem\u00e1tica que nunca antes hab\u00eda grabado.<\/p>\n<p style=\"font-weight: 400\">Adem\u00e1s, el aclamado artista llevar\u00e1 <em>El \u00c1rbol de La Alegr\u00eda<\/em> a los escenarios en una gira que recorrer\u00e1 la geograf\u00eda espa\u00f1ola con un directo que ir\u00e1 de lo tradicional a lo actual, mezclando lenguajes y texturas en una \u201ccoctelera\u201d que respira Navidad sin t\u00f3picos.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><em>\u00abM\u00e1s que un disco de villancicos, &#8216;El \u00e1rbol de la alegr\u00eda&#8217; es un abrazo sonoro que re\u00fane el esp\u00edritu de la Navidad en todas sus formas: la risa compartida, el eco de las voces familiares, las sillas vac\u00edas que siguen ocupadas en el coraz\u00f3n y esa chispa de esperanza que nunca se apaga\u00bb<\/em><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/17\/2025\/11\/gira-arbol-alegria-de-miguel-poveda.webp\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-83766\" src=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/17\/2025\/11\/gira-arbol-alegria-de-miguel-poveda.webp\" alt=\"\" width=\"1308\" height=\"1322\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"font-weight: 400\"><strong>Las primeras fechas de &#8216;El \u00e1rbol de la alegr\u00eda&#8217;<\/strong><\/h2>\n<p style=\"font-weight: 400\">15 NOV \u00b7 ROQUETAS DE MAR | Auditorio de Roquetas de Mar<\/p>\n<p style=\"font-weight: 400\">23 NOV \u00b7 ALICANTE | ADDA<\/p>\n<p style=\"font-weight: 400\">29 NOV \u00b7 TORREMOLINOS | Auditorio Pr\u00edncipe de Asturias<\/p>\n<p style=\"font-weight: 400\">6 DIC \u00b7 LLEIDA | Auditorio La Llotja<\/p>\n<p style=\"font-weight: 400\">14 DIC \u00b7 SAN ROQUE | Teatro Juan Luis Galiardo<\/p>\n<p style=\"font-weight: 400\">16 y 17 DIC \u00b7 C\u00c1DIZ | Gran Teatro Falla<\/p>\n<p style=\"font-weight: 400\">19 DIC \u00b7 MADRID | Starlite<\/p>\n<p style=\"font-weight: 400\">20 DIC \u00b7 PALMA DE MALLORCA | Auditorium de Palma<\/p>\n<p style=\"font-weight: 400\">26 DIC \u00b7 SALAMANCA | CAEM<\/p>\n<p style=\"font-weight: 400\">27 DIC \u00b7 GIJ\u00d3N | Teatro de La Laboral<\/p>\n<p style=\"font-weight: 400\">28 DIC \u00b7 SANTANDER | Palacio de Festivales<\/p>\n<p style=\"font-weight: 400\">30 DIC \u00b7 VALENCIA | Palau de la M\u00fasica<\/p>\n<p style=\"font-weight: 400\">3 ENE \u00b7 JA\u00c9N | Auditorio Infanta Leonor<\/p>\n<p>&nbsp;<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>El cantaor catal\u00e1n lanza el 7 de noviembre su nuevo trabajo discogr\u00e1fico, &#8216;El \u00e1rbol de la alegr\u00eda&#8217;. Un nuevo \u00e1lbum de inspiraci\u00f3n navide\u00f1a que llevar\u00e1 a los escenarios con una gira hom\u00f3nima.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":5,"featured_media":3805,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","jnews-multi-image_gallery":[],"jnews_single_post":null,"jnews_primary_category":{"id":"4226"},"jnews_override_bookmark_settings":{"override_bookmark_button":"0","override_show_bookmark_button":"0"},"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[37,38],"tags":[194,54,353,2445],"class_list":["post-3804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-en-portada","tag-miguel-poveda","tag-cantaor-flamenco","tag-el-arbol-de-la-alegria","tag-nuevo-album","pmpro-has-access"],"acf":[],"aioseo_notices":[],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/3804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/comments?post=3804"}],"version-history":[{"count":0,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/3804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media\/3805"}],"wp:attachment":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media?parent=3804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/categories?post=3804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/tags?post=3804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}