{"id":2189,"date":"2024-12-29T10:50:34","date_gmt":"2024-12-29T09:50:34","guid":{"rendered":"https:\/\/expoflamenco.com\/revistanew\/la-guitarra-flamenca-en-el-siglo-xxi\/"},"modified":"2024-12-29T10:50:34","modified_gmt":"2024-12-29T09:50:34","slug":"la-guitarra-flamenca-en-el-siglo-xxi","status":"publish","type":"post","link":"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/","title":{"rendered":"La guitarra flamenca en el siglo XXI","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<p>Antes de empezar, quiero agradecer a los lectores de esta serie sus sugerencias a trav\u00e9s de las redes sociales. Es muy dif\u00edcil resumir en poco espacio toda una \u00e9poca con todas sus figuras. Ruego que me disculpen por ello, ya que todo est\u00e1 escrito desde el m\u00e1ximo respeto, cari\u00f1o y admiraci\u00f3n por este maravilloso instrumento. As\u00ed que vamos a rematar.<\/p>\n<p>A lo largo de lo que llevamos de siglo, vemos un avance notorio en la guitarra flamenca de concierto y de acompa\u00f1amiento al baile y al cante. La guitarra flamenca es uno de nuestros iconos tradicionales y art\u00edsticos. Evoluciona y se enriquece constantemente en construcci\u00f3n, repertorio, estilo, sonoridad y estudio t\u00e9cnico. Cambios desde la misma esencia del instrumento hasta adaptarse a los tiempos en los que nos ubicamos.\u00a0 En el flamenco, la guitarra no es un mero acompa\u00f1ante, cada vez su protagonismo se hace m\u00e1s visible. Recuerdo conversaciones con dos guitarristas, el onubense <strong>Manuel de la Luz<\/strong> y el sanluque\u00f1o <strong>Ni\u00f1o Manuel<\/strong>, en las que ambos coincid\u00edan en que \u00ablos guitarristas son los alba\u00f1iles y enfermeros del flamenco\u00bb.<\/p>\n<p>La t\u00e9cnica en la guitarra flamenca evoluciona notablemente en los \u00faltimos a\u00f1os. Se incorporan nuevos sonidos y estilos. Se experimenta con fusiones del flamenco tradicional con g\u00e9neros contempor\u00e1neos. Se ampl\u00eda el cat\u00e1logo de texturas musicales que, en consecuencia directa, acercan <strong>el flamenco a nuevos p\u00fablicos de diversas culturas y zonas geogr\u00e1ficas<\/strong>. La tecnolog\u00eda desempe\u00f1a un papel importante. Avances que facilitan la grabaci\u00f3n digital y la difusi\u00f3n a trav\u00e9s de las plataformas de <em>streaming<\/em> y redes sociales. Muchos guitarristas se sirven de herramientas modernas para explorar nuevas posibilidades r\u00edtmicas y sonoras. Y la creaci\u00f3n de contenido audiovisual permite mayor contacto con todo tipo de p\u00fablicos.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><em>\u00abRecuerdo conversaciones con dos guitarristas, el onubense Manuel de la Luz y el sanluque\u00f1o Ni\u00f1o Manuel, en las que ambos coincid\u00edan en que los guitarristas son los alba\u00f1iles y enfermeros del flamenco\u00bb<\/em><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><strong>El di\u00e1logo flamenco entre lo cl\u00e1sico y lo moderno<\/strong>, que desde la esencia busca la innovaci\u00f3n, es un hecho constante. La guitarra flamenca es un veh\u00edculo de expresi\u00f3n y transmisi\u00f3n. Se adapta a las corrientes musicales. Infinidad de artistas exploran nuevos horizontes por medio de fusiones con otros g\u00e9neros musicales. Con este di\u00e1logo entre lo tradicional y lo moderno se preserva su legado hist\u00f3rico y se mantiene la evoluci\u00f3n cultural y musical.<\/p>\n<p>La entrada de la guitarra flamenca en los conservatorios de m\u00fasica es un hecho importante, aunque hay que seguir luchando para que sea una realidad completa. Cuando <strong>Juan Zarzuela Gil<\/strong> inicia esta cruzada desde Jerez, con apoyo pol\u00edtico, docente y de artistas importantes, los resultados aparecen de forma paulatina. La incorporaci\u00f3n est\u00e1 siendo lenta, desde que <strong>Paco Pe\u00f1a<\/strong> o <strong>Manuel Cano<\/strong> iniciaran sus ense\u00f1anzas. Y de la esperada y controvertida <strong>Ley del Flamenco<\/strong> no se aprecia el apoyo que se prometi\u00f3 y se deseaba, ni en lo docente ni en lo art\u00edstico. No obstante, los estudios de guitarra flamenca en los conservatorios afloran, con una hornada de guitarristas de excelente formaci\u00f3n.<\/p>\n<p>A modo de resumen, la guitarra flamenca en el siglo XXI evoluciona de manera considerable en busca de recursos sonoros r\u00edtmicos, arm\u00f3nicos y mel\u00f3dicos. La presencia de la scordatura, que altera la afinaci\u00f3n de una o varias cuerdas para modificar el timbre del instrumento, es recurso t\u00e9cnico musical cada vez m\u00e1s presente. Como las interacciones con otros g\u00e9neros musicales. En los c\u00f3digos tradicionales de acompa\u00f1amiento, se crean m\u00fasicas exclusivas y originales para coreograf\u00edas y temas cantados. No quiere decir que no se hiciera en \u00e9pocas anteriores, pero s\u00ed se manifiestan m\u00e1s en los \u00faltimos a\u00f1os. Las escuelas tradicionales del toque tambi\u00e9n se diferencian a trav\u00e9s de sus m\u00e1ximos exponentes, as\u00ed como la incursi\u00f3n notable de mujeres guitarristas, que desarrollan un toque extraordinario, florece desde diversos puntos de la geograf\u00eda flamenca.<\/p>\n<p>Tambi\u00e9n cabe decir que a\u00fan maestros de generaciones anteriores siguen en activo con un toque muy vigente: <strong>Paco Cepero<\/strong>, <strong>Vicente Amigo<\/strong>, <strong>Juan Manuel Ca\u00f1izares<\/strong>, <strong>Luis Calderito<\/strong>, <strong>Paco<\/strong> y <strong>Miguel \u00c1ngel Cort\u00e9s<\/strong>, <strong>Rafael Riqueni<\/strong>, <strong>Ni\u00f1o de Pura<\/strong>, <strong>Manolo Franco<\/strong>, <strong>Juan Carlos Romero<\/strong>, <strong>Jose Luis de la Paz<\/strong>, <strong>Ricardo Mi\u00f1o<\/strong> o el mismo <strong>Serranito<\/strong>. Aun nos acompa\u00f1an maestros como <strong>Andr\u00e9s Batista<\/strong> y <strong>Juan Serrano<\/strong>.<\/p>\n<p>La escuela jerezana sigue manteniendo su esencia. Guitarristas de la talla de <strong>Alfredo Lagos<\/strong>, <strong>Manuel Parrilla<\/strong>, <strong>Diego del Morao<\/strong>, <strong>Pepe del Morao<\/strong>, <strong>Jos\u00e9 Quevedo Bolita<\/strong>, <strong>Miguel Sallado<\/strong>, <strong>Isaac Moreno<\/strong>, <strong>Antonio Higuero<\/strong>, <strong>Manuel Jero<\/strong> o <strong>Manuel Valencia<\/strong> siguen imprimiendo ese soniquete de sus antecesores. Sin olvidarnos de <strong>Antonio Rey<\/strong>, con sus dos Grammys Latinos. Aparte, C\u00e1diz es una tierra flamenca. Destaca la labor de <strong>Santiago Lara<\/strong> con sus espect\u00e1culos <em>Tauramagia<\/em> y <em>Medea<\/em>, en recuerdo del maestro <strong>Manolo Sanl\u00facar<\/strong>. Y nos acordamos de <strong>Paco Le\u00f3n<\/strong>, <strong>Jes\u00fas Guerrero<\/strong>, <strong>Ni\u00f1o Manuel<\/strong>, <strong>Jos\u00e9 Carlos G\u00f3mez<\/strong>, <strong>Salvador Andrades<\/strong>, <strong>Paco Vidal<\/strong>, <strong>Pituquete<\/strong> o <strong>Keko Baldomero<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><em>\u00abCreo que en multitud de ocasiones nos obcecamos con la complejidad t\u00e9cnica, cuando es reconocido por m\u00fasicos a nivel internacional que menos es m\u00e1s. Al igual que empezar la casa por el tejado cuando la ra\u00edz la encontramos en esas grabaciones antol\u00f3gicas de Miguel Borrull, Ram\u00f3n Montoya, Ni\u00f1o Ricardo o Sabicas\u00bb<\/em><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>Desde Mor\u00f3n de la Frontera se huele el aroma de <strong>Diego del Gastor<\/strong>. Y esa forma tan arcaica y an\u00e1rquica en el toque se conserva hasta d\u00eda de hoy como santo y se\u00f1a de un estilo \u00fanico. Por medio de <strong>Paco del Gastor<\/strong> y su nieto <strong>Gastor de Paco<\/strong> o de <strong>Paco<\/strong> e <strong>Ignacio de Amparo<\/strong> se aprecian esos matices moroneros que tanto identifican ese toque. Aunque Mor\u00f3n tiene un exponente en la figura de <strong>Dani de Mor\u00f3n<\/strong>. Le apreciamos un toque personal, alegre, limpio y exquisito que se arropa entre el bordoneo del juego del comp\u00e1s. Y une la ra\u00edz m\u00e1s flamenca con la vanguardia m\u00e1s actual.<\/p>\n<p>Desde Granada encontramos a <strong>Alfredo Mesa<\/strong>, esposo de la bailaora Ana Cali y profesor de conservatorio. <strong>\u00c1lvaro Martinete<\/strong>, disc\u00edpulo de <strong>Gerardo N\u00fa\u00f1ez<\/strong>. <strong>Jos\u00e9 Ferm\u00edn Fern\u00e1ndez<\/strong>, que en 2019 obtuvo tanto el Bord\u00f3n Minero como el primer premio en el Nacional de C\u00f3rdoba. O el heredero de la saga de los Habichuelas, <strong>Juan Habichuela Nieto<\/strong>. La continuidad de la guitarra almeriense de <strong>Tomatito<\/strong>\u00a0se aprecia en su hijo <strong>Jos\u00e9 del Tomate<\/strong>. Y <strong>Ni\u00f1o Josele<\/strong>, cuyo lenguaje musical es un manantial de riquezas sonoras. M\u00e1laga la Bella nos acompa\u00f1a con <strong>Ismael Rueda<\/strong>, <strong>Daniel Casares<\/strong>, <strong>Paco Javier Jimeno<\/strong>, <strong>Chaparro de M\u00e1laga<\/strong>, <strong>Jos\u00e9 Juan Pantoja<\/strong>, <strong>Luis Fonseca<\/strong>, <strong>Curro de Mar\u00eda<\/strong> o <strong>Salvador Rinqu\u00edn<\/strong>, entre otros.<\/p>\n<p>C\u00f3rdoba es un vergel guitarrero. Destaca el trabajo que se hace desde el <a href=\"https:\/\/csmcordoba.com\/\" target=\"_blank\" rel=\"noopener\">Conservatorio Superior de M\u00fasica Rafael Orozco<\/a> en el itinerario de guitarra flamenca. De la provincia de C\u00f3rdoba escuchamos a <strong>Paco Serrano<\/strong>, <strong>Jos\u00e9 Tom\u00e1s<\/strong>, <strong>Antonio Patrocinio Hijo<\/strong>, <strong>\u00c1ngel Mata<\/strong>, <strong>Rafael Chaparro Hijo<\/strong>, <strong>David Navarro<\/strong> o <strong>Ni\u00f1o Seve<\/strong>. Mencionamos a <strong>Francisco Prieto Currito<\/strong>, hijo del maestro <strong>Antonio Prieto El Curri<\/strong>, o a <strong>Rafael Trenas Hijo,<\/strong> descendiente de <strong>Rafael Trenas<\/strong>. Sin olvidar al maestro <strong>Manuel Silveria<\/strong>.<\/p>\n<p>Otros enclaves como Huelva, aportan importantes figuras. Manuel de la Luz, guitarrista y compositor, escudero de Miguel Poveda o Eva Yerbabuena con dos maravillosos discos en solitario. El moguere\u00f1o <strong>Francis G\u00f3mez<\/strong>, con una prol\u00edfica carrera, y a su vez imprescindible tanto para <strong>Arc\u00e1ngel<\/strong> como para <strong>Joaqu\u00edn Grilo<\/strong>. <strong>\u00c1lvaro Mora<\/strong>, \u00fanico Bord\u00f3n Minero de tierras onubenses, acompa\u00f1ante de las principales figuras tanto del baile como del cante, entre ellas <strong>Jeromo Segura<\/strong>. <strong>Antonio Dovao<\/strong> realiza un trabajo de difusi\u00f3n, con una incre\u00edble plataforma online, adem\u00e1s de su academia y su trabajo como acompa\u00f1ante. <strong>Paco Cruzado<\/strong>, docente y guitarrista, realiza un trabajo espectacular sobre escuela bolera. <strong>Gaspar de Holanda<\/strong>, un holand\u00e9s puramente onubense, presenta dos discos rebosantes de flamencura. Y por supuesto <strong>Joaqu\u00edn Brito<\/strong> o <strong>Carmelo Pic\u00f3n<\/strong>. No me olvido de mi querido y admirado, amigo de la infancia, <strong>Dani V\u00e9lez<\/strong>.<\/p>\n<p>En la provincia de Sevilla contin\u00faa la estela de maestros de generaciones anteriores. En ello vemos a <strong>Pedro Sanchez<\/strong>, hijo de <strong>Naranjito de Triana<\/strong>, <strong>Manuel Herrera<\/strong> padre y <strong>Manuel Herrera Hijo<\/strong>, <strong>Ram\u00f3n Amador<\/strong>, <strong>Curro Vargas <\/strong>de Utrera, <strong>Antonio Garc\u00eda<\/strong> de \u00c9cija o <strong>Rycardo Moreno<\/strong> de Lebrija. Hago eco a varios guitarristas que han hecho del acompa\u00f1amiento al baile una se\u00f1a de identidad de su toque. Uno es <strong>Juan Campallo<\/strong>, y otro, uno de los padres del toque para el baile, <strong>Miguel P\u00e9rez<\/strong>. El joven valor <strong>David de Aharal<\/strong> o el consagrado <strong>Ra\u00fal El Perla<\/strong> son dos realidades guitarreras. Y el maestro <strong>Salvador Gutierrez<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><em>\u00abNo olvidemos que la guitarra es una transmisora de mensajes y sentimientos. Transmite fuerza, sensibilidad, tristeza, alegr\u00eda, rabia, muerte o pasi\u00f3n por medio de seguiriyas, buler\u00edas, fandangos, mineras o soleares. Los tr\u00e9molos, arpegios, alzap\u00faas, rasgueos o picados deben disponerse al servicio de la transmisi\u00f3n de un mensaje. Como dir\u00eda Lorca en diferentes versos de su poema\u00bb<\/em><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>En Extremadura encontramos a <strong>Miguel Vargas<\/strong>, patriarca de los Vargas. <strong>Juan Vargas<\/strong>, su hijo, es la evoluci\u00f3n y herencia de ese toque extreme\u00f1o. Miguel Vargas es el que dota de la identidad flamenca que carec\u00eda al toque extreme\u00f1o. Otro exponente extreme\u00f1o es <strong>Joaqu\u00edn Mu\u00f1ino<\/strong>.<\/p>\n<p>Menci\u00f3n especial al trabajo de un guitarrista alicantino, la tierra del maestro <strong>Mario Escudero<\/strong>. <strong>Alejandro Hurtado<\/strong> tiene dos trabajos discogr\u00e1ficos maravillosos. En uno homenajea y recuerda a los maestros <strong>Manolo de Huelva<\/strong> y <strong>Ram\u00f3n Montoya<\/strong>. En otro expone sus credenciales musicales m\u00e1s flamencas. Con un complet\u00edsimo repertorio de matices, hondura y verdad en su toque. E interpreta el <em>Concierto de Aranjuez<\/em> de <strong>Joaqu\u00edn Rodrigo <\/strong>en recitales a nivel internacional.<\/p>\n<p>El pa\u00eds de la piel de toro tiene una riqueza musical incalculable. Los guitarristas se mueven por toda la geograf\u00eda espa\u00f1ola. Claro ejemplo de ellos son <strong>Josemi Carmona<\/strong>, <strong>Juan Jos\u00e9 Su\u00e1rez<\/strong>, <strong>Agust\u00edn Carbonel El Bola<\/strong>, <strong>Amos Lora<\/strong>, <strong>David Leiva<\/strong>, <strong>Oscar Herrero<\/strong>, <strong>Antonio Fern\u00e1ndez<\/strong>, <strong>Andr\u00e9s S\u00e1nchez<\/strong>, <strong>Jos\u00e9 Luis Mont\u00f3n<\/strong>, <strong>Kilino Jim\u00e9nez<\/strong>, <strong>Jes\u00fas de Rosario, Jer\u00f3nimo Maya<\/strong>, <strong>Juan Ram\u00f3n Caro<\/strong> o <strong>Yeray Cort\u00e9s<\/strong>.<\/p>\n<p>Y por supuesto, ellas. Mujeres con un valor espl\u00e9ndido. Que adem\u00e1s tienen el h\u00e1ndicap de la tradici\u00f3n machista flamenca. Ellas, con tes\u00f3n y trabajo, se sobreponen a ello. Un toque cargado de elegancia, sutileza y desarrollo t\u00e9cnico. Con enjundia en su pureza y flamencura en su desarrollo. Gracias a periodistas como <strong>\u00c1ngeles Cruzado<\/strong> o <strong>Mar\u00eda Jes\u00fas Castro<\/strong>, la tocaora flamenca tiene m\u00e1s visibilidad. Sirvan como modelo las propuestas de <strong>Davinia Ballesteros<\/strong>,<strong> Laura Gonz\u00e1lez<\/strong>, <strong>Antonio Jim\u00e9nez<\/strong>, <strong>Alba Martos<\/strong>, <strong>Celia Morales<\/strong>, <strong>Pilar Alonso<\/strong>, <strong>Lola Yang<\/strong>, <strong>\u00c1ngela Zarzuela<\/strong>, <strong>Teresa Jim\u00e9nez<\/strong>, <strong>Mar\u00eda Jos\u00e9 Matos<\/strong>, <strong>Silvia Brener<\/strong> o <strong>Mercedes Luj\u00e1n. <\/strong>Un cat\u00e1logo que se amplia poco a poco.<\/p>\n<p>La guitarra es un instrumento maravilloso. Su capacidad de transmisi\u00f3n es infinita. Pero muchas veces el desarrollo t\u00e9cnico y el lenguaje sofisticado del toque impiden que el mensaje sea claro y conciso. Me ha emocionado desde una zambra de <strong>Esteban de Sanl\u00facar<\/strong> hasta una sucesi\u00f3n de acordes arpegiados de Miguel Vargas, pasando por <strong>Ni\u00f1o Miguel<\/strong>, <strong>Paco de Luc\u00eda<\/strong>, <strong>Mora\u00edto<\/strong> o <strong>Enique de Melchor<\/strong>. Creo que en multitud de ocasiones nos obcecamos con la complejidad t\u00e9cnica, cuando es reconocido por m\u00fasicos a nivel internacional que menos es m\u00e1s. Al igual que empezar la casa por el tejado cuando la ra\u00edz la encontramos en esas grabaciones antol\u00f3gicas de <strong>Miguel Borrull<\/strong>, Ram\u00f3n Montoya, <strong>Ni\u00f1o Ricardo<\/strong> o <strong>Sabicas<\/strong>. No nos olvidemos que la guitarra es una transmisora de mensajes y sentimientos. Transmite fuerza, sensibilidad, tristeza, alegr\u00eda, rabia, muerte o pasi\u00f3n por medio de seguiriyas, buler\u00edas, fandangos, mineras o soleares. Los tr\u00e9molos, arpegios, alzap\u00faas, rasgueos o picados deben disponerse al servicio de la transmisi\u00f3n de un mensaje. Como dir\u00eda Lorca en diferentes versos de su poema.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Empieza el llanto<\/em><br \/>\n<em>de la guitarra.<\/em><br \/>\n<em>Es imposible<\/em><br \/>\n<em>callarla.<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>A lo largo de lo que llevamos de siglo vemos un avance notorio en la guitarra flamenca de concierto y de acompa\u00f1amiento al baile y al cante. La guitarra flamenca es uno de nuestros iconos tradicionales y art\u00edsticos. Evoluciona y se enriquece constantemente en construcci\u00f3n, repertorio, estilo, sonoridad y estudio t\u00e9cnico.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":23,"featured_media":2190,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","override":[{"template":"2","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"bottom","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_reading_time":"1","post_reading_time_wpm":"250","post_calculate_word_method":"str_word_count","show_zoom_button":"1","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"1","show_inline_post_related":"1"}],"image_override":[{"single_post_thumbnail_size":"no-crop","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Tendencias","sponsored_post_label":"Patrocinado por","disable_ad":"0","subtitle":"A lo largo de lo que llevamos de siglo vemos un avance notorio en la guitarra flamenca de concierto y de acompa\u00f1amiento al baile y al cante. La guitarra flamenca es uno de nuestros iconos tradicionales y art\u00edsticos. Evoluciona y se enriquece constantemente en construcci\u00f3n, repertorio, estilo, sonoridad y estudio t\u00e9cnico."},"jnews_primary_category":{"id":"2969"},"jnews_override_bookmark_settings":{"override_bookmark_button":"0","override_show_bookmark_button":"0"},"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[527,94],"tags":[1954,1288],"class_list":["post-2189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-de-guitarreras-maneras","category-firmas","tag-guitarristas-flamencos","tag-historia-de-la-guitarra-flamenca","pmpro-has-access"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"A lo largo de lo que llevamos de siglo vemos un avance notorio en la guitarra flamenca de concierto y de acompa\u00f1amiento al baile y al cante. La guitarra flamenca es uno de nuestros iconos tradicionales y art\u00edsticos. Evoluciona y se enriquece constantemente en construcci\u00f3n, repertorio, estilo, sonoridad y estudio t\u00e9cnico.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Irra Torres\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/la-guitarra-flamenca-en-el-siglo-xxi\\\/#blogposting\",\"name\":\"La guitarra flamenca en el siglo XXI - Revista ExpoFlamenco\",\"headline\":\"La guitarra flamenca en el siglo XXI\",\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/irratorres\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2026\\\/01\\\/expoflamenco-guitarra-flamenca.webp\",\"width\":1140,\"height\":570},\"datePublished\":\"2024-12-29T10:50:34+01:00\",\"dateModified\":\"2024-12-29T10:50:34+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/la-guitarra-flamenca-en-el-siglo-xxi\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/la-guitarra-flamenca-en-el-siglo-xxi\\\/#webpage\"},\"articleSection\":\"De Guitarreras Maneras, Firmas, guitarristas flamencos, historia de la guitarra flamenca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/la-guitarra-flamenca-en-el-siglo-xxi\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista#listItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/#listItem\",\"name\":\"Firmas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/#listItem\",\"position\":2,\"name\":\"Firmas\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/de-guitarreras-maneras\\\/#listItem\",\"name\":\"De Guitarreras Maneras\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista#listItem\",\"name\":\"Hogar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/de-guitarreras-maneras\\\/#listItem\",\"position\":3,\"name\":\"De Guitarreras Maneras\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/de-guitarreras-maneras\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/la-guitarra-flamenca-en-el-siglo-xxi\\\/#listItem\",\"name\":\"La guitarra flamenca en el siglo XXI\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/#listItem\",\"name\":\"Firmas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/la-guitarra-flamenca-en-el-siglo-xxi\\\/#listItem\",\"position\":4,\"name\":\"La guitarra flamenca en el siglo XXI\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/de-guitarreras-maneras\\\/#listItem\",\"name\":\"De Guitarreras Maneras\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\",\"name\":\"Revista ExpoFlamenco\",\"description\":\"Revista ExpoFlamenco\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/irratorres\\\/#author\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/irratorres\\\/\",\"name\":\"Irra Torres\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/la-guitarra-flamenca-en-el-siglo-xxi\\\/#authorImage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-irratorres.jpeg\",\"width\":96,\"height\":96,\"caption\":\"Irra Torres\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/la-guitarra-flamenca-en-el-siglo-xxi\\\/#webpage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/la-guitarra-flamenca-en-el-siglo-xxi\\\/\",\"name\":\"La guitarra flamenca en el siglo XXI - Revista ExpoFlamenco\",\"description\":\"A lo largo de lo que llevamos de siglo vemos un avance notorio en la guitarra flamenca de concierto y de acompa\\u00f1amiento al baile y al cante. La guitarra flamenca es uno de nuestros iconos tradicionales y art\\u00edsticos. Evoluciona y se enriquece constantemente en construcci\\u00f3n, repertorio, estilo, sonoridad y estudio t\\u00e9cnico.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/la-guitarra-flamenca-en-el-siglo-xxi\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/irratorres\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/irratorres\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2026\\\/01\\\/expoflamenco-guitarra-flamenca.webp\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/la-guitarra-flamenca-en-el-siglo-xxi\\\/#mainImage\",\"width\":1140,\"height\":570},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/la-guitarra-flamenca-en-el-siglo-xxi\\\/#mainImage\"},\"datePublished\":\"2024-12-29T10:50:34+01:00\",\"dateModified\":\"2024-12-29T10:50:34+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/\",\"name\":\"Revista ExpoFlamenco\",\"description\":\"Revista ExpoFlamenco\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script>(function(w,d,s,l,i){w[l]=w[l]||[];w[l].push({'gtm.start': new Date().getTime(),event:'gtm.js'});var f=d.getElementsByTagName(s)[0], j=d.createElement(s),dl=l!='dataLayer'?'&l='+l:'';j.async=true;j.src='https:\/\/www.googletagmanager.com\/gtm.js?id='+i+dl;f.parentNode.insertBefore(j,f);})(window,document,'script','dataLayer',\"GTM-N28N9JJ\");<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La guitarra flamenca en el siglo XXI - Revista ExpoFlamenco<\/title>\n\n","aioseo_head_json":{"title":"La guitarra flamenca en el siglo XXI - Revista ExpoFlamenco","description":"A lo largo de lo que llevamos de siglo vemos un avance notorio en la guitarra flamenca de concierto y de acompa\u00f1amiento al baile y al cante. La guitarra flamenca es uno de nuestros iconos tradicionales y art\u00edsticos. Evoluciona y se enriquece constantemente en construcci\u00f3n, repertorio, estilo, sonoridad y estudio t\u00e9cnico.","canonical_url":"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/#blogposting","name":"La guitarra flamenca en el siglo XXI - Revista ExpoFlamenco","headline":"La guitarra flamenca en el siglo XXI","author":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/irratorres\/#author"},"publisher":{"@id":"https:\/\/expoflamenco.com\/revista\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/expoflamenco-guitarra-flamenca.webp","width":1140,"height":570},"datePublished":"2024-12-29T10:50:34+01:00","dateModified":"2024-12-29T10:50:34+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/#webpage"},"isPartOf":{"@id":"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/#webpage"},"articleSection":"De Guitarreras Maneras, Firmas, guitarristas flamencos, historia de la guitarra flamenca"},{"@type":"BreadcrumbList","@id":"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista#listItem","position":1,"name":"Hogar","item":"https:\/\/expoflamenco.com\/revista","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/#listItem","name":"Firmas"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/#listItem","position":2,"name":"Firmas","item":"https:\/\/expoflamenco.com\/revista\/firmas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/de-guitarreras-maneras\/#listItem","name":"De Guitarreras Maneras"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista#listItem","name":"Hogar"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/de-guitarreras-maneras\/#listItem","position":3,"name":"De Guitarreras Maneras","item":"https:\/\/expoflamenco.com\/revista\/firmas\/de-guitarreras-maneras\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/#listItem","name":"La guitarra flamenca en el siglo XXI"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/#listItem","name":"Firmas"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/#listItem","position":4,"name":"La guitarra flamenca en el siglo XXI","previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/de-guitarreras-maneras\/#listItem","name":"De Guitarreras Maneras"}}]},{"@type":"Organization","@id":"https:\/\/expoflamenco.com\/revista\/#organization","name":"Revista ExpoFlamenco","description":"Revista ExpoFlamenco","url":"https:\/\/expoflamenco.com\/revista\/"},{"@type":"Person","@id":"https:\/\/expoflamenco.com\/revista\/author\/irratorres\/#author","url":"https:\/\/expoflamenco.com\/revista\/author\/irratorres\/","name":"Irra Torres","image":{"@type":"ImageObject","@id":"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/#authorImage","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/2024\/12\/cropped-irratorres.jpeg","width":96,"height":96,"caption":"Irra Torres"}},{"@type":"WebPage","@id":"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/#webpage","url":"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/","name":"La guitarra flamenca en el siglo XXI - Revista ExpoFlamenco","description":"A lo largo de lo que llevamos de siglo vemos un avance notorio en la guitarra flamenca de concierto y de acompa\u00f1amiento al baile y al cante. La guitarra flamenca es uno de nuestros iconos tradicionales y art\u00edsticos. Evoluciona y se enriquece constantemente en construcci\u00f3n, repertorio, estilo, sonoridad y estudio t\u00e9cnico.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/expoflamenco.com\/revista\/#website"},"breadcrumb":{"@id":"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/#breadcrumblist"},"author":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/irratorres\/#author"},"creator":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/irratorres\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/expoflamenco-guitarra-flamenca.webp","@id":"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/#mainImage","width":1140,"height":570},"primaryImageOfPage":{"@id":"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/#mainImage"},"datePublished":"2024-12-29T10:50:34+01:00","dateModified":"2024-12-29T10:50:34+01:00"},{"@type":"WebSite","@id":"https:\/\/expoflamenco.com\/revista\/#website","url":"https:\/\/expoflamenco.com\/revista\/","name":"Revista ExpoFlamenco","description":"Revista ExpoFlamenco","inLanguage":"es-ES","publisher":{"@id":"https:\/\/expoflamenco.com\/revista\/#organization"}}]}},"aioseo_meta_data":{"post_id":"2189","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-07-14 19:43:07","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2026-01-15 19:31:16","updated":"2026-07-14 19:43:07"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\" title=\"Hogar\">Hogar<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\/firmas\/\" title=\"Firmas\">Firmas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\/firmas\/de-guitarreras-maneras\/\" title=\"De Guitarreras Maneras\">De Guitarreras Maneras<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa guitarra flamenca en el siglo XXI\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Hogar","link":"https:\/\/expoflamenco.com\/revista"},{"label":"Firmas","link":"https:\/\/expoflamenco.com\/revista\/firmas\/"},{"label":"De Guitarreras Maneras","link":"https:\/\/expoflamenco.com\/revista\/firmas\/de-guitarreras-maneras\/"},{"label":"La guitarra flamenca en el siglo XXI","link":"https:\/\/expoflamenco.com\/revista\/la-guitarra-flamenca-en-el-siglo-xxi\/"}],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/2189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/comments?post=2189"}],"version-history":[{"count":0,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/2189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media\/2190"}],"wp:attachment":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media?parent=2189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/categories?post=2189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/tags?post=2189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}