{"id":203,"date":"2026-01-12T10:21:33","date_gmt":"2026-01-12T09:21:33","guid":{"rendered":"https:\/\/expoflamenco.com\/revistanew\/2026\/01\/12\/exitazo-de-patricia-guerrero-en-la-plateria\/"},"modified":"2026-01-16T08:45:20","modified_gmt":"2026-01-16T07:45:20","slug":"exitazo-de-patricia-guerrero-en-la-plateria","status":"publish","type":"post","link":"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/","title":{"rendered":"Exitazo de Patricia Guerrero en La Plater\u00eda","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<p class=\"Standard\" style=\"text-align: justify\">Ha arrancado el a\u00f1o 2026 en Granada de la mejor manera posible, con la excelencia del baile de una de las mejores, de mayor proyecci\u00f3n internacional y con numerosos reconocimientos adem\u00e1s de un bagaje en los escenarios tremendo. La <a href=\"https:\/\/laplateria.es\/\" target=\"_blank\" rel=\"noopener\">Pe\u00f1a La Plater\u00eda<\/a> del Albaic\u00edn abri\u00f3 sus puertas a una de sus hijas, socia de la casa, socia de honor de la pe\u00f1a, Premio nacional de danza, Desplante minero de La Uni\u00f3n y actual directora del <a href=\"https:\/\/www.juntadeandalucia.es\/cultura\/flamenco\/ballet-flamenco-andalucia\" target=\"_blank\" rel=\"noopener\">Ballet flamenco de Andaluc\u00eda<\/a>, con unas ganas de triunfar conseguidas que no precisaron m\u00e1s que dos movimientos de hombros para despejar cualquier duda.<b> Patricia Guerrero<\/b>, la gran Patricia, dise\u00f1\u00f3 para la ocasi\u00f3n un espect\u00e1culo preciso, medido, flamenco y elegante en el que no faltaron gui\u00f1os a la est\u00e9tica de las danzas sacromontanas, con esos movimientos de hombro que tan sensuales se antojan.<\/p>\n<p class=\"Standard\" style=\"text-align: justify\">A pesar del fr\u00edo polar en la noche del s\u00e1bado, no cab\u00eda un alfiler en el sal\u00f3n del cante de la pe\u00f1a para admirar, adorar y disfrutar de Patricia. Vino acompa\u00f1ada de la guitarra inconmensurable de <b>Jos\u00e9 Ferm\u00edn Fern\u00e1ndez<\/b>, del cante de <b>Sergio el Colorao<\/b> y el comp\u00e1s de <b>Jos\u00e9 Cort\u00e9s el Indio<\/b>.<\/p>\n<p class=\"Standard\" style=\"text-align: justify\">Aunque Sergio el Colorao ven\u00eda tocado tras estar las navidades con gripe y sin apenas cantar, demostr\u00f3 lo gran profesional que es. Otro se habr\u00eda amparado en el grupo para pasar desapercibido, pero \u00e9l se vino arriba y lo demostr\u00f3 en muchos tercios en los que no hubo trampa ni cart\u00f3n. Lleg\u00f3 hasta donde pudo y bien llegado, sobre todo en la seguiriya.<\/p>\n<p class=\"Standard\" style=\"text-align: justify\">Adem\u00e1s hubo congregaci\u00f3n de artistas de la tierra que tampoco quisieron perderse a la bailaora. <b>Jaime El Parr\u00f3n, Esther Crisol, Vicente M\u00e1rquez Tente, Juan Pinilla<\/b> o <b>Joni Cort\u00e9s<\/b> anduvieron por all\u00ed. El Colorao se present\u00f3 por tientos con la guitarra de Ferm\u00edn y la entrada inicial de Guerrero. Templada, sosegada, limpia en los movimientos, milim\u00e9trica en cada braceo, una definici\u00f3n exacta a caballo entre lo cl\u00e1sico y la vanguardia, su gran fuerte y su sello. Por tangos hubo gui\u00f1os al Sacromonte y a <b>Curro Albaic\u00edn<\/b> que ha instaurado una forma sugerente de provocar con el hombro. Pero Patricia va m\u00e1s all\u00e1 y propone nuevas f\u00f3rmulas a las que agarrarse.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><em>\u00abPatricia Guerrero, la gran Patricia, dise\u00f1\u00f3 para la ocasi\u00f3n un espect\u00e1culo preciso, medido, flamenco y elegante en el que no faltaron gui\u00f1os a la est\u00e9tica de las danzas sacromontanas, con esos movimientos de hombro tan sensuales\u00bb<\/em><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_85315\" aria-describedby=\"caption-attachment-85315\" style=\"width: 899px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/17\/2026\/01\/expoflamenco-patricia-guerrero-3-pena-plateria-granada-ene26-foto-gilberto-gonzalez.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-85315\" src=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/17\/2026\/01\/expoflamenco-patricia-guerrero-3-pena-plateria-granada-ene26-foto-gilberto-gonzalez.jpg\" alt=\"Recital de baile de Patricia Guerrero. Pe\u00f1a La Plater\u00eda, Granada. 10 enero 2026. Foto: Gilberto Gonz\u00e1lez\" width=\"899\" height=\"1600\" \/><\/a><figcaption id=\"caption-attachment-85315\" class=\"wp-caption-text\">Recital de baile de Patricia Guerrero. Pe\u00f1a La Plater\u00eda, Granada. 10 enero 2026. Foto: Gilberto Gonz\u00e1lez<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p class=\"Standard\" style=\"text-align: justify\">Se qued\u00f3 solo Ferm\u00edn en el escenario anunciando: \u00abVoy a tocar algo, \u00bfno? Y se lo voy a dedicar al \u00faltimo mohicano del cante, Jaime el Parr\u00f3n\u00bb. Aquello vino en comp\u00e1s de \u00be con un detalle del <i>Anda jaleo<\/i>, algunos pasajes que me recordaron sutilmente al <strong>Ni\u00f1o Miguel<\/strong>, otros a falsetas de tangos de los<b> Ovejilla<\/b>, o incluso aires de fandangos de Huelva. Ferm\u00edn, \u00bfse puede saber qu\u00e9 hiciste? \u00a1Nos volviste locos con esa forma de tocar! Todo andaba en comp\u00e1s de aparente buler\u00eda pero ven\u00eda y se iba como el soplo del viento. Porque entre medias, un remate de abandolao y de grana\u00ednas dieron la vez a El Colorao, que meti\u00f3 la <i>Baladilla de los tres r\u00edos<\/i> de <b>Pepe Albaic\u00edn,<\/b> de aquel lejano cante y tron\u00edo por milongas que supusieron meter por primer vez a <b>Lorca<\/b> discogr\u00e1ficamente en el flamenco.<\/p>\n<p class=\"Standard\" style=\"text-align: justify\">Por la puerta lateral aparecieron Patricia y El Indio bail\u00e1ndose el uno al otro, recorriendo el pasillo hasta el escenario a fuerza de comp\u00e1s desnudo para bailar ella por alegr\u00edas. A solas, sin guitarra, solo cante y comp\u00e1s guiaron a la bailaora. Sin falta de nada m\u00e1s. Pantal\u00f3n blanco roto y camisa de lunares, \u00a1no se pu\u00e9 s\u00e9 m\u00e1s flamenca! Y sin silencios, ni enga\u00f1os ni remilgos, porque los caracoles en el baile no parece que lo permitan y as\u00ed lo respet\u00f3. Para quien quiera profundizar en su baile, que se fije en c\u00f3mo domina los brazos y los hombros en el conjunto de movimientos de cintura para arriba. Para m\u00ed, sublime.<\/p>\n<p class=\"Standard\" style=\"text-align: justify\">Sigui\u00f3 El Colorao por seguiriyas con la guitarra de Ferm\u00edn, con entrega y solvencia a pesar del postcatarro. Se envalenton\u00f3 en los tercios iniciales de <b>Manuel Molina <\/b>conjugados con otra a caballo entre la del <b>Viejo de la Isla<\/b> y<b> Francisco la Perla<\/b> apost\u00e1ndolo todo al remate de<b> Curro Durse <\/b>mir\u00e1ndose en el espejo de <b>Manuel Torres.<\/b><\/p>\n<p class=\"Standard\">Guerrero dej\u00f3 la sole\u00e1 para el final. Y termin\u00f3 como comenz\u00f3, templada, sosegada, fina, pulcra en la est\u00e9tica y aplicando la danza del siglo XXI al baile del pasado: un <i>t\u00f3tum rev\u00f3lutum<\/i> excepcional.<\/p>\n<p class=\"Standard\">Los artistas se situaron toda la noche en una esquina del escenario lo que no hizo sospechar desde el principio que ver\u00edamos una bata de cola. Y as\u00ed fue, embutida en un traje de lunares gris ajustado, con hombros y mangas de encaje negro y vuelo corto pero fastuoso cuando tomaba protagonismo en el revuelo de volantes. Y para cerrar, un fin de fiesta por buler\u00edas. Como dije antes: \u00a1\u00a1No se pu\u00e9 ped\u00ed m\u00e1s!!<\/p>\n<p>&nbsp;<\/p>\n<p class=\"Standard\"><strong>Ficha art\u00edstica<\/strong><\/p>\n<p class=\"Standard\">Recital de baile de Patricia Guerrero<br \/>\nPe\u00f1a La Plater\u00eda, Granada.<br \/>\n10 de enero de 2026<br \/>\nBaile: Patricia Guerrero<br \/>\nToque: Jos\u00e9 Ferm\u00edn Fern\u00e1ndez<br \/>\nCante: Sergio El Colorao<br \/>\nPalmas: Jos\u00e9 Cort\u00e9s El Indio<\/p>\n<p class=\"Standard\">\n<figure id=\"attachment_85316\" aria-describedby=\"caption-attachment-85316\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/17\/2026\/01\/expoflamenco-patricia-guerrero-2-pena-plateria-granada-ene26-foto-gilberto-gonzalez.jpg\"><img decoding=\"async\" class=\"size-full wp-image-85316\" src=\"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/17\/2026\/01\/expoflamenco-patricia-guerrero-2-pena-plateria-granada-ene26-foto-gilberto-gonzalez.jpg\" alt=\"Recital de baile de Patricia Guerrero. Pe\u00f1a La Plater\u00eda, Granada. 10 enero 2026. Foto: Gilberto Gonz\u00e1lez\" width=\"1600\" height=\"1066\" \/><\/a><figcaption id=\"caption-attachment-85316\" class=\"wp-caption-text\">Recital de baile de Patricia Guerrero. Pe\u00f1a La Plater\u00eda, Granada. 10 enero 2026. Foto: Gilberto Gonz\u00e1lez<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>La bailaora albaicinera despleg\u00f3 todas sus artes para deleitar a una afici\u00f3n ansiosa de buen baile en el que la danza flamenca tradicional y de vanguardia fue la protagonista.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":65,"featured_media":204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","jnews-multi-image_gallery":[],"jnews_single_post":null,"jnews_primary_category":{"id":"248"},"jnews_override_bookmark_settings":{"override_bookmark_button":"0","override_show_bookmark_button":"0"},"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[46,38],"tags":[48,80,81],"class_list":["post-203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronicas","category-en-portada","tag-bailaora-flamenca","tag-patricia-guerrero","tag-pena-la-plateria-de-granada","pmpro-has-access"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La bailaora albaicinera despleg\u00f3 todas sus artes para deleitar a una afici\u00f3n ansiosa de buen baile en el que la danza flamenca tradicional y de vanguardia fue la protagonista.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Antonio Conde\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/exitazo-de-patricia-guerrero-en-la-plateria\\\/#blogposting\",\"name\":\"Exitazo de Patricia Guerrero en La Plater\\u00eda - Revista ExpoFlamenco\",\"headline\":\"Exitazo de Patricia Guerrero en La Plater\\u00eda\",\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/antonioconde\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2026\\\/01\\\/expoflamenco-patricia-guerrero-1-pena-plateria-granada-ene26-foto-gilberto-gonzalez-1.webp\",\"width\":1600,\"height\":900,\"caption\":\"Recital de baile de Patricia Guerrero. Pe\\u00f1a La Plater\\u00eda, Granada. 10 enero 2026. Foto: Gilberto Gonz\\u00e1lez\"},\"datePublished\":\"2026-01-12T10:21:33+01:00\",\"dateModified\":\"2026-01-16T08:45:20+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/exitazo-de-patricia-guerrero-en-la-plateria\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/exitazo-de-patricia-guerrero-en-la-plateria\\\/#webpage\"},\"articleSection\":\"Cr\\u00f3nicas, En Portada, bailaora flamenca, Patricia Guerrero, Pe\\u00f1a La Plater\\u00eda de Granada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/exitazo-de-patricia-guerrero-en-la-plateria\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista#listItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/en-portada\\\/#listItem\",\"name\":\"En Portada\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/en-portada\\\/#listItem\",\"position\":2,\"name\":\"En Portada\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/en-portada\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/exitazo-de-patricia-guerrero-en-la-plateria\\\/#listItem\",\"name\":\"Exitazo de Patricia Guerrero en La Plater\\u00eda\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista#listItem\",\"name\":\"Hogar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/exitazo-de-patricia-guerrero-en-la-plateria\\\/#listItem\",\"position\":3,\"name\":\"Exitazo de Patricia Guerrero en La Plater\\u00eda\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/en-portada\\\/#listItem\",\"name\":\"En Portada\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\",\"name\":\"Revista ExpoFlamenco\",\"description\":\"Revista ExpoFlamenco\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/antonioconde\\\/#author\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/antonioconde\\\/\",\"name\":\"Antonio Conde\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/exitazo-de-patricia-guerrero-en-la-plateria\\\/#authorImage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/antonio-conde-1-150x150.jpg\",\"width\":96,\"height\":96,\"caption\":\"Antonio Conde\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/exitazo-de-patricia-guerrero-en-la-plateria\\\/#webpage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/exitazo-de-patricia-guerrero-en-la-plateria\\\/\",\"name\":\"Exitazo de Patricia Guerrero en La Plater\\u00eda - Revista ExpoFlamenco\",\"description\":\"La bailaora albaicinera despleg\\u00f3 todas sus artes para deleitar a una afici\\u00f3n ansiosa de buen baile en el que la danza flamenca tradicional y de vanguardia fue la protagonista.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/exitazo-de-patricia-guerrero-en-la-plateria\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/antonioconde\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/antonioconde\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2026\\\/01\\\/expoflamenco-patricia-guerrero-1-pena-plateria-granada-ene26-foto-gilberto-gonzalez-1.webp\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/exitazo-de-patricia-guerrero-en-la-plateria\\\/#mainImage\",\"width\":1600,\"height\":900,\"caption\":\"Recital de baile de Patricia Guerrero. Pe\\u00f1a La Plater\\u00eda, Granada. 10 enero 2026. Foto: Gilberto Gonz\\u00e1lez\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/exitazo-de-patricia-guerrero-en-la-plateria\\\/#mainImage\"},\"datePublished\":\"2026-01-12T10:21:33+01:00\",\"dateModified\":\"2026-01-16T08:45:20+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/\",\"name\":\"Revista ExpoFlamenco\",\"description\":\"Revista ExpoFlamenco\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script>(function(w,d,s,l,i){w[l]=w[l]||[];w[l].push({'gtm.start': new Date().getTime(),event:'gtm.js'});var f=d.getElementsByTagName(s)[0], j=d.createElement(s),dl=l!='dataLayer'?'&l='+l:'';j.async=true;j.src='https:\/\/www.googletagmanager.com\/gtm.js?id='+i+dl;f.parentNode.insertBefore(j,f);})(window,document,'script','dataLayer',\"GTM-N28N9JJ\");<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Exitazo de Patricia Guerrero en La Plater\u00eda - Revista ExpoFlamenco<\/title>\n\n","aioseo_head_json":{"title":"Exitazo de Patricia Guerrero en La Plater\u00eda - Revista ExpoFlamenco","description":"La bailaora albaicinera despleg\u00f3 todas sus artes para deleitar a una afici\u00f3n ansiosa de buen baile en el que la danza flamenca tradicional y de vanguardia fue la protagonista.","canonical_url":"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/#blogposting","name":"Exitazo de Patricia Guerrero en La Plater\u00eda - Revista ExpoFlamenco","headline":"Exitazo de Patricia Guerrero en La Plater\u00eda","author":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/antonioconde\/#author"},"publisher":{"@id":"https:\/\/expoflamenco.com\/revista\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/expoflamenco-patricia-guerrero-1-pena-plateria-granada-ene26-foto-gilberto-gonzalez-1.webp","width":1600,"height":900,"caption":"Recital de baile de Patricia Guerrero. Pe\u00f1a La Plater\u00eda, Granada. 10 enero 2026. Foto: Gilberto Gonz\u00e1lez"},"datePublished":"2026-01-12T10:21:33+01:00","dateModified":"2026-01-16T08:45:20+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/#webpage"},"isPartOf":{"@id":"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/#webpage"},"articleSection":"Cr\u00f3nicas, En Portada, bailaora flamenca, Patricia Guerrero, Pe\u00f1a La Plater\u00eda de Granada"},{"@type":"BreadcrumbList","@id":"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista#listItem","position":1,"name":"Hogar","item":"https:\/\/expoflamenco.com\/revista","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/en-portada\/#listItem","name":"En Portada"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/en-portada\/#listItem","position":2,"name":"En Portada","item":"https:\/\/expoflamenco.com\/revista\/en-portada\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/#listItem","name":"Exitazo de Patricia Guerrero en La Plater\u00eda"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista#listItem","name":"Hogar"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/#listItem","position":3,"name":"Exitazo de Patricia Guerrero en La Plater\u00eda","previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/en-portada\/#listItem","name":"En Portada"}}]},{"@type":"Organization","@id":"https:\/\/expoflamenco.com\/revista\/#organization","name":"Revista ExpoFlamenco","description":"Revista ExpoFlamenco","url":"https:\/\/expoflamenco.com\/revista\/"},{"@type":"Person","@id":"https:\/\/expoflamenco.com\/revista\/author\/antonioconde\/#author","url":"https:\/\/expoflamenco.com\/revista\/author\/antonioconde\/","name":"Antonio Conde","image":{"@type":"ImageObject","@id":"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/#authorImage","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/2026\/02\/antonio-conde-1-150x150.jpg","width":96,"height":96,"caption":"Antonio Conde"}},{"@type":"WebPage","@id":"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/#webpage","url":"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/","name":"Exitazo de Patricia Guerrero en La Plater\u00eda - Revista ExpoFlamenco","description":"La bailaora albaicinera despleg\u00f3 todas sus artes para deleitar a una afici\u00f3n ansiosa de buen baile en el que la danza flamenca tradicional y de vanguardia fue la protagonista.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/expoflamenco.com\/revista\/#website"},"breadcrumb":{"@id":"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/#breadcrumblist"},"author":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/antonioconde\/#author"},"creator":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/antonioconde\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/expoflamenco-patricia-guerrero-1-pena-plateria-granada-ene26-foto-gilberto-gonzalez-1.webp","@id":"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/#mainImage","width":1600,"height":900,"caption":"Recital de baile de Patricia Guerrero. Pe\u00f1a La Plater\u00eda, Granada. 10 enero 2026. Foto: Gilberto Gonz\u00e1lez"},"primaryImageOfPage":{"@id":"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/#mainImage"},"datePublished":"2026-01-12T10:21:33+01:00","dateModified":"2026-01-16T08:45:20+01:00"},{"@type":"WebSite","@id":"https:\/\/expoflamenco.com\/revista\/#website","url":"https:\/\/expoflamenco.com\/revista\/","name":"Revista ExpoFlamenco","description":"Revista ExpoFlamenco","inLanguage":"es-ES","publisher":{"@id":"https:\/\/expoflamenco.com\/revista\/#organization"}}]}},"aioseo_meta_data":{"post_id":"203","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-07-14 14:35:29","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2026-01-15 13:40:30","updated":"2026-07-14 14:35:29"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\" title=\"Hogar\">Hogar<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\/en-portada\/\" title=\"En Portada\">En Portada<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tExitazo de Patricia Guerrero en La Plater\u00eda\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Hogar","link":"https:\/\/expoflamenco.com\/revista"},{"label":"En Portada","link":"https:\/\/expoflamenco.com\/revista\/en-portada\/"},{"label":"Exitazo de Patricia Guerrero en La Plater\u00eda","link":"https:\/\/expoflamenco.com\/revista\/exitazo-de-patricia-guerrero-en-la-plateria\/"}],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/comments?post=203"}],"version-history":[{"count":1,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/203\/revisions"}],"predecessor-version":[{"id":361,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/203\/revisions\/361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media\/204"}],"wp:attachment":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media?parent=203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/categories?post=203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/tags?post=203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}