{"id":1227,"date":"2024-06-09T08:31:12","date_gmt":"2024-06-09T06:31:12","guid":{"rendered":"https:\/\/expoflamenco.com\/revistanew\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/"},"modified":"2024-06-09T08:31:12","modified_gmt":"2024-06-09T06:31:12","slug":"con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria","status":"publish","type":"post","link":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/","title":{"rendered":"Con una copla de m\u00e1s (XVI): la cotidianidad carcelaria","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<p>En las coplas carcelarias se suele repetir el nombre de algunos penales famosos. El que m\u00e1s, el del\u00a0<strong>Puerto de Santa Mar\u00eda<\/strong>, de funesto recuerdo:<\/p>\n<p><em>Mejor quisiera estar muerto<\/em><br \/>\n<em>que estar pasando la v\u00eda<\/em><br \/>\n<em>en este penal del Puerto,<\/em><br \/>\n<em>Puerto de Santa Mar\u00eda.<\/em><\/p>\n<p>Por fortuna hace muchos a\u00f1os que es centro cultural, como nos cuentan en este v\u00eddeo en YouTube:<\/p>\n<p>&nbsp;<\/p>\n<div class=\"jeg_video_container jeg_video_content\"><iframe title=\"El antiguo Penal del Puerto se convierte en centro cultural (1995)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/gg1A57P2X5s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<div class=\"fluidvids\"><\/div>\n<p>&nbsp;<\/p>\n<p>Otros muy nombrados tambi\u00e9n son los de Utrera, Cartagena\u2026:<\/p>\n<p><em>Me cogieron los civiles<\/em><br \/>\n<em>robando en Sierra Morena,<\/em><br \/>\n<em>los jueces me condenaron<\/em><br \/>\n<em>y me trajeron andando<\/em><br \/>\n<em>al penal de Cartagena.<\/em><\/p>\n<p>La vida en todos estos presidios \u2013hablamos, sobre todo, del siglo XIX\u2013 era muy dura. A la\u00a0<strong>injusticia general<\/strong>, pues, por un lado, muchas veces el reo era inocente o ten\u00eda una posible atenuante como es el hambre, y, por otro, el no tener dinero supon\u00eda una desasistencia mayor, se a\u00f1ade la angustiosa cotidianidad, ese diario horrible del preso: la mala comida, los castigos, la falta de visitas de sus familiares, las requisas, los toques\u2026<\/p>\n<p>Contamos con un trabajo espec\u00edfico de 2003, editado por el Ayuntamiento de M\u00e1laga, de\u00a0<strong>Jos\u00e9 Calvo Gonz\u00e1lez<\/strong>, titulado\u00a0<em>El Cante por Derecho<\/em>, Derecho con ma\u00fduscula porque se refiere a que se trata el flamenco y sus letras desde la visi\u00f3n del Derecho, de las leyes. En el cap\u00edtulo \u201cVida carcelaria\u201d (pp. 52 a 54) recoge algunas de las letras que citamos tambi\u00e9n aqu\u00ed y que nos han llegado de la tradici\u00f3n. Recomendamos la lectura completa de esta obra, pues trata del tema que abordamos.<\/p>\n<p>He aqu\u00ed una breve antolog\u00eda de este horror, coplas que reflejan esa\u00a0<strong>dura cotidianidad<\/strong>, que responde a la pregunta de en qu\u00e9 se entretiene un preso y qu\u00e9 momentos del d\u00eda anhela o le angustian:<\/p>\n<p><em>A qu\u00e9 me das esos palos.<\/em><br \/>\n<em>\u00bfQu\u00e9 da\u00f1o te he jecho yo?<\/em><br \/>\n<em>Si me he quedao dorm\u00edo,<\/em><br \/>\n<em>er sue\u00f1o rinde ar le\u00f3n.<\/em><\/p>\n<p><em>A un oscuro calaboso<\/em><br \/>\n<em>me llevaban la com\u00eda,<\/em><br \/>\n<em>m\u00e1s l\u00e1grima erramaba<\/em><br \/>\n<em>que boca\u00edtos com\u00eda.<\/em><\/p>\n<p><em>Cuando yega la requisa<\/em><br \/>\n<em>ar cuarto donde\u00b4stoy yo<\/em><br \/>\n<em>echan en abrir la puerta<\/em><br \/>\n<em>dos horitas por rel\u00f3.<\/em><\/p>\n<p>Aqu\u00ed dos similares, dos variantes:<\/p>\n<p><em>Cuando yo estaba en prisiones<\/em><br \/>\n<em>en lo que me entreten\u00eda<\/em><br \/>\n<em>era en escribir tu nombre<\/em><br \/>\n<em>en los ladrillos que hab\u00eda.<\/em><\/p>\n<p><em>Cuando yo estaba en prisiones<\/em><br \/>\n<em>solito me entreten\u00eda<\/em><br \/>\n<em>en contar los eslabones<\/em><br \/>\n<em>que mi cadena ten\u00eda.<\/em><\/p>\n<p>Y lo peor del mundo, lo m\u00e1s temido,\u00a0<strong>un testigo falso<\/strong>:<\/p>\n<p><em>Con cuatro testigos falsos<\/em><br \/>\n<em>y un escribano ladr\u00f3n<\/em><br \/>\n<em>echan un hombre a presidio<\/em><br \/>\n<em>sin que tenga apelaci\u00f3n.<\/em><\/p>\n<p>El\u00a0<strong>chantaje de los carceleros<\/strong>, la explotaci\u00f3n m\u00edsera es denunciada continuamente:<\/p>\n<p><em>El anillo que me distes<\/em><br \/>\n<em>se lo di a la carcelera,<\/em><br \/>\n<em>que me quitara los grillos<\/em><br \/>\n<em>y la libertad me diera.<\/em><\/p>\n<p>Aqu\u00ed vemos al mism\u00edsimo\u00a0<strong>Chocolate<\/strong>\u00a0cantando dese una reja carcelaria, por suerte es una grabaci\u00f3n. Canta esta letra:<\/p>\n<p>&nbsp;<\/p>\n<div><a href=\"https:\/\/www.youtube.com\/watch?v=k2ZkuNpXurY\" target=\"_blank\" rel=\"noopener\">https:\/\/www.youtube.com\/watch?v=k2ZkuNpXurY<\/a><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>Ten\u00eda mi calaboso<\/em><br \/>\n<em>una ventanita ar m\u00e1<\/em><br \/>\n<em>onde yo m\u00b4entreten\u00eda<\/em><br \/>\n<em>en ve los barcos pas\u00e1.<\/em><\/p>\n<p><em>Ya ha sonao el toque de silencio,<\/em><br \/>\n<em>ya nos mandan a callar<\/em><br \/>\n<em>y al toque de diana, madre,<\/em><br \/>\n<em>nos mandan a levantar.<\/em><em>\u00a0 \u00a0<\/em><\/p>\n<p><em>Ya van tres d\u00edas que no como<\/em><br \/>\n<em>m\u00e1s que l\u00e1grimas y pan.<\/em><br \/>\n<em>Estos son los alimentos<\/em><br \/>\n<em>que mis guardianes me dan.<\/em><\/p>\n<p>La vida del preso, minuto a minuto, es dura, como vemos. Lo m\u00e1s agradable, que ser\u00eda ver a <strong>los familiares<\/strong>, a veces se rechaza porque deja, con la posterior ausencia, un gran vac\u00edo, mayor dolor. Dem\u00f3filo recoge:<\/p>\n<p><em>A la reja e la carse<\/em><br \/>\n<em>no me vengas a yor\u00e1,<\/em><br \/>\n<em>ya que no me quitas pena<\/em><br \/>\n<em>no me las vengas a da.<\/em><\/p>\n<p>Se llega al insulto desesperado a\u00a0<strong>la madre<\/strong>, lo m\u00e1s querido, debido a la desesperaci\u00f3n. En esta le recrimina que no haga todo lo posible por liberarlo, empe\u00f1ando algo de valor:<\/p>\n<p><em>Mare, no es ust\u00e9 mi mare,<\/em><br \/>\n<em>que si ust\u00e9 mi mare fuera<\/em><br \/>\n<em>echar\u00eda un empe\u00f1ito<\/em><br \/>\n<em>y de la c\u00e1rcel saliera.<\/em><\/p>\n<p>Pero se echa de menos el afecto de los seres queridos. Por ello, surgen letras como la siguiente, pura recriminaci\u00f3n:<\/p>\n<p><em>Preso en la c\u00e1rcel estoy<\/em><br \/>\n<em>y no me vienes a ver.<\/em><br \/>\n<em>Digo que no tienes alma<\/em><br \/>\n<em>ni coraz\u00f3n de mujer.<\/em><\/p>\n<p>La c\u00e1rcel siempre estropea a las personas. Lo sentencia, sin apelaci\u00f3n en esta copla, a modo de refr\u00e1n infalible:<\/p>\n<p><em>A la puerta del presidio<\/em><br \/>\n<em>Hay escrito con carb\u00f3n:<\/em><br \/>\n<em>Aqu\u00ed el bueno se hace malo,<\/em><br \/>\n<em>el malo se hace peor.<\/em><\/p>\n<p>Lo m\u00e1s valioso para el gitano (y el que no lo es),\u00a0<strong>la salud y la libertad<\/strong>, no se valora hasta que no se pierde:<\/p>\n<p><em>La libertad y la salud<\/em><br \/>\n<em>son prendas de gran val\u00eda,<\/em><br \/>\n<em>y nadie lo reconoce<\/em><br \/>\n<em>hasta que las ve perd\u00edas.<\/em><\/p>\n<p>Bueno, que nunca nos veamos en esta circunstancia y menos inocentemente. La vida en la c\u00e1rcel es, y sobre todo era, dura. Lo atestiguan estas dram\u00e1ticas letras flamencas. Nos despedimos con este cap\u00edtulo de\u00a0<em>Rito y geograf\u00eda del cante<\/em>\u00a0dedicado a las ton\u00e1s (minuto 28\u00a0<strong>Manuel Agujetas<\/strong>\u00a0martinete y carcelera):<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div><a href=\"https:\/\/www.youtube.com\/watch?v=X7vpU5zLl-A\" target=\"_blank\" rel=\"noopener\">https:\/\/www.youtube.com\/watch?v=X7vpU5zLl-A<\/a><\/div>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>La vida en la c\u00e1rcel es, y sobre todo era, dura. Lo atestiguan estas dram\u00e1ticas letras flamencas.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":24,"featured_media":1228,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","jnews-multi-image_gallery":[],"jnews_single_post":null,"jnews_primary_category":[],"jnews_override_bookmark_settings":{"override_bookmark_button":"0","override_show_bookmark_button":"0"},"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[162,94],"tags":[1088,132],"class_list":["post-1227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-con-una-copla-de-mas","category-firmas","tag-letras-carcelarias","tag-letras-flamencas","pmpro-has-access"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La vida en la c\u00e1rcel es, y sobre todo era, dura. Lo atestiguan estas dram\u00e1ticas letras flamencas.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Jos\u00e9 Cenizo\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\\\/#blogposting\",\"name\":\"Con una copla de m\\u00e1s (XVI): la cotidianidad carcelaria - Revista ExpoFlamenco\",\"headline\":\"Con una copla de m\\u00e1s (XVI): la cotidianidad carcelaria\",\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/josecenizo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2026\\\/01\\\/expoflamenco-letras-flamencas-sobre-prision-foto-freepik-middle-aged-man-spending-time-jail.jpg\",\"width\":1300,\"height\":800},\"datePublished\":\"2024-06-09T08:31:12+02:00\",\"dateModified\":\"2024-06-09T08:31:12+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\\\/#webpage\"},\"articleSection\":\"Con una copla de m\\u00e1s, Firmas, letras carcelarias, Letras flamencas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista#listItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/#listItem\",\"name\":\"Firmas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/#listItem\",\"position\":2,\"name\":\"Firmas\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/con-una-copla-de-mas\\\/#listItem\",\"name\":\"Con una copla de m\\u00e1s\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista#listItem\",\"name\":\"Hogar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/con-una-copla-de-mas\\\/#listItem\",\"position\":3,\"name\":\"Con una copla de m\\u00e1s\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/con-una-copla-de-mas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\\\/#listItem\",\"name\":\"Con una copla de m\\u00e1s (XVI): la cotidianidad carcelaria\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/#listItem\",\"name\":\"Firmas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\\\/#listItem\",\"position\":4,\"name\":\"Con una copla de m\\u00e1s (XVI): la cotidianidad carcelaria\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/firmas\\\/con-una-copla-de-mas\\\/#listItem\",\"name\":\"Con una copla de m\\u00e1s\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\",\"name\":\"Revista ExpoFlamenco\",\"description\":\"Revista ExpoFlamenco\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/josecenizo\\\/#author\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/josecenizo\\\/\",\"name\":\"Jos\\u00e9 Cenizo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\\\/#authorImage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/jose-cenizo-120px.jpg\",\"width\":96,\"height\":96,\"caption\":\"Jos\\u00e9 Cenizo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\\\/#webpage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\\\/\",\"name\":\"Con una copla de m\\u00e1s (XVI): la cotidianidad carcelaria - Revista ExpoFlamenco\",\"description\":\"La vida en la c\\u00e1rcel es, y sobre todo era, dura. Lo atestiguan estas dram\\u00e1ticas letras flamencas.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/josecenizo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/josecenizo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2026\\\/01\\\/expoflamenco-letras-flamencas-sobre-prision-foto-freepik-middle-aged-man-spending-time-jail.jpg\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\\\/#mainImage\",\"width\":1300,\"height\":800},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\\\/#mainImage\"},\"datePublished\":\"2024-06-09T08:31:12+02:00\",\"dateModified\":\"2024-06-09T08:31:12+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/\",\"name\":\"Revista ExpoFlamenco\",\"description\":\"Revista ExpoFlamenco\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script>(function(w,d,s,l,i){w[l]=w[l]||[];w[l].push({'gtm.start': new Date().getTime(),event:'gtm.js'});var f=d.getElementsByTagName(s)[0], j=d.createElement(s),dl=l!='dataLayer'?'&l='+l:'';j.async=true;j.src='https:\/\/www.googletagmanager.com\/gtm.js?id='+i+dl;f.parentNode.insertBefore(j,f);})(window,document,'script','dataLayer',\"GTM-N28N9JJ\");<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Con una copla de m\u00e1s (XVI): la cotidianidad carcelaria - Revista ExpoFlamenco<\/title>\n\n","aioseo_head_json":{"title":"Con una copla de m\u00e1s (XVI): la cotidianidad carcelaria - Revista ExpoFlamenco","description":"La vida en la c\u00e1rcel es, y sobre todo era, dura. Lo atestiguan estas dram\u00e1ticas letras flamencas.","canonical_url":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/#blogposting","name":"Con una copla de m\u00e1s (XVI): la cotidianidad carcelaria - Revista ExpoFlamenco","headline":"Con una copla de m\u00e1s (XVI): la cotidianidad carcelaria","author":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/josecenizo\/#author"},"publisher":{"@id":"https:\/\/expoflamenco.com\/revista\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/expoflamenco-letras-flamencas-sobre-prision-foto-freepik-middle-aged-man-spending-time-jail.jpg","width":1300,"height":800},"datePublished":"2024-06-09T08:31:12+02:00","dateModified":"2024-06-09T08:31:12+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/#webpage"},"isPartOf":{"@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/#webpage"},"articleSection":"Con una copla de m\u00e1s, Firmas, letras carcelarias, Letras flamencas"},{"@type":"BreadcrumbList","@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista#listItem","position":1,"name":"Hogar","item":"https:\/\/expoflamenco.com\/revista","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/#listItem","name":"Firmas"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/#listItem","position":2,"name":"Firmas","item":"https:\/\/expoflamenco.com\/revista\/firmas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/con-una-copla-de-mas\/#listItem","name":"Con una copla de m\u00e1s"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista#listItem","name":"Hogar"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/con-una-copla-de-mas\/#listItem","position":3,"name":"Con una copla de m\u00e1s","item":"https:\/\/expoflamenco.com\/revista\/firmas\/con-una-copla-de-mas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/#listItem","name":"Con una copla de m\u00e1s (XVI): la cotidianidad carcelaria"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/#listItem","name":"Firmas"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/#listItem","position":4,"name":"Con una copla de m\u00e1s (XVI): la cotidianidad carcelaria","previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/firmas\/con-una-copla-de-mas\/#listItem","name":"Con una copla de m\u00e1s"}}]},{"@type":"Organization","@id":"https:\/\/expoflamenco.com\/revista\/#organization","name":"Revista ExpoFlamenco","description":"Revista ExpoFlamenco","url":"https:\/\/expoflamenco.com\/revista\/"},{"@type":"Person","@id":"https:\/\/expoflamenco.com\/revista\/author\/josecenizo\/#author","url":"https:\/\/expoflamenco.com\/revista\/author\/josecenizo\/","name":"Jos\u00e9 Cenizo","image":{"@type":"ImageObject","@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/#authorImage","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/2025\/01\/jose-cenizo-120px.jpg","width":96,"height":96,"caption":"Jos\u00e9 Cenizo"}},{"@type":"WebPage","@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/#webpage","url":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/","name":"Con una copla de m\u00e1s (XVI): la cotidianidad carcelaria - Revista ExpoFlamenco","description":"La vida en la c\u00e1rcel es, y sobre todo era, dura. Lo atestiguan estas dram\u00e1ticas letras flamencas.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/expoflamenco.com\/revista\/#website"},"breadcrumb":{"@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/#breadcrumblist"},"author":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/josecenizo\/#author"},"creator":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/josecenizo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/expoflamenco-letras-flamencas-sobre-prision-foto-freepik-middle-aged-man-spending-time-jail.jpg","@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/#mainImage","width":1300,"height":800},"primaryImageOfPage":{"@id":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/#mainImage"},"datePublished":"2024-06-09T08:31:12+02:00","dateModified":"2024-06-09T08:31:12+02:00"},{"@type":"WebSite","@id":"https:\/\/expoflamenco.com\/revista\/#website","url":"https:\/\/expoflamenco.com\/revista\/","name":"Revista ExpoFlamenco","description":"Revista ExpoFlamenco","inLanguage":"es-ES","publisher":{"@id":"https:\/\/expoflamenco.com\/revista\/#organization"}}]}},"aioseo_meta_data":{"post_id":"1227","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-07-14 17:17:38","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2026-01-15 16:30:05","updated":"2026-07-14 17:17:38"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\" title=\"Hogar\">Hogar<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\/firmas\/\" title=\"Firmas\">Firmas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\/firmas\/con-una-copla-de-mas\/\" title=\"Con una copla de m\u00e1s\">Con una copla de m\u00e1s<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tCon una copla de m\u00e1s (XVI): la cotidianidad carcelaria\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Hogar","link":"https:\/\/expoflamenco.com\/revista"},{"label":"Firmas","link":"https:\/\/expoflamenco.com\/revista\/firmas\/"},{"label":"Con una copla de m\u00e1s","link":"https:\/\/expoflamenco.com\/revista\/firmas\/con-una-copla-de-mas\/"},{"label":"Con una copla de m\u00e1s (XVI): la cotidianidad carcelaria","link":"https:\/\/expoflamenco.com\/revista\/con-una-copla-de-mas-xvi-la-cotidianidad-carcelaria\/"}],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/1227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/comments?post=1227"}],"version-history":[{"count":0,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/1227\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media\/1228"}],"wp:attachment":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media?parent=1227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/categories?post=1227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/tags?post=1227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}