{"id":1203,"date":"2024-06-12T17:28:30","date_gmt":"2024-06-12T15:28:30","guid":{"rendered":"https:\/\/expoflamenco.com\/revistanew\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/"},"modified":"2024-06-12T17:28:30","modified_gmt":"2024-06-12T15:28:30","slug":"13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango","status":"publish","type":"post","link":"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/","title":{"rendered":"13 de junio: la provincia de Huelva celebra el D\u00eda del Fandango","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"<p><em>Fandango \u2026 \/ un consejo yo dar\u00eda \/ para cantar un fandango \/ m\u00e1s que busques la med\u00eda \/ precura que sea un desgarro \/ de una emoci\u00f3n de tu v\u00eda.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Ya lo cantaba <strong>Paco Toronjo<\/strong> entre mediados y finales del siglo XX: desgarro y emoci\u00f3n. No hay nada que puede definir mejor a un cante como el fandango de Huelva. Cinco versos, a veces cuatro, convertido en seis tercios que encierran sentencias.<\/p>\n<p>Es 13 de junio de 2024. Hoy cumplir\u00eda 96 a\u00f1os <strong>Francisco Antonio Toronjo Arreciado<\/strong>, Paco Toronjo. Como cada cumplea\u00f1os del insigne cantaor, la provincia de Huelva celebra el <strong>D\u00eda del Fandango<\/strong><em>. <\/em>Fue el cr\u00edtico flamenco onubense <strong>Onofre L\u00f3pez<\/strong> quien d\u00e9cadas atr\u00e1s reclam\u00f3 a las autoridades p\u00fablicas la institucionalizaci\u00f3n de un d\u00eda al a\u00f1o en el que el fandango fuera protagonista absoluto de la actividad cultural. Se consigui\u00f3, no sin poco empe\u00f1o, y cada a\u00f1o uno de los municipios con variante propia es el encargado de organizar dicho evento. En 2024, corresponde a la andevale\u00f1a localidad de <strong>Valverde del Camino<\/strong>, en pleno centro geogr\u00e1fico de la provincia.<\/p>\n<p>Valverde, conocida por su fandango, es tambi\u00e9n municipio de reconocido prestigio en actividades industriales de confecci\u00f3n de calzado. Cuenta con la <strong>Pe\u00f1a Flamenca El Gatillo<\/strong>, en homenaje a <strong>Ildefonso Romero Bermejo<\/strong>, conocido con ese sobrenombre, creador y referente genuino del fandango de la tierra.<\/p>\n<p>Los actos se celebran durante los d\u00edas 12 y 13 de junio, contando con una declaraci\u00f3n institucional que ser\u00e1 le\u00edda por <strong>Mari \u00c1ngeles Cruzado<\/strong> y <strong>Pepe Bravo<\/strong>, este \u00faltimo de la Pe\u00f1a Flamenca El Gatillo. Adem\u00e1s, tendremos ronda de guitarras y actuaciones de Mari \u00c1ngeles Cruzado, <strong>Luc\u00eda Beltr\u00e1n, Consuelo Hald\u00f3n<\/strong> y <strong>Jeromo Segura<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><em>\u00abCantar por Huelva. El cante de la tierra que me vio nacer, y me acoge desde entonces, es una bocanada de aire fresco con una jondura a prueba de gargantas brav\u00edas, lleno de giros y dardos capaces de cogerte de la solapa del alma y no soltarte jam\u00e1s\u00bb<\/em><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/expoflamenco.com\/prensa\/wp-content\/uploads\/sites\/17\/2024\/06\/cartel-dia-del-fandango-huelva-13-junio-2024-valverde-del-camino.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-51274\" src=\"https:\/\/expoflamenco.com\/prensa\/wp-content\/uploads\/sites\/17\/2024\/06\/cartel-dia-del-fandango-huelva-13-junio-2024-valverde-del-camino.jpg\" alt=\"\" width=\"500\" height=\"700\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Para m\u00ed <strong>hablar del fandango es hacerlo del hilo conductor de mi vida.<\/strong> No s\u00e9 lo que es vivir sin escuchar cantar por fandangos, o como a m\u00ed me gusta decir, <em>cantar por Huelva<\/em>. El cante de la tierra que me vio nacer, y me acoge desde entonces, es una bocanada de aire fresco con una jondura a prueba de gargantas brav\u00edas, lleno de giros y dardos capaces de cogerte de la solapa del alma y no soltarte jam\u00e1s. En qu\u00e9 puede parecerse un fandango de la sierra a uno del \u00c1nd\u00e9valo o de la capital o de la costa. No saben a lo mismo y sin embargo no hay paladar que lo deseche.<\/p>\n<p>Institucionalizar un d\u00eda al a\u00f1o un cante como el fandango es hacer instituci\u00f3n a sus cuatro puntales: <strong>Paco Isidro, Pepe Rebollo, Antonio Rengel<\/strong> y Paco Toronjo. Pero tambi\u00e9n a todos aquellos y aquellas que fueron capaces de crear escuela o <em>pellizcar <\/em>el coraz\u00f3n con sus maneras cantaoras, o quienes con sus estudios e investigaciones han elevado este cante a cotas intelectuales. Es tambi\u00e9n institucionalizar el genuino toque de nuestras guitarras. Se sabe que es de Huelva por c\u00f3mo le suenan las seis cuerdas por fandangos.<\/p>\n<p>Afortunadamente, <strong>Huelva vive una \u00e9poca dorada en cuanto al cante en general y, tambi\u00e9n, el fandango en particular.<\/strong> De ello son en mayor o menor medida culpables las asociaciones y pe\u00f1as flamencas, as\u00ed como el auge de escuelas de cante. El fandango ha pisado en los \u00faltimos cincuenta a\u00f1os escenarios tan diferentes como el Vaticano o teatros de Centroeuropa o Am\u00e9rica, y en todos ellos ha sido triunfador absoluto.<\/p>\n<p>En mis recuerdos vitales siempre quedar\u00e1n momentos donde el fandango atraves\u00f3 la noche, o el d\u00eda, y se plant\u00f3 delante de m\u00ed sin dejarme escapar. \u00a1\u00a1Benditos barrotes!!<\/p>\n<p>Y os cuento todo esto no s\u00f3lo para <em>ronear de cante<\/em>, sino para haceros tambi\u00e9n part\u00edcipes de una manera de expresi\u00f3n que pertenece a la humanidad, igual que el flamenco en su conjunto. De <strong>un cante que debe ser valorado por su flamencura y por la rica cultura y antropolog\u00eda aut\u00f3ctona que trae intr\u00ednseca<\/strong>, y porque Huelva y su provincia son m\u00e1s felices compartiendo el fandango con sus amigos de fuera.<\/p>\n<p>Disfruten de este d\u00eda 13 de junio, d\u00eda del fandango. <strong>Y recuerden que s\u00f3lo si emociona es fandango.<\/strong><\/p>\n<h6 style=\"text-align: right;\"><\/h6>\n<p>&nbsp;<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>Como cada cumplea\u00f1os del insigne cantaor Paco Toronjo, la provincia de Huelva celebra el D\u00eda del Fandango. Valverde del Camino acoge la gala.<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":29,"featured_media":1204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"footnotes":""},"categories":[73],"tags":[1065,457,1066],"class_list":["post-1203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","tag-dia-del-fandango","tag-paco-toronjo","tag-valverde-del-camino","pmpro-has-access"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Como cada cumplea\u00f1os del insigne cantaor Paco Toronjo, la provincia de Huelva celebra el D\u00eda del Fandango. Valverde del Camino acoge la gala.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Jes\u00fas Naranjo\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\\\/#blogposting\",\"name\":\"13 de junio: la provincia de Huelva celebra el D\\u00eda del Fandango - Revista ExpoFlamenco\",\"headline\":\"13 de junio: la provincia de Huelva celebra el D\\u00eda del Fandango\",\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/jesusnaranjo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2026\\\/01\\\/expoflamenco-cuadro-de-paco-toronjo-por-miguel-verdejo-rocataliata.jpg\",\"width\":1300,\"height\":800,\"caption\":\"Paco Toronjo. Pintura de Miguel Verdejo Rocataliata.\"},\"datePublished\":\"2024-06-12T17:28:30+02:00\",\"dateModified\":\"2024-06-12T17:28:30+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\\\/#webpage\"},\"articleSection\":\"Opini\\u00f3n, D\\u00eda del Fandango, Paco Toronjo, Valverde del Camino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista#listItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/opinion\\\/#listItem\",\"name\":\"Opini\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/opinion\\\/#listItem\",\"position\":2,\"name\":\"Opini\\u00f3n\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/opinion\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\\\/#listItem\",\"name\":\"13 de junio: la provincia de Huelva celebra el D\\u00eda del Fandango\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista#listItem\",\"name\":\"Hogar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\\\/#listItem\",\"position\":3,\"name\":\"13 de junio: la provincia de Huelva celebra el D\\u00eda del Fandango\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/opinion\\\/#listItem\",\"name\":\"Opini\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\",\"name\":\"Revista ExpoFlamenco\",\"description\":\"Revista ExpoFlamenco\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/jesusnaranjo\\\/#author\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/jesusnaranjo\\\/\",\"name\":\"Jes\\u00fas Naranjo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\\\/#authorImage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/jesus-naranjo.jpg\",\"width\":96,\"height\":96,\"caption\":\"Jes\\u00fas Naranjo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\\\/#webpage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\\\/\",\"name\":\"13 de junio: la provincia de Huelva celebra el D\\u00eda del Fandango - Revista ExpoFlamenco\",\"description\":\"Como cada cumplea\\u00f1os del insigne cantaor Paco Toronjo, la provincia de Huelva celebra el D\\u00eda del Fandango. Valverde del Camino acoge la gala.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/jesusnaranjo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/author\\\/jesusnaranjo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2026\\\/01\\\/expoflamenco-cuadro-de-paco-toronjo-por-miguel-verdejo-rocataliata.jpg\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\\\/#mainImage\",\"width\":1300,\"height\":800,\"caption\":\"Paco Toronjo. Pintura de Miguel Verdejo Rocataliata.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\\\/#mainImage\"},\"datePublished\":\"2024-06-12T17:28:30+02:00\",\"dateModified\":\"2024-06-12T17:28:30+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/\",\"name\":\"Revista ExpoFlamenco\",\"description\":\"Revista ExpoFlamenco\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/revista\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script>(function(w,d,s,l,i){w[l]=w[l]||[];w[l].push({'gtm.start': new Date().getTime(),event:'gtm.js'});var f=d.getElementsByTagName(s)[0], j=d.createElement(s),dl=l!='dataLayer'?'&l='+l:'';j.async=true;j.src='https:\/\/www.googletagmanager.com\/gtm.js?id='+i+dl;f.parentNode.insertBefore(j,f);})(window,document,'script','dataLayer',\"GTM-N28N9JJ\");<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>13 de junio: la provincia de Huelva celebra el D\u00eda del Fandango - Revista ExpoFlamenco<\/title>\n\n","aioseo_head_json":{"title":"13 de junio: la provincia de Huelva celebra el D\u00eda del Fandango - Revista ExpoFlamenco","description":"Como cada cumplea\u00f1os del insigne cantaor Paco Toronjo, la provincia de Huelva celebra el D\u00eda del Fandango. Valverde del Camino acoge la gala.","canonical_url":"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/#blogposting","name":"13 de junio: la provincia de Huelva celebra el D\u00eda del Fandango - Revista ExpoFlamenco","headline":"13 de junio: la provincia de Huelva celebra el D\u00eda del Fandango","author":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/jesusnaranjo\/#author"},"publisher":{"@id":"https:\/\/expoflamenco.com\/revista\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/expoflamenco-cuadro-de-paco-toronjo-por-miguel-verdejo-rocataliata.jpg","width":1300,"height":800,"caption":"Paco Toronjo. Pintura de Miguel Verdejo Rocataliata."},"datePublished":"2024-06-12T17:28:30+02:00","dateModified":"2024-06-12T17:28:30+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/#webpage"},"isPartOf":{"@id":"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/#webpage"},"articleSection":"Opini\u00f3n, D\u00eda del Fandango, Paco Toronjo, Valverde del Camino"},{"@type":"BreadcrumbList","@id":"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista#listItem","position":1,"name":"Hogar","item":"https:\/\/expoflamenco.com\/revista","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/opinion\/#listItem","name":"Opini\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/opinion\/#listItem","position":2,"name":"Opini\u00f3n","item":"https:\/\/expoflamenco.com\/revista\/opinion\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/#listItem","name":"13 de junio: la provincia de Huelva celebra el D\u00eda del Fandango"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista#listItem","name":"Hogar"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/#listItem","position":3,"name":"13 de junio: la provincia de Huelva celebra el D\u00eda del Fandango","previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/revista\/opinion\/#listItem","name":"Opini\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/expoflamenco.com\/revista\/#organization","name":"Revista ExpoFlamenco","description":"Revista ExpoFlamenco","url":"https:\/\/expoflamenco.com\/revista\/"},{"@type":"Person","@id":"https:\/\/expoflamenco.com\/revista\/author\/jesusnaranjo\/#author","url":"https:\/\/expoflamenco.com\/revista\/author\/jesusnaranjo\/","name":"Jes\u00fas Naranjo","image":{"@type":"ImageObject","@id":"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/#authorImage","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/2024\/03\/jesus-naranjo.jpg","width":96,"height":96,"caption":"Jes\u00fas Naranjo"}},{"@type":"WebPage","@id":"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/#webpage","url":"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/","name":"13 de junio: la provincia de Huelva celebra el D\u00eda del Fandango - Revista ExpoFlamenco","description":"Como cada cumplea\u00f1os del insigne cantaor Paco Toronjo, la provincia de Huelva celebra el D\u00eda del Fandango. Valverde del Camino acoge la gala.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/expoflamenco.com\/revista\/#website"},"breadcrumb":{"@id":"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/#breadcrumblist"},"author":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/jesusnaranjo\/#author"},"creator":{"@id":"https:\/\/expoflamenco.com\/revista\/author\/jesusnaranjo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/revista\/wp-content\/uploads\/sites\/46\/2026\/01\/expoflamenco-cuadro-de-paco-toronjo-por-miguel-verdejo-rocataliata.jpg","@id":"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/#mainImage","width":1300,"height":800,"caption":"Paco Toronjo. Pintura de Miguel Verdejo Rocataliata."},"primaryImageOfPage":{"@id":"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/#mainImage"},"datePublished":"2024-06-12T17:28:30+02:00","dateModified":"2024-06-12T17:28:30+02:00"},{"@type":"WebSite","@id":"https:\/\/expoflamenco.com\/revista\/#website","url":"https:\/\/expoflamenco.com\/revista\/","name":"Revista ExpoFlamenco","description":"Revista ExpoFlamenco","inLanguage":"es-ES","publisher":{"@id":"https:\/\/expoflamenco.com\/revista\/#organization"}}]}},"aioseo_meta_data":{"post_id":"1203","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-07-14 17:21:33","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2026-01-15 16:33:16","updated":"2026-07-14 17:21:33"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\" title=\"Hogar\">Hogar<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/revista\/opinion\/\" title=\"Opini\u00f3n\">Opini\u00f3n<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t13 de junio: la provincia de Huelva celebra el D\u00eda del Fandango\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Hogar","link":"https:\/\/expoflamenco.com\/revista"},{"label":"Opini\u00f3n","link":"https:\/\/expoflamenco.com\/revista\/opinion\/"},{"label":"13 de junio: la provincia de Huelva celebra el D\u00eda del Fandango","link":"https:\/\/expoflamenco.com\/revista\/13-de-junio-la-provincia-de-huelva-celebra-el-dia-del-fandango\/"}],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/1203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/comments?post=1203"}],"version-history":[{"count":0,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/posts\/1203\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media\/1204"}],"wp:attachment":[{"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/media?parent=1203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/categories?post=1203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expoflamenco.com\/revista\/wp-json\/wp\/v2\/tags?post=1203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}