{"id":54693,"date":"2024-09-09T23:04:23","date_gmt":"2024-09-09T21:04:23","guid":{"rendered":"https:\/\/expoflamenco.online\/espacio\/?p=54693"},"modified":"2024-09-10T01:14:47","modified_gmt":"2024-09-09T23:14:47","slug":"presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios","status":"publish","type":"post","link":"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/","title":{"rendered":"Presentaci\u00f3n del LI Festival Flamenco de La Mistela de Los Palacios","gt_translate_keys":[{"key":"rendered","format":"text"}]},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El&nbsp;<strong>LI Festival Flamenco de La Mistela de Los Palacios<\/strong>&nbsp;present\u00f3 su programaci\u00f3n en nuestro espacio cultural de Jerez.&nbsp;<strong>Manuel Carvajal<\/strong>, concejal de Cultura, y&nbsp;<strong>Enrique Duque<\/strong>, presidente de la Tertulia Flamenca El Pozo de las Penas, desgranaron la programaci\u00f3n de la cita e hicieron memoria sobre la historia del festival y la Venencia Flamenca. Este a\u00f1o ir\u00e1 a manos del joven cantaor palaciego&nbsp;<strong>Juan Juanelo<\/strong>, que nos deleit\u00f3 con un par de cantes con el que se abre y cierra el v\u00eddeo que van a ver.<\/p>\n\n\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/1phtovdbMIhTjeGgm4EzArOlpLN8ZzAUD\/preview\" width=\"854\" height=\"480\" allow=\"autoplay\"><\/iframe><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"excerpt":{"rendered":"<p>El&nbsp;LI Festival Flamenco de La Mistela de Los Palacios&nbsp;present\u00f3 su programaci\u00f3n en nuestro espacio cultural de Jerez.&nbsp;Manuel Carvajal, concejal de Cultura, y&nbsp;Enrique Duque, presidente de la Tertulia Flamenca El Pozo de las Penas, desgranaron la programaci\u00f3n de la cita e hicieron memoria sobre la historia del festival y la Venencia Flamenca. Este a\u00f1o ir\u00e1 a [&hellip;]<\/p>\n","protected":false,"gt_translate_keys":[{"key":"rendered","format":"html"}]},"author":62,"featured_media":54700,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"footnotes":""},"categories":[46,22],"tags":[417,418,419],"class_list":["post-54693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-encuentros","tag-juan-juanelo-cantaor","tag-la-mistela-de-los-palacios-y-villafranca","tag-venencia-flamenca-de-la-mistela","pmpro-has-access"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El LI Festival Flamenco de La Mistela de Los Palacios present\u00f3 su programaci\u00f3n en nuestro espacio cultural de Jerez. Manuel Carvajal, concejal de Cultura, y Enrique Duque, presidente de la Tertulia Flamenca El Pozo de las Penas, desgranaron la programaci\u00f3n de la cita e hicieron memoria sobre la historia del festival y la Venencia Flamenca. Este a\u00f1o ir\u00e1 a\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Jose Maria Casta\u00f1o\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\\\/#blogposting\",\"name\":\"Presentaci\\u00f3n del LI Festival Flamenco de La Mistela de Los Palacios - Espacio ExpoFlamenco\",\"headline\":\"Presentaci\\u00f3n del LI Festival Flamenco de La Mistela de Los Palacios\",\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/author\\\/josemariacastano\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/09\\\/mistela-portada-web-1140x570px.jpg\",\"width\":1140,\"height\":570},\"datePublished\":\"2024-09-09T23:04:23+02:00\",\"dateModified\":\"2024-09-10T01:14:47+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\\\/#webpage\"},\"articleSection\":\"Actualidad, Encuentros, Juan Juanelo cantaor, La Mistela de Los Palacios y Villafranca, Venencia Flamenca de La Mistela\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/encuentros\\\/#listItem\",\"name\":\"Encuentros\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/encuentros\\\/#listItem\",\"position\":2,\"name\":\"Encuentros\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/encuentros\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\\\/#listItem\",\"name\":\"Presentaci\\u00f3n del LI Festival Flamenco de La Mistela de Los Palacios\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\\\/#listItem\",\"position\":3,\"name\":\"Presentaci\\u00f3n del LI Festival Flamenco de La Mistela de Los Palacios\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/encuentros\\\/#listItem\",\"name\":\"Encuentros\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/#organization\",\"name\":\"Espacio ExpoFlamenco\",\"description\":\"Espacio Cultural en Jerez\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/expoflamenco\\\/\",\"https:\\\/\\\/x.com\\\/expo_flamenco\",\"https:\\\/\\\/www.instagram.com\\\/expoflamenco\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@expoflamenco\",\"https:\\\/\\\/www.youtube.com\\\/expoflamenco\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/expoflamenco\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/author\\\/josemariacastano\\\/#author\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/author\\\/josemariacastano\\\/\",\"name\":\"Jose Maria Casta\\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\\\/#authorImage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Jose-Maria-Castano-150x150.jpg\",\"width\":96,\"height\":96,\"caption\":\"Jose Maria Casta\\u00f1o\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\\\/#webpage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\\\/\",\"name\":\"Presentaci\\u00f3n del LI Festival Flamenco de La Mistela de Los Palacios - Espacio ExpoFlamenco\",\"description\":\"El LI Festival Flamenco de La Mistela de Los Palacios present\\u00f3 su programaci\\u00f3n en nuestro espacio cultural de Jerez. Manuel Carvajal, concejal de Cultura, y Enrique Duque, presidente de la Tertulia Flamenca El Pozo de las Penas, desgranaron la programaci\\u00f3n de la cita e hicieron memoria sobre la historia del festival y la Venencia Flamenca. Este a\\u00f1o ir\\u00e1 a\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/author\\\/josemariacastano\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/author\\\/josemariacastano\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/09\\\/mistela-portada-web-1140x570px.jpg\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\\\/#mainImage\",\"width\":1140,\"height\":570},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\\\/#mainImage\"},\"datePublished\":\"2024-09-09T23:04:23+02:00\",\"dateModified\":\"2024-09-10T01:14:47+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/#website\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/\",\"name\":\"Espacio ExpoFlamenco\",\"description\":\"Espacio Cultural en Jerez\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/espacio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script>(function(w,d,s,l,i){w[l]=w[l]||[];w[l].push({'gtm.start': new Date().getTime(),event:'gtm.js'});var f=d.getElementsByTagName(s)[0], j=d.createElement(s),dl=l!='dataLayer'?'&l='+l:'';j.async=true;j.src='https:\/\/www.googletagmanager.com\/gtm.js?id='+i+dl;f.parentNode.insertBefore(j,f);})(window,document,'script','dataLayer',\"GTM-N28N9JJ\");<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Presentaci\u00f3n del LI Festival Flamenco de La Mistela de Los Palacios - Espacio ExpoFlamenco<\/title>\n\n","aioseo_head_json":{"title":"Presentaci\u00f3n del LI Festival Flamenco de La Mistela de Los Palacios - Espacio ExpoFlamenco","description":"El LI Festival Flamenco de La Mistela de Los Palacios present\u00f3 su programaci\u00f3n en nuestro espacio cultural de Jerez. Manuel Carvajal, concejal de Cultura, y Enrique Duque, presidente de la Tertulia Flamenca El Pozo de las Penas, desgranaron la programaci\u00f3n de la cita e hicieron memoria sobre la historia del festival y la Venencia Flamenca. Este a\u00f1o ir\u00e1 a","canonical_url":"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/#blogposting","name":"Presentaci\u00f3n del LI Festival Flamenco de La Mistela de Los Palacios - Espacio ExpoFlamenco","headline":"Presentaci\u00f3n del LI Festival Flamenco de La Mistela de Los Palacios","author":{"@id":"https:\/\/expoflamenco.com\/espacio\/author\/josemariacastano\/#author"},"publisher":{"@id":"https:\/\/expoflamenco.com\/espacio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/espacio\/wp-content\/uploads\/sites\/25\/2024\/09\/mistela-portada-web-1140x570px.jpg","width":1140,"height":570},"datePublished":"2024-09-09T23:04:23+02:00","dateModified":"2024-09-10T01:14:47+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/#webpage"},"isPartOf":{"@id":"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/#webpage"},"articleSection":"Actualidad, Encuentros, Juan Juanelo cantaor, La Mistela de Los Palacios y Villafranca, Venencia Flamenca de La Mistela"},{"@type":"BreadcrumbList","@id":"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/espacio#listItem","position":1,"name":"Home","item":"https:\/\/expoflamenco.com\/espacio","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/espacio\/encuentros\/#listItem","name":"Encuentros"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/espacio\/encuentros\/#listItem","position":2,"name":"Encuentros","item":"https:\/\/expoflamenco.com\/espacio\/encuentros\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/#listItem","name":"Presentaci\u00f3n del LI Festival Flamenco de La Mistela de Los Palacios"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/espacio#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/#listItem","position":3,"name":"Presentaci\u00f3n del LI Festival Flamenco de La Mistela de Los Palacios","previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/espacio\/encuentros\/#listItem","name":"Encuentros"}}]},{"@type":"Organization","@id":"https:\/\/expoflamenco.com\/espacio\/#organization","name":"Espacio ExpoFlamenco","description":"Espacio Cultural en Jerez","url":"https:\/\/expoflamenco.com\/espacio\/","sameAs":["https:\/\/www.facebook.com\/expoflamenco\/","https:\/\/x.com\/expo_flamenco","https:\/\/www.instagram.com\/expoflamenco\/","https:\/\/www.tiktok.com\/@expoflamenco","https:\/\/www.youtube.com\/expoflamenco","https:\/\/www.linkedin.com\/company\/expoflamenco"]},{"@type":"Person","@id":"https:\/\/expoflamenco.com\/espacio\/author\/josemariacastano\/#author","url":"https:\/\/expoflamenco.com\/espacio\/author\/josemariacastano\/","name":"Jose Maria Casta\u00f1o","image":{"@type":"ImageObject","@id":"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/#authorImage","url":"https:\/\/expoflamenco.com\/espacio\/wp-content\/uploads\/2025\/01\/Jose-Maria-Castano-150x150.jpg","width":96,"height":96,"caption":"Jose Maria Casta\u00f1o"}},{"@type":"WebPage","@id":"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/#webpage","url":"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/","name":"Presentaci\u00f3n del LI Festival Flamenco de La Mistela de Los Palacios - Espacio ExpoFlamenco","description":"El LI Festival Flamenco de La Mistela de Los Palacios present\u00f3 su programaci\u00f3n en nuestro espacio cultural de Jerez. Manuel Carvajal, concejal de Cultura, y Enrique Duque, presidente de la Tertulia Flamenca El Pozo de las Penas, desgranaron la programaci\u00f3n de la cita e hicieron memoria sobre la historia del festival y la Venencia Flamenca. Este a\u00f1o ir\u00e1 a","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/expoflamenco.com\/espacio\/#website"},"breadcrumb":{"@id":"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/#breadcrumblist"},"author":{"@id":"https:\/\/expoflamenco.com\/espacio\/author\/josemariacastano\/#author"},"creator":{"@id":"https:\/\/expoflamenco.com\/espacio\/author\/josemariacastano\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/espacio\/wp-content\/uploads\/sites\/25\/2024\/09\/mistela-portada-web-1140x570px.jpg","@id":"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/#mainImage","width":1140,"height":570},"primaryImageOfPage":{"@id":"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/#mainImage"},"datePublished":"2024-09-09T23:04:23+02:00","dateModified":"2024-09-10T01:14:47+02:00"},{"@type":"WebSite","@id":"https:\/\/expoflamenco.com\/espacio\/#website","url":"https:\/\/expoflamenco.com\/espacio\/","name":"Espacio ExpoFlamenco","description":"Espacio Cultural en Jerez","inLanguage":"es-ES","publisher":{"@id":"https:\/\/expoflamenco.com\/espacio\/#organization"}}]}},"aioseo_meta_data":{"post_id":"54693","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 00:54:30","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2025-05-07 04:02:05","updated":"2026-05-13 00:54:30"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/espacio\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/espacio\/encuentros\/\" title=\"Encuentros\">Encuentros<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tPresentaci\u00f3n del LI Festival Flamenco de La Mistela de Los Palacios\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/expoflamenco.com\/espacio"},{"label":"Encuentros","link":"https:\/\/expoflamenco.com\/espacio\/encuentros\/"},{"label":"Presentaci\u00f3n del LI Festival Flamenco de La Mistela de Los Palacios","link":"https:\/\/expoflamenco.com\/espacio\/presentacion-del-li-festival-flamenco-de-la-mistela-de-los-palacios\/"}],"gt_translate_keys":[{"key":"link","format":"url"}],"_links":{"self":[{"href":"https:\/\/expoflamenco.com\/espacio\/wp-json\/wp\/v2\/posts\/54693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expoflamenco.com\/espacio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expoflamenco.com\/espacio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/espacio\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/espacio\/wp-json\/wp\/v2\/comments?post=54693"}],"version-history":[{"count":0,"href":"https:\/\/expoflamenco.com\/espacio\/wp-json\/wp\/v2\/posts\/54693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/espacio\/wp-json\/wp\/v2\/media\/54700"}],"wp:attachment":[{"href":"https:\/\/expoflamenco.com\/espacio\/wp-json\/wp\/v2\/media?parent=54693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expoflamenco.com\/espacio\/wp-json\/wp\/v2\/categories?post=54693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expoflamenco.com\/espacio\/wp-json\/wp\/v2\/tags?post=54693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}