{"id":730,"count":2,"description":"","link":"https:\/\/expoflamenco.com\/agenda\/tag\/teatro-de-la-abadia\/","name":"Teatro-de-La-Abad\u00eda","slug":"teatro-de-la-abadia","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"qp99EvZ7gDO9YjsGQX1WTdzaSSjVeGG9OIkeeRYaZAU\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/expoflamenco.com\/agenda\/tag\/teatro-de-la-abadia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/730\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/teatro-de-la-abadia\\\/#listItem\",\"name\":\"Teatro-de-La-Abad\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/teatro-de-la-abadia\\\/#listItem\",\"position\":2,\"name\":\"Teatro-de-La-Abad\\u00eda\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/730\\\/#collectionpage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/730\\\/\",\"name\":\"Teatro-de-La-Abad\\u00eda - Agenda ExpoFlamenco\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/730\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#organization\",\"name\":\"Agenda ExpoFlamenco\",\"description\":\"Agenda Flamenca\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/expoflamenco\\\/\",\"https:\\\/\\\/x.com\\\/expo_flamenco\",\"https:\\\/\\\/www.instagram.com\\\/expoflamenco\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@expoflamenco\",\"https:\\\/\\\/www.youtube.com\\\/expoflamenco\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/expoflamenco\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#website\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/\",\"name\":\"Agenda ExpoFlamenco\",\"description\":\"Agenda Flamenca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script>(function(w,d,s,l,i){w[l]=w[l]||[];w[l].push({'gtm.start': new Date().getTime(),event:'gtm.js'});var f=d.getElementsByTagName(s)[0], j=d.createElement(s),dl=l!='dataLayer'?'&l='+l:'';j.async=true;j.src='https:\/\/www.googletagmanager.com\/gtm.js?id='+i+dl;f.parentNode.insertBefore(j,f);})(window,document,'script','dataLayer',\"GTM-N28N9JJ\");<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Teatro-de-La-Abad\u00eda - Agenda ExpoFlamenco<\/title>\n\n","aioseo_head_json":{"title":"Teatro-de-La-Abad\u00eda - Agenda ExpoFlamenco","description":"","canonical_url":"https:\/\/expoflamenco.com\/agenda\/tag\/teatro-de-la-abadia\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"qp99EvZ7gDO9YjsGQX1WTdzaSSjVeGG9OIkeeRYaZAU","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/tags\/730\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda#listItem","position":1,"name":"Home","item":"https:\/\/expoflamenco.com\/agenda","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/tag\/teatro-de-la-abadia\/#listItem","name":"Teatro-de-La-Abad\u00eda"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/tag\/teatro-de-la-abadia\/#listItem","position":2,"name":"Teatro-de-La-Abad\u00eda","previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/tags\/730\/#collectionpage","url":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/tags\/730\/","name":"Teatro-de-La-Abad\u00eda - Agenda ExpoFlamenco","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/expoflamenco.com\/agenda\/#website"},"breadcrumb":{"@id":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/tags\/730\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/expoflamenco.com\/agenda\/#organization","name":"Agenda ExpoFlamenco","description":"Agenda Flamenca","url":"https:\/\/expoflamenco.com\/agenda\/","sameAs":["https:\/\/www.facebook.com\/expoflamenco\/","https:\/\/x.com\/expo_flamenco","https:\/\/www.instagram.com\/expoflamenco\/","https:\/\/www.tiktok.com\/@expoflamenco","https:\/\/www.youtube.com\/expoflamenco","https:\/\/www.linkedin.com\/company\/expoflamenco"]},{"@type":"WebSite","@id":"https:\/\/expoflamenco.com\/agenda\/#website","url":"https:\/\/expoflamenco.com\/agenda\/","name":"Agenda ExpoFlamenco","description":"Agenda Flamenca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/expoflamenco.com\/agenda\/#organization"}}]}},"aioseo_meta_data":{"term_id":"730","title":null,"description":null,"keywords":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"pillar_content":null,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-10-01 18:40:42","breadcrumb_settings":null,"created":"2025-10-01 18:40:42","updated":"2025-10-01 18:40:42"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/agenda\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tTeatro-de-La-Abad\u00eda\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/expoflamenco.com\/agenda"},{"label":"Teatro-de-La-Abad\u00eda","link":"https:\/\/expoflamenco.com\/agenda\/tag\/teatro-de-la-abadia\/"}],"_links":{"self":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/tags\/730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/posts?tags=730"},{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec-events?tags=730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}