{"id":80591,"date":"2025-09-25T15:14:39","date_gmt":"2025-09-25T13:14:39","guid":{"rendered":"https:\/\/expoflamenco.com\/agenda\/?post_type=mec-events&#038;p=80591"},"modified":"2025-09-26T13:05:00","modified_gmt":"2025-09-26T11:05:00","slug":"vii-dia-del-flamenco-en-la-provincia-de-cadiz","status":"publish","type":"mec-events","link":"https:\/\/expoflamenco.com\/agenda\/eventos\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\/","title":{"rendered":"VII D\u00cdA DEL FLAMENCO EN LA PROVINCIA DE C\u00c1DIZ"},"content":{"rendered":"<hr \/>\n<h3 style=\"text-align: center\">26 y 27 de Septiembre<\/h3>\n<hr \/>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-80603\" src=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/09\/Cartel-Dia-de-la-Provincia-2025-1.webp\" alt=\"\" width=\"1140\" height=\"814\" srcset=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/09\/Cartel-Dia-de-la-Provincia-2025-1.webp 1140w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/09\/Cartel-Dia-de-la-Provincia-2025-1-300x214.webp 300w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/09\/Cartel-Dia-de-la-Provincia-2025-1-1024x731.webp 1024w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/09\/Cartel-Dia-de-la-Provincia-2025-1-768x548.webp 768w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/09\/Cartel-Dia-de-la-Provincia-2025-1-120x86.webp 120w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/09\/Cartel-Dia-de-la-Provincia-2025-1-350x250.webp 350w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/09\/Cartel-Dia-de-la-Provincia-2025-1-750x536.webp 750w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" \/><\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><em>\u00bfQuieres que t<strong>u evento aparezca en nuestra agenda? Es totalmente gratuito:<\/strong>\u00a0envianos la informaci\u00f3n lo mas completa posible y subiremos conforme relevancia y nuestra disponibilidad, tendr\u00e1n prioridad los eventos con programaci\u00f3n mensual o ciclos.<\/em><br \/>\n<em>Y si quieres<strong>\u00a0anunciarte con nosotros,<\/strong>\u00a0tenemos muchas opciones, envianos un mensaje y buscamos lo mejor para ti.\u00a0<strong>agenda@expoflamenco.com.<\/strong><\/em><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>26 y 27 de Septiembre &nbsp; \u00bfQuieres que tu evento aparezca en nuestra agenda? Es totalmente gratuito:\u00a0envianos la informaci\u00f3n lo mas completa posible y subiremos conforme relevancia y nuestra disponibilidad, tendr\u00e1n prioridad los eventos con programaci\u00f3n mensual o ciclos. Y si quieres\u00a0anunciarte con nosotros,\u00a0tenemos muchas opciones, envianos un mensaje y buscamos lo mejor para ti.\u00a0agenda@expoflamenco.com.<\/p>\n","protected":false},"author":56,"featured_media":80592,"comment_status":"open","ping_status":"closed","template":"","tags":[1708,1709,1248],"mec_category":[477,478,476,479],"mec_sponsor":[],"class_list":["post-80591","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-cadiz-flamenco","tag-dia-del-flamenco","tag-internacional","mec_category-baile","mec_category-cante","mec_category-concierto","mec_category-guitarra","pmpro-has-access"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"26 y 27 de Septiembre \u00bfQuieres que tu evento aparezca en nuestra agenda? Es totalmente gratuito: envianos la informaci\u00f3n lo mas completa posible y subiremos conforme relevancia y nuestra disponibilidad, tendr\u00e1n prioridad los eventos con programaci\u00f3n mensual o ciclos. Y si quieres anunciarte con nosotros, tenemos muchas opciones, envianos un mensaje y buscamos lo mejor para ti. agenda@expoflamenco.com.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Patri Manes\"\/>\n\t<meta name=\"google-site-verification\" content=\"qp99EvZ7gDO9YjsGQX1WTdzaSSjVeGG9OIkeeRYaZAU\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/expoflamenco.com\/agenda\/eventos\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/#listItem\",\"name\":\"Eventos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/#listItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/internacional\\\/#listItem\",\"name\":\"internacional\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/internacional\\\/#listItem\",\"position\":3,\"name\":\"internacional\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/internacional\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\\\/#listItem\",\"name\":\"VII D\\u00cdA DEL FLAMENCO EN LA PROVINCIA DE C\\u00c1DIZ\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/#listItem\",\"name\":\"Eventos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\\\/#listItem\",\"position\":4,\"name\":\"VII D\\u00cdA DEL FLAMENCO EN LA PROVINCIA DE C\\u00c1DIZ\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/internacional\\\/#listItem\",\"name\":\"internacional\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#organization\",\"name\":\"Agenda ExpoFlamenco\",\"description\":\"Agenda Flamenca\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/expoflamenco\\\/\",\"https:\\\/\\\/x.com\\\/expo_flamenco\",\"https:\\\/\\\/www.instagram.com\\\/expoflamenco\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@expoflamenco\",\"https:\\\/\\\/www.youtube.com\\\/expoflamenco\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/expoflamenco\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/#author\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/\",\"name\":\"Patri Manes\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\\\/#authorImage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Imagen-de-WhatsApp-2024-09-12-a-las-12.38.47_89f61861-150x150.jpg\",\"width\":96,\"height\":96,\"caption\":\"Patri Manes\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\\\/#webpage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\\\/\",\"name\":\"VII D\\u00cdA DEL FLAMENCO EN LA PROVINCIA DE C\\u00c1DIZ - Agenda ExpoFlamenco\",\"description\":\"26 y 27 de Septiembre \\u00bfQuieres que tu evento aparezca en nuestra agenda? Es totalmente gratuito: envianos la informaci\\u00f3n lo mas completa posible y subiremos conforme relevancia y nuestra disponibilidad, tendr\\u00e1n prioridad los eventos con programaci\\u00f3n mensual o ciclos. Y si quieres anunciarte con nosotros, tenemos muchas opciones, envianos un mensaje y buscamos lo mejor para ti. agenda@expoflamenco.com.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2025\\\/09\\\/cabecera-cadizflamenco.webp\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\\\/#mainImage\",\"width\":1140,\"height\":570,\"caption\":\"Cartel dia del flamenco de C\\u00e1diz 2025\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\\\/#mainImage\"},\"datePublished\":\"2025-09-25T15:14:39+02:00\",\"dateModified\":\"2025-09-26T13:05:00+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#website\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/\",\"name\":\"Agenda ExpoFlamenco\",\"description\":\"Agenda Flamenca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script>(function(w,d,s,l,i){w[l]=w[l]||[];w[l].push({'gtm.start': new Date().getTime(),event:'gtm.js'});var f=d.getElementsByTagName(s)[0], j=d.createElement(s),dl=l!='dataLayer'?'&l='+l:'';j.async=true;j.src='https:\/\/www.googletagmanager.com\/gtm.js?id='+i+dl;f.parentNode.insertBefore(j,f);})(window,document,'script','dataLayer',\"GTM-N28N9JJ\");<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>VII D\u00cdA DEL FLAMENCO EN LA PROVINCIA DE C\u00c1DIZ - Agenda ExpoFlamenco<\/title>\n\n","aioseo_head_json":{"title":"VII D\u00cdA DEL FLAMENCO EN LA PROVINCIA DE C\u00c1DIZ - Agenda ExpoFlamenco","description":"26 y 27 de Septiembre \u00bfQuieres que tu evento aparezca en nuestra agenda? Es totalmente gratuito: envianos la informaci\u00f3n lo mas completa posible y subiremos conforme relevancia y nuestra disponibilidad, tendr\u00e1n prioridad los eventos con programaci\u00f3n mensual o ciclos. Y si quieres anunciarte con nosotros, tenemos muchas opciones, envianos un mensaje y buscamos lo mejor para ti. agenda@expoflamenco.com.","canonical_url":"https:\/\/expoflamenco.com\/agenda\/eventos\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"qp99EvZ7gDO9YjsGQX1WTdzaSSjVeGG9OIkeeRYaZAU","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda#listItem","position":1,"name":"Home","item":"https:\/\/expoflamenco.com\/agenda","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/#listItem","name":"Eventos"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/#listItem","position":2,"name":"Eventos","item":"https:\/\/expoflamenco.com\/agenda\/eventos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/tag\/internacional\/#listItem","name":"internacional"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/tag\/internacional\/#listItem","position":3,"name":"internacional","item":"https:\/\/expoflamenco.com\/agenda\/tag\/internacional\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\/#listItem","name":"VII D\u00cdA DEL FLAMENCO EN LA PROVINCIA DE C\u00c1DIZ"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/#listItem","name":"Eventos"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\/#listItem","position":4,"name":"VII D\u00cdA DEL FLAMENCO EN LA PROVINCIA DE C\u00c1DIZ","previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/tag\/internacional\/#listItem","name":"internacional"}}]},{"@type":"Organization","@id":"https:\/\/expoflamenco.com\/agenda\/#organization","name":"Agenda ExpoFlamenco","description":"Agenda Flamenca","url":"https:\/\/expoflamenco.com\/agenda\/","sameAs":["https:\/\/www.facebook.com\/expoflamenco\/","https:\/\/x.com\/expo_flamenco","https:\/\/www.instagram.com\/expoflamenco\/","https:\/\/www.tiktok.com\/@expoflamenco","https:\/\/www.youtube.com\/expoflamenco","https:\/\/www.linkedin.com\/company\/expoflamenco"]},{"@type":"Person","@id":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/#author","url":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/","name":"Patri Manes","image":{"@type":"ImageObject","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\/#authorImage","url":"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/2024\/09\/Imagen-de-WhatsApp-2024-09-12-a-las-12.38.47_89f61861-150x150.jpg","width":96,"height":96,"caption":"Patri Manes"}},{"@type":"WebPage","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\/#webpage","url":"https:\/\/expoflamenco.com\/agenda\/eventos\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\/","name":"VII D\u00cdA DEL FLAMENCO EN LA PROVINCIA DE C\u00c1DIZ - Agenda ExpoFlamenco","description":"26 y 27 de Septiembre \u00bfQuieres que tu evento aparezca en nuestra agenda? Es totalmente gratuito: envianos la informaci\u00f3n lo mas completa posible y subiremos conforme relevancia y nuestra disponibilidad, tendr\u00e1n prioridad los eventos con programaci\u00f3n mensual o ciclos. Y si quieres anunciarte con nosotros, tenemos muchas opciones, envianos un mensaje y buscamos lo mejor para ti. agenda@expoflamenco.com.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/expoflamenco.com\/agenda\/#website"},"breadcrumb":{"@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\/#breadcrumblist"},"author":{"@id":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/#author"},"creator":{"@id":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/09\/cabecera-cadizflamenco.webp","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\/#mainImage","width":1140,"height":570,"caption":"Cartel dia del flamenco de C\u00e1diz 2025"},"primaryImageOfPage":{"@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\/#mainImage"},"datePublished":"2025-09-25T15:14:39+02:00","dateModified":"2025-09-26T13:05:00+02:00"},{"@type":"WebSite","@id":"https:\/\/expoflamenco.com\/agenda\/#website","url":"https:\/\/expoflamenco.com\/agenda\/","name":"Agenda ExpoFlamenco","description":"Agenda Flamenca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/expoflamenco.com\/agenda\/#organization"}}]}},"aioseo_meta_data":{"post_id":"80591","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-10-09 03:11:56","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-09-25 10:53:19","updated":"2025-11-26 22:47:55"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/agenda\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/agenda\/eventos\/\" title=\"Eventos\">Eventos<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/agenda\/tag\/internacional\/\" title=\"internacional\">internacional<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tVII D\u00cdA DEL FLAMENCO EN LA PROVINCIA DE C\u00c1DIZ\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/expoflamenco.com\/agenda"},{"label":"Eventos","link":"https:\/\/expoflamenco.com\/agenda\/eventos\/"},{"label":"internacional","link":"https:\/\/expoflamenco.com\/agenda\/tag\/internacional\/"},{"label":"VII D\u00cdA DEL FLAMENCO EN LA PROVINCIA DE C\u00c1DIZ","link":"https:\/\/expoflamenco.com\/agenda\/eventos\/vii-dia-del-flamenco-en-la-provincia-de-cadiz\/"}],"_links":{"self":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec-events\/80591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/comments?post=80591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/media\/80592"}],"wp:attachment":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/media?parent=80591"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/tags?post=80591"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec_category?post=80591"},{"taxonomy":"mec_sponsor","embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec_sponsor?post=80591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}