{"id":80569,"date":"2025-09-10T14:11:17","date_gmt":"2025-09-10T12:11:17","guid":{"rendered":"https:\/\/expoflamenco.com\/agenda\/?post_type=mec-events&#038;p=80569"},"modified":"2025-09-10T14:27:51","modified_gmt":"2025-09-10T12:27:51","slug":"festival-flamenco-de-la-mistela-2025","status":"publish","type":"mec-events","link":"https:\/\/expoflamenco.com\/agenda\/eventos\/festival-flamenco-de-la-mistela-2025\/","title":{"rendered":"Festival Flamenco de la Mistela 2025"},"content":{"rendered":"<hr \/>\n<h3 style=\"text-align: center;\">10, 11, 17 y 18 de octubre<br \/>\nTeatro Municipal Pedro P\u00e9rez Fern\u00e1ndez.<\/h3>\n<hr \/>\n<h4>Programaci\u00f3n<\/h4>\n<p style=\"text-align: left;\"><b>Viernes 10 de octubre<\/b><span style=\"font-weight: 400;\">: J<\/span><i><span style=\"font-weight: 400;\">uan Tom\u00e1s de la Mol\u00eda<\/span><\/i><span style=\"font-weight: 400;\">, joven bailaor de Trebujena, recibir\u00e1 la Venencia Flamenca al Baile 2025 y presentar\u00e1 el espect\u00e1culo <\/span><i><span style=\"font-weight: 400;\">Vertebrados<\/span><\/i><span style=\"font-weight: 400;\">, 65 minutos por buler\u00edas, dirigido por <\/span><i><span style=\"font-weight: 400;\">Manuel Li\u00f1an<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p style=\"text-align: left;\"><b>S\u00e1bado 11 de octubre<\/b><span style=\"font-weight: 400;\">: <\/span><i><span style=\"font-weight: 400;\">Andr\u00e9s Mar\u00edn<\/span><\/i><span style=\"font-weight: 400;\"> y <\/span><i><span style=\"font-weight: 400;\">Ana Morales<\/span><\/i><span style=\"font-weight: 400;\">, Premios Nacionales de Danza 2022, presentar\u00e1n <\/span><i><span style=\"font-weight: 400;\">Matarife\/Para\u00edso<\/span><\/i><span style=\"font-weight: 400;\">, una propuesta esc\u00e9nica transgresora y muy personal.<\/span><\/p>\n<p style=\"text-align: left;\"><b>Viernes 17 de octubre<\/b><span style=\"font-weight: 400;\">: <\/span><i><span style=\"font-weight: 400;\">Rosario \u201cLa Tremendita\u201d<\/span><\/i><span style=\"font-weight: 400;\">, cantaora, compositora e instrumentista de Triana, ofrecer\u00e1 su espect\u00e1culo <\/span><i><span style=\"font-weight: 400;\">Tr\u00e1nsito (Huyendo del ruido)<\/span><\/i><span style=\"font-weight: 400;\">, acompa\u00f1ada por la guitarra de <\/span><i><span style=\"font-weight: 400;\">Dani de Mor\u00f3n<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p style=\"text-align: left;\"><b>S\u00e1bado 18 de octubre<\/b><span style=\"font-weight: 400;\">: <\/span><i><span style=\"font-weight: 400;\">David Pe\u00f1a Dorantes<\/span><\/i><span style=\"font-weight: 400;\"> cerrar\u00e1 el festival con un concierto conmemorativo de las bodas de plata de su aclamada obra <\/span><i><span style=\"font-weight: 400;\">Orobroy<\/span><\/i><span style=\"font-weight: 400;\">, acompa\u00f1ado por la bailaora <\/span><i><span style=\"font-weight: 400;\">Leonor Leal<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p>\n<figure id=\"attachment_80573\" aria-describedby=\"caption-attachment-80573\" style=\"width: 582px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-80573\" src=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/09\/Mistela-2025-cartel.webp\" alt=\"Cartel Festival Mistela 2025\" width=\"582\" height=\"816\" srcset=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/09\/Mistela-2025-cartel.webp 582w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/09\/Mistela-2025-cartel-214x300.webp 214w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/09\/Mistela-2025-cartel-360x504.webp 360w\" sizes=\"(max-width: 582px) 100vw, 582px\" \/><figcaption id=\"caption-attachment-80573\" class=\"wp-caption-text\">Cartel Festival Mistela 2025<\/figcaption><\/figure>\n<div class=\"field field--name-field-evento-fecha-inicio field--type-datetime field--label-inline\" role=\"region\" aria-label=\"Fecha inicio\" data-insuit-uuid=\"5a4b0a4a-738a-49cb-8d79-0891acc662aa\">\n<hr \/>\n<\/div>\n<blockquote>\n<div role=\"region\" aria-label=\"Fecha inicio\" data-insuit-uuid=\"5a4b0a4a-738a-49cb-8d79-0891acc662aa\">\n<hr \/>\n<p><em>\u00bfQuieres que tu\u00a0<strong>evento<\/strong>\u00a0aparezca en nuestra agenda? Es totalmente\u00a0<strong>gratuito<\/strong>: envianos la informaci\u00f3n lo mas completa posible y subiremos conforme relevancia y nuestra disponibilidad, tendr\u00e1n prioridad los eventos con programaci\u00f3n mensual o ciclos.<\/em><br \/>\n<em>Y si quieres<strong>\u00a0anunciarte con nosotros<\/strong>, tenemos muchas opciones, envianos un mensaje y buscamos lo mejor para ti.\u00a0<strong>agenda@expoflamenco.com.<\/strong><\/em><\/p>\n<\/div>\n<\/blockquote>\n<div class=\"field field--name-field-evento-fecha-fin field--type-datetime field--label-inline\" role=\"region\" aria-label=\"Fecha fin\" data-insuit-uuid=\"fa87d991-eaae-4698-a038-63590bf9715d\">\n<div class=\"field--item\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Mistela sigue siendo un referente del flamenco aut\u00e9ntico, con capacidad para unir tradici\u00f3n e innovaci\u00f3n, artistas consagrados y nuevos talentos. Un festival que trasciende lo local para situarse como una de las grandes citas del calendario flamenco nacional.<\/p>\n","protected":false},"author":56,"featured_media":80572,"comment_status":"open","ping_status":"closed","template":"","tags":[746,686,685,655,1706,653,961,196,654,1707],"mec_category":[477,478,472,479],"mec_sponsor":[],"class_list":["post-80569","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-746","tag-ana-morales","tag-andres-marin","tag-bajo-guadalquivir","tag-dorantes","tag-festival-de-la-mistela","tag-rosario-la-tremendita","tag-sevilla","tag-teatro-municipal-pedro-perez-fernandez","tag-tomas-de-la-molia","mec_category-baile","mec_category-cante","mec_category-festival","mec_category-guitarra","pmpro-has-access"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Mistela sigue siendo un referente del flamenco aut\u00e9ntico, con capacidad para unir tradici\u00f3n e innovaci\u00f3n, artistas consagrados y nuevos talentos. Un festival que trasciende lo local para situarse como una de las grandes citas del calendario flamenco nacional.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Patri Manes\"\/>\n\t<meta name=\"google-site-verification\" content=\"qp99EvZ7gDO9YjsGQX1WTdzaSSjVeGG9OIkeeRYaZAU\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/expoflamenco.com\/agenda\/eventos\/festival-flamenco-de-la-mistela-2025\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/festival-flamenco-de-la-mistela-2025\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/#listItem\",\"name\":\"Eventos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/#listItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/sevilla\\\/#listItem\",\"name\":\"Sevilla\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/sevilla\\\/#listItem\",\"position\":3,\"name\":\"Sevilla\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/sevilla\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/festival-flamenco-de-la-mistela-2025\\\/#listItem\",\"name\":\"Festival Flamenco de la Mistela 2025\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/#listItem\",\"name\":\"Eventos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/festival-flamenco-de-la-mistela-2025\\\/#listItem\",\"position\":4,\"name\":\"Festival Flamenco de la Mistela 2025\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/sevilla\\\/#listItem\",\"name\":\"Sevilla\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#organization\",\"name\":\"Agenda ExpoFlamenco\",\"description\":\"Agenda Flamenca\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/expoflamenco\\\/\",\"https:\\\/\\\/x.com\\\/expo_flamenco\",\"https:\\\/\\\/www.instagram.com\\\/expoflamenco\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@expoflamenco\",\"https:\\\/\\\/www.youtube.com\\\/expoflamenco\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/expoflamenco\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/#author\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/\",\"name\":\"Patri Manes\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/festival-flamenco-de-la-mistela-2025\\\/#authorImage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Imagen-de-WhatsApp-2024-09-12-a-las-12.38.47_89f61861-150x150.jpg\",\"width\":96,\"height\":96,\"caption\":\"Patri Manes\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/festival-flamenco-de-la-mistela-2025\\\/#webpage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/festival-flamenco-de-la-mistela-2025\\\/\",\"name\":\"Festival Flamenco de la Mistela 2025 - Agenda ExpoFlamenco\",\"description\":\"La Mistela sigue siendo un referente del flamenco aut\\u00e9ntico, con capacidad para unir tradici\\u00f3n e innovaci\\u00f3n, artistas consagrados y nuevos talentos. Un festival que trasciende lo local para situarse como una de las grandes citas del calendario flamenco nacional.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/festival-flamenco-de-la-mistela-2025\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2025\\\/09\\\/Mistela-2025-cabecera.webp\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/festival-flamenco-de-la-mistela-2025\\\/#mainImage\",\"width\":1140,\"height\":570,\"caption\":\"Cartel  Festival Mistela 2025\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/festival-flamenco-de-la-mistela-2025\\\/#mainImage\"},\"datePublished\":\"2025-09-10T14:11:17+02:00\",\"dateModified\":\"2025-09-10T14:27:51+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#website\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/\",\"name\":\"Agenda ExpoFlamenco\",\"description\":\"Agenda Flamenca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script>(function(w,d,s,l,i){w[l]=w[l]||[];w[l].push({'gtm.start': new Date().getTime(),event:'gtm.js'});var f=d.getElementsByTagName(s)[0], j=d.createElement(s),dl=l!='dataLayer'?'&l='+l:'';j.async=true;j.src='https:\/\/www.googletagmanager.com\/gtm.js?id='+i+dl;f.parentNode.insertBefore(j,f);})(window,document,'script','dataLayer',\"GTM-N28N9JJ\");<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Festival Flamenco de la Mistela 2025 - Agenda ExpoFlamenco<\/title>\n\n","aioseo_head_json":{"title":"Festival Flamenco de la Mistela 2025 - Agenda ExpoFlamenco","description":"La Mistela sigue siendo un referente del flamenco aut\u00e9ntico, con capacidad para unir tradici\u00f3n e innovaci\u00f3n, artistas consagrados y nuevos talentos. Un festival que trasciende lo local para situarse como una de las grandes citas del calendario flamenco nacional.","canonical_url":"https:\/\/expoflamenco.com\/agenda\/eventos\/festival-flamenco-de-la-mistela-2025\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"qp99EvZ7gDO9YjsGQX1WTdzaSSjVeGG9OIkeeRYaZAU","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/festival-flamenco-de-la-mistela-2025\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda#listItem","position":1,"name":"Home","item":"https:\/\/expoflamenco.com\/agenda","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/#listItem","name":"Eventos"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/#listItem","position":2,"name":"Eventos","item":"https:\/\/expoflamenco.com\/agenda\/eventos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/tag\/sevilla\/#listItem","name":"Sevilla"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/tag\/sevilla\/#listItem","position":3,"name":"Sevilla","item":"https:\/\/expoflamenco.com\/agenda\/tag\/sevilla\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/festival-flamenco-de-la-mistela-2025\/#listItem","name":"Festival Flamenco de la Mistela 2025"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/#listItem","name":"Eventos"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/festival-flamenco-de-la-mistela-2025\/#listItem","position":4,"name":"Festival Flamenco de la Mistela 2025","previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/tag\/sevilla\/#listItem","name":"Sevilla"}}]},{"@type":"Organization","@id":"https:\/\/expoflamenco.com\/agenda\/#organization","name":"Agenda ExpoFlamenco","description":"Agenda Flamenca","url":"https:\/\/expoflamenco.com\/agenda\/","sameAs":["https:\/\/www.facebook.com\/expoflamenco\/","https:\/\/x.com\/expo_flamenco","https:\/\/www.instagram.com\/expoflamenco\/","https:\/\/www.tiktok.com\/@expoflamenco","https:\/\/www.youtube.com\/expoflamenco","https:\/\/www.linkedin.com\/company\/expoflamenco"]},{"@type":"Person","@id":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/#author","url":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/","name":"Patri Manes","image":{"@type":"ImageObject","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/festival-flamenco-de-la-mistela-2025\/#authorImage","url":"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/2024\/09\/Imagen-de-WhatsApp-2024-09-12-a-las-12.38.47_89f61861-150x150.jpg","width":96,"height":96,"caption":"Patri Manes"}},{"@type":"WebPage","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/festival-flamenco-de-la-mistela-2025\/#webpage","url":"https:\/\/expoflamenco.com\/agenda\/eventos\/festival-flamenco-de-la-mistela-2025\/","name":"Festival Flamenco de la Mistela 2025 - Agenda ExpoFlamenco","description":"La Mistela sigue siendo un referente del flamenco aut\u00e9ntico, con capacidad para unir tradici\u00f3n e innovaci\u00f3n, artistas consagrados y nuevos talentos. Un festival que trasciende lo local para situarse como una de las grandes citas del calendario flamenco nacional.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/expoflamenco.com\/agenda\/#website"},"breadcrumb":{"@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/festival-flamenco-de-la-mistela-2025\/#breadcrumblist"},"author":{"@id":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/#author"},"creator":{"@id":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/09\/Mistela-2025-cabecera.webp","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/festival-flamenco-de-la-mistela-2025\/#mainImage","width":1140,"height":570,"caption":"Cartel  Festival Mistela 2025"},"primaryImageOfPage":{"@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/festival-flamenco-de-la-mistela-2025\/#mainImage"},"datePublished":"2025-09-10T14:11:17+02:00","dateModified":"2025-09-10T14:27:51+02:00"},{"@type":"WebSite","@id":"https:\/\/expoflamenco.com\/agenda\/#website","url":"https:\/\/expoflamenco.com\/agenda\/","name":"Agenda ExpoFlamenco","description":"Agenda Flamenca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/expoflamenco.com\/agenda\/#organization"}}]}},"aioseo_meta_data":{"post_id":"80569","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-10-09 03:10:14","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-09-10 11:45:19","updated":"2025-11-26 22:47:54"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/agenda\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/agenda\/eventos\/\" title=\"Eventos\">Eventos<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/agenda\/tag\/sevilla\/\" title=\"Sevilla\">Sevilla<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tFestival Flamenco de la Mistela 2025\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/expoflamenco.com\/agenda"},{"label":"Eventos","link":"https:\/\/expoflamenco.com\/agenda\/eventos\/"},{"label":"Sevilla","link":"https:\/\/expoflamenco.com\/agenda\/tag\/sevilla\/"},{"label":"Festival Flamenco de la Mistela 2025","link":"https:\/\/expoflamenco.com\/agenda\/eventos\/festival-flamenco-de-la-mistela-2025\/"}],"_links":{"self":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec-events\/80569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/comments?post=80569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/media\/80572"}],"wp:attachment":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/media?parent=80569"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/tags?post=80569"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec_category?post=80569"},{"taxonomy":"mec_sponsor","embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec_sponsor?post=80569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}