{"id":79257,"date":"2025-04-15T12:03:46","date_gmt":"2025-04-15T10:03:46","guid":{"rendered":"https:\/\/expoflamenco.com\/agenda\/?post_type=mec-events&#038;p=79257"},"modified":"2025-04-15T12:28:57","modified_gmt":"2025-04-15T10:28:57","slug":"origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba","status":"publish","type":"mec-events","link":"https:\/\/expoflamenco.com\/agenda\/eventos\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\/","title":{"rendered":"C\u00f3rdoba: Origen &#8211; La semilla de los tiempos"},"content":{"rendered":"<hr \/>\n<h3 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"24\" data-lineheight=\"normal\"><span class=\"tribe-event-date-start\">8 de julio &#8211; 20:30h\u00a0 &#8211; Gran Teatro C\u00f3rdoba<\/span><\/h3>\n<hr \/>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\"><em><strong>ORIGEN. La semilla de los tiempos. Rapsodia en 7 actos\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: left;\">Patricia Guerrero y Fahmi Alqhai, acompa\u00f1ados del Ballet Flamenco de Andaluc\u00eda y de la Accademia del Piacere dialogan en busca de un pasado y un presente comunes por la m\u00fasica y la danza, v\u00eda universal de hermandad de pueblos y culturas. Dos estilos que se abrazan y se funden. Un camino com\u00fan entre el flamenco y la tradici\u00f3n hist\u00f3rica de la m\u00fasica espa\u00f1ola.<\/p>\n<ul class=\"list-inline\" style=\"text-align: left;\">\n<li><strong>Direcci\u00f3n de escena y coreograf\u00eda:<\/strong>\u00a0Patricia Guerrero<\/li>\n<li><strong>Direcci\u00f3n musical:<\/strong>\u00a0Fahmi Alqhai<\/li>\n<\/ul>\n<div class=\"extraInfo pt-4\">\n<p style=\"text-align: left;\">Accademia del Piacere<br \/>\nDirector: Fahmi Alqhai<\/p>\n<p style=\"text-align: left;\">Ballet Flamenco de Andalucia<br \/>\nDirectora: Patricia Guerrero<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-79255 size-full\" src=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/04\/ballet-flamenco-andalucia-2025-origens-04.webp\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/04\/ballet-flamenco-andalucia-2025-origens-04.webp 800w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/04\/ballet-flamenco-andalucia-2025-origens-04-300x200.webp 300w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/04\/ballet-flamenco-andalucia-2025-origens-04-768x512.webp 768w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/04\/ballet-flamenco-andalucia-2025-origens-04-391x260.webp 391w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/04\/ballet-flamenco-andalucia-2025-origens-04-750x500.webp 750w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<figure id=\"attachment_79256\" aria-describedby=\"caption-attachment-79256\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-79256 size-full\" src=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/04\/ballet-flamenco-andalucia-2025-origens-05.webp\" alt=\"Origen - La semilla de los tiempos\" width=\"800\" height=\"533\" srcset=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/04\/ballet-flamenco-andalucia-2025-origens-05.webp 800w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/04\/ballet-flamenco-andalucia-2025-origens-05-300x200.webp 300w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/04\/ballet-flamenco-andalucia-2025-origens-05-768x512.webp 768w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/04\/ballet-flamenco-andalucia-2025-origens-05-391x260.webp 391w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/04\/ballet-flamenco-andalucia-2025-origens-05-750x500.webp 750w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-79256\" class=\"wp-caption-text\">Origen &#8211; La semilla de los tiempos<\/figcaption><\/figure>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Guerrero y Alqhai, acompa\u00f1ados del Ballet Flamenco de Andaluc\u00eda y de la Accademia del Piacere dialogan en busca de un pasado y un presente comunes por la m\u00fasica y la danza, v\u00eda universal de hermandad de pueblos y culturas. Dos estilos que se abrazan y se funden. Un camino com\u00fan entre el flamenco y la tradici\u00f3n hist\u00f3rica de la m\u00fasica espa\u00f1ola.<\/p>\n","protected":false},"author":56,"featured_media":79248,"comment_status":"open","ping_status":"closed","template":"","tags":[1439,1405,1438,892,1437],"mec_category":[477,475],"mec_sponsor":[],"class_list":["post-79257","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-academia-de-piaccere","tag-ballet-flamenco-andalucia","tag-fahmi-alqhai","tag-patricia-guerrero","tag-sevilla-flamenco","mec_category-baile","mec_category-espectaculo","pmpro-has-access"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Guerrero y Alqhai, acompa\u00f1ados del Ballet Flamenco de Andaluc\u00eda y de la Accademia del Piacere dialogan en busca de un pasado y un presente comunes por la m\u00fasica y la danza, v\u00eda universal de hermandad de pueblos y culturas. Dos estilos que se abrazan y se funden. Un camino com\u00fan entre el flamenco y la tradici\u00f3n hist\u00f3rica de la m\u00fasica espa\u00f1ola.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Patri Manes\"\/>\n\t<meta name=\"google-site-verification\" content=\"qp99EvZ7gDO9YjsGQX1WTdzaSSjVeGG9OIkeeRYaZAU\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/expoflamenco.com\/agenda\/eventos\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/#listItem\",\"name\":\"Eventos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/#listItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/patricia-guerrero\\\/#listItem\",\"name\":\"patricia-guerrero\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/patricia-guerrero\\\/#listItem\",\"position\":3,\"name\":\"patricia-guerrero\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/patricia-guerrero\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\\\/#listItem\",\"name\":\"C\\u00f3rdoba: Origen &#8211; La semilla de los tiempos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/#listItem\",\"name\":\"Eventos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\\\/#listItem\",\"position\":4,\"name\":\"C\\u00f3rdoba: Origen &#8211; La semilla de los tiempos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/patricia-guerrero\\\/#listItem\",\"name\":\"patricia-guerrero\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#organization\",\"name\":\"Agenda ExpoFlamenco\",\"description\":\"Agenda Flamenca\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/expoflamenco\\\/\",\"https:\\\/\\\/x.com\\\/expo_flamenco\",\"https:\\\/\\\/www.instagram.com\\\/expoflamenco\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@expoflamenco\",\"https:\\\/\\\/www.youtube.com\\\/expoflamenco\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/expoflamenco\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/#author\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/\",\"name\":\"Patri Manes\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\\\/#authorImage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Imagen-de-WhatsApp-2024-09-12-a-las-12.38.47_89f61861-150x150.jpg\",\"width\":96,\"height\":96,\"caption\":\"Patri Manes\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\\\/#webpage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\\\/\",\"name\":\"C\\u00f3rdoba: Origen \\u2013 La semilla de los tiempos - Agenda ExpoFlamenco\",\"description\":\"Guerrero y Alqhai, acompa\\u00f1ados del Ballet Flamenco de Andaluc\\u00eda y de la Accademia del Piacere dialogan en busca de un pasado y un presente comunes por la m\\u00fasica y la danza, v\\u00eda universal de hermandad de pueblos y culturas. Dos estilos que se abrazan y se funden. Un camino com\\u00fan entre el flamenco y la tradici\\u00f3n hist\\u00f3rica de la m\\u00fasica espa\\u00f1ola.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2025\\\/04\\\/ballet-flamenco-andalucia-2025.webp\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\\\/#mainImage\",\"width\":800,\"height\":400,\"caption\":\"Origen - La semilla de los tiempos - Ballet Flamenco de Andalucia\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\\\/#mainImage\"},\"datePublished\":\"2025-04-15T12:03:46+02:00\",\"dateModified\":\"2025-04-15T12:28:57+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#website\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/\",\"name\":\"Agenda ExpoFlamenco\",\"description\":\"Agenda Flamenca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script>(function(w,d,s,l,i){w[l]=w[l]||[];w[l].push({'gtm.start': new Date().getTime(),event:'gtm.js'});var f=d.getElementsByTagName(s)[0], j=d.createElement(s),dl=l!='dataLayer'?'&l='+l:'';j.async=true;j.src='https:\/\/www.googletagmanager.com\/gtm.js?id='+i+dl;f.parentNode.insertBefore(j,f);})(window,document,'script','dataLayer',\"GTM-N28N9JJ\");<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>C\u00f3rdoba: Origen \u2013 La semilla de los tiempos - Agenda ExpoFlamenco<\/title>\n\n","aioseo_head_json":{"title":"C\u00f3rdoba: Origen \u2013 La semilla de los tiempos - Agenda ExpoFlamenco","description":"Guerrero y Alqhai, acompa\u00f1ados del Ballet Flamenco de Andaluc\u00eda y de la Accademia del Piacere dialogan en busca de un pasado y un presente comunes por la m\u00fasica y la danza, v\u00eda universal de hermandad de pueblos y culturas. Dos estilos que se abrazan y se funden. Un camino com\u00fan entre el flamenco y la tradici\u00f3n hist\u00f3rica de la m\u00fasica espa\u00f1ola.","canonical_url":"https:\/\/expoflamenco.com\/agenda\/eventos\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"qp99EvZ7gDO9YjsGQX1WTdzaSSjVeGG9OIkeeRYaZAU","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda#listItem","position":1,"name":"Home","item":"https:\/\/expoflamenco.com\/agenda","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/#listItem","name":"Eventos"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/#listItem","position":2,"name":"Eventos","item":"https:\/\/expoflamenco.com\/agenda\/eventos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/tag\/patricia-guerrero\/#listItem","name":"patricia-guerrero"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/tag\/patricia-guerrero\/#listItem","position":3,"name":"patricia-guerrero","item":"https:\/\/expoflamenco.com\/agenda\/tag\/patricia-guerrero\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\/#listItem","name":"C\u00f3rdoba: Origen &#8211; La semilla de los tiempos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/#listItem","name":"Eventos"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\/#listItem","position":4,"name":"C\u00f3rdoba: Origen &#8211; La semilla de los tiempos","previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/tag\/patricia-guerrero\/#listItem","name":"patricia-guerrero"}}]},{"@type":"Organization","@id":"https:\/\/expoflamenco.com\/agenda\/#organization","name":"Agenda ExpoFlamenco","description":"Agenda Flamenca","url":"https:\/\/expoflamenco.com\/agenda\/","sameAs":["https:\/\/www.facebook.com\/expoflamenco\/","https:\/\/x.com\/expo_flamenco","https:\/\/www.instagram.com\/expoflamenco\/","https:\/\/www.tiktok.com\/@expoflamenco","https:\/\/www.youtube.com\/expoflamenco","https:\/\/www.linkedin.com\/company\/expoflamenco"]},{"@type":"Person","@id":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/#author","url":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/","name":"Patri Manes","image":{"@type":"ImageObject","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\/#authorImage","url":"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/2024\/09\/Imagen-de-WhatsApp-2024-09-12-a-las-12.38.47_89f61861-150x150.jpg","width":96,"height":96,"caption":"Patri Manes"}},{"@type":"WebPage","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\/#webpage","url":"https:\/\/expoflamenco.com\/agenda\/eventos\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\/","name":"C\u00f3rdoba: Origen \u2013 La semilla de los tiempos - Agenda ExpoFlamenco","description":"Guerrero y Alqhai, acompa\u00f1ados del Ballet Flamenco de Andaluc\u00eda y de la Accademia del Piacere dialogan en busca de un pasado y un presente comunes por la m\u00fasica y la danza, v\u00eda universal de hermandad de pueblos y culturas. Dos estilos que se abrazan y se funden. Un camino com\u00fan entre el flamenco y la tradici\u00f3n hist\u00f3rica de la m\u00fasica espa\u00f1ola.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/expoflamenco.com\/agenda\/#website"},"breadcrumb":{"@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\/#breadcrumblist"},"author":{"@id":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/#author"},"creator":{"@id":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/04\/ballet-flamenco-andalucia-2025.webp","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\/#mainImage","width":800,"height":400,"caption":"Origen - La semilla de los tiempos - Ballet Flamenco de Andalucia"},"primaryImageOfPage":{"@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\/#mainImage"},"datePublished":"2025-04-15T12:03:46+02:00","dateModified":"2025-04-15T12:28:57+02:00"},{"@type":"WebSite","@id":"https:\/\/expoflamenco.com\/agenda\/#website","url":"https:\/\/expoflamenco.com\/agenda\/","name":"Agenda ExpoFlamenco","description":"Agenda Flamenca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/expoflamenco.com\/agenda\/#organization"}}]}},"aioseo_meta_data":{"post_id":"79257","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-10-09 02:26:07","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2025-05-07 12:01:30","updated":"2025-11-26 22:45:46"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/agenda\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/agenda\/eventos\/\" title=\"Eventos\">Eventos<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/agenda\/tag\/patricia-guerrero\/\" title=\"patricia-guerrero\">patricia-guerrero<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tC\u00f3rdoba: Origen \u2013 La semilla de los tiempos\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/expoflamenco.com\/agenda"},{"label":"Eventos","link":"https:\/\/expoflamenco.com\/agenda\/eventos\/"},{"label":"patricia-guerrero","link":"https:\/\/expoflamenco.com\/agenda\/tag\/patricia-guerrero\/"},{"label":"C\u00f3rdoba: Origen &#8211; La semilla de los tiempos","link":"https:\/\/expoflamenco.com\/agenda\/eventos\/origen-la-semilla-de-los-tiempos-ballet-flamenco-de-andalucia-cordoba\/"}],"_links":{"self":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec-events\/79257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/comments?post=79257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/media\/79248"}],"wp:attachment":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/media?parent=79257"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/tags?post=79257"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec_category?post=79257"},{"taxonomy":"mec_sponsor","embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec_sponsor?post=79257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}