{"id":78050,"date":"2025-02-20T09:10:52","date_gmt":"2025-02-20T08:10:52","guid":{"rendered":"https:\/\/expoflamenco.com\/agenda\/?post_type=mec-events&#038;p=78050"},"modified":"2025-03-03T18:40:58","modified_gmt":"2025-03-03T17:40:58","slug":"cursos-durante-festival-de-jerez","status":"publish","type":"mec-events","link":"https:\/\/expoflamenco.com\/agenda\/eventos\/cursos-durante-festival-de-jerez\/","title":{"rendered":"Cursos durante Festival de Jerez"},"content":{"rendered":"<div class=\"modern-event-listing-wrap wpb_left-to-right wpb_animate_when_almost_visible wpb_start_animation\">\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<h4 style=\"text-align: center;\"><strong>\u00bfTe has quedado sin plaza en la programaci\u00f3n oficial del Festival de Jerez 2025?<br \/>\nAqu\u00ed tienes todo el listado de cursos durante el Festival en Jerez de la Frontera.<\/strong><\/h4>\n<p style=\"text-align: center;\">Si quieres publicar tu curso o espect\u00e1culo en nuestra agenda durante el Festival de Jerez 2025.<br \/>\nEnv\u00eda la programaci\u00f3n a <a href=\"mailto:agenda@expoflamenco.com\">agenda@expoflamenco.com<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<hr \/>\n<hr \/>\n<hr \/>\n<div class=\"modern-event-listing-wrap wpb_left-to-right wpb_animate_when_almost_visible wpb_start_animation\">\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<figure id=\"attachment_78067\" aria-describedby=\"caption-attachment-78067\" style=\"width: 228px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\" wp-image-78067\" src=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/curso-palmas-festival-de-jerez-2025-300x300.webp\" alt=\"Curso de Palmas Festival de Jerez 2025\" width=\"228\" height=\"228\" srcset=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/curso-palmas-festival-de-jerez-2025-300x300.webp 300w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/curso-palmas-festival-de-jerez-2025-150x150.webp 150w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/curso-palmas-festival-de-jerez-2025-75x75.webp 75w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/curso-palmas-festival-de-jerez-2025-350x350.webp 350w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/curso-palmas-festival-de-jerez-2025.webp 400w\" sizes=\"(max-width: 228px) 100vw, 228px\" \/><figcaption id=\"caption-attachment-78067\" class=\"wp-caption-text\">Curso de Palmas Festival de Jerez 2025<\/figcaption><\/figure>\n<div class=\"modern-event-listing-wrap wpb_left-to-right wpb_animate_when_almost_visible wpb_start_animation\">\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<h3 class=\"product_title entry-title\" style=\"text-align: left;\">Curso de comp\u00e1s y palmas<br \/>\nJer\u00f3nimo Utrilla<\/h3>\n<h4 class=\"product_title entry-title\" style=\"text-align: left;\">(1 y 2 marzo)<\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div dir=\"auto\" style=\"text-align: left;\">\n<p>En este curso trabajemos los secretos de la buler\u00eda, los tangos o las alegr\u00edas. Aprender\u00e1s los diferentes tipos de palmas: palmas base, contratiempos y remates, adem\u00e1s de las diferentes palmas para el cante y para el baile, sonido y ejercicios de contra \u2063\u2063\u2063. Centro de Jerez<\/p>\n<p><strong>Horario:\u00a0<\/strong>11:30 a 14\u00a0h.\u2063<br \/>\n<strong>Fecha:<\/strong> 1 y 2 de Marzo.\u2063<br \/>\n<strong>Precio:<\/strong> 60 euros, a trav\u00e9s de Bizum (+34 669 384 340). \u206365 euros si el pago se hace a trav\u00e9s de Pay Pal o tarjeta bancaria. Reserva aqui<br \/>\n<strong>Idioma:<\/strong> Espa\u00f1ol, ingl\u00e9s y franc\u00e9s.<\/p>\n<\/div>\n<hr \/>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><img decoding=\"async\" class=\"wp-image-78501 aligncenter\" src=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/curso-compas-juen-mateo-festival-jerez-240x300.webp\" alt=\"\" width=\"263\" height=\"329\" srcset=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/curso-compas-juen-mateo-festival-jerez-240x300.webp 240w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/curso-compas-juen-mateo-festival-jerez-768x960.webp 768w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/curso-compas-juen-mateo-festival-jerez-750x938.webp 750w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/curso-compas-juen-mateo-festival-jerez.webp 800w\" sizes=\"(max-width: 263px) 100vw, 263px\" \/><\/p>\n<div class=\"modern-event-listing-wrap wpb_left-to-right wpb_animate_when_almost_visible wpb_start_animation\">\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<h3 class=\"product_title entry-title\" style=\"text-align: left;\">Curso de comp\u00e1s y palmas<br \/>\nJuan Mateos<\/h3>\n<h4 style=\"text-align: left;\">24\/25\/26 de Febrero 1\/2 de marzo<\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div dir=\"auto\" style=\"text-align: left;\">\n<p><strong>Horario:\u00a0<\/strong>112h a 13:30h.\u2063<br \/>\n<strong>Fecha:<\/strong> 24\/25\/26 de Febrero 1\/2 de marzo<br \/>\n<strong>Precio:<\/strong> 75 euros curso completo<br \/>\n<strong>Donde:<\/strong> Singa Estudio Calle Divina Pastora &#8211;<br \/>\n<strong>Info::<\/strong> 617 11 86 24<\/p>\n<\/div>\n<hr \/>\n<hr \/>\n<div dir=\"auto\">\n<figure id=\"attachment_78327\" aria-describedby=\"caption-attachment-78327\" style=\"width: 285px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\" wp-image-78327\" src=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/curso-bulerias-festival-2025-300x252.webp\" alt=\"Festival Jerez 2025 Curso de Bulerias\" width=\"285\" height=\"239\" srcset=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/curso-bulerias-festival-2025-300x252.webp 300w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/curso-bulerias-festival-2025-768x644.webp 768w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/curso-bulerias-festival-2025-750x629.webp 750w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/curso-bulerias-festival-2025.webp 800w\" sizes=\"(max-width: 285px) 100vw, 285px\" \/><figcaption id=\"caption-attachment-78327\" class=\"wp-caption-text\">Festival Jerez 2025 Curso de Bulerias<\/figcaption><\/figure>\n<\/div>\n<div class=\"modern-event-listing-wrap wpb_left-to-right wpb_animate_when_almost_visible wpb_start_animation\">\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"modern-event-listing-wrap wpb_left-to-right wpb_animate_when_almost_visible wpb_start_animation\">\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<h3 class=\"product_title entry-title\" style=\"text-align: left;\">Curso de Buler\u00edas de Jerez con<br \/>\nEsther Aranda<\/h3>\n<h4 class=\"product_title entry-title\" style=\"text-align: left;\">(25 y 25 Feb. \/ 3 y 4 Marzo)<\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div dir=\"auto\" style=\"text-align: left;\">\n<p>En este curso trabajemos los secretos de la buler\u00eda, con el cante de MOMO MONEO<\/p>\n<p><strong>Horario:\u00a0<\/strong>12h a 13:30 h.\u2063<br \/>\n<strong>Fecha:<\/strong> 24 y 25 de Febrero \/ 3 y 4 de Marzo.\u2063<br \/>\n<strong>Lugar:<\/strong> Pe\u00f1a Buena Gente\u2063<br \/>\n<strong>Informaci\u00f3n:<\/strong> +34 697 47 51 79<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div dir=\"auto\" style=\"text-align: left;\">\n<hr \/>\n<\/div>\n<div dir=\"auto\">\n<hr \/>\n<hr \/>\n<\/div>\n<figure id=\"attachment_78311\" aria-describedby=\"caption-attachment-78311\" style=\"width: 240px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-medium wp-image-78311\" src=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/01\/festival-jerez-2025-expoflamenco-240x300.jpg\" alt=\"Festival de Jerez en EXpoflamenco\" width=\"240\" height=\"300\" srcset=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/01\/festival-jerez-2025-expoflamenco-240x300.jpg 240w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/01\/festival-jerez-2025-expoflamenco-820x1024.jpg 820w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/01\/festival-jerez-2025-expoflamenco-768x960.jpg 768w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/01\/festival-jerez-2025-expoflamenco-1229x1536.jpg 1229w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/01\/festival-jerez-2025-expoflamenco-750x937.jpg 750w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/01\/festival-jerez-2025-expoflamenco-1140x1424.jpg 1140w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/01\/festival-jerez-2025-expoflamenco.jpg 1639w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/><figcaption id=\"caption-attachment-78311\" class=\"wp-caption-text\">Festival de Jerez en EXpoflamenco<\/figcaption><\/figure>\n<h1 style=\"text-align: center;\"><strong>ESPACIO CULTURAL EXPOFLAMENCO<\/strong><\/h1>\n<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/FGCPMEFWtrjyGqbC7\">Como llegar: C\/ Diego Fernand\u00e9z Herrera, centro Jerez.<\/a><br \/>\nTel\u00e9fono:\u00a0\u00a0\u00a0\u00a0(+34) 673 651 042<br \/>\nPrecios: desde 50\u20ac a 100\u20ac<br \/>\n<strong>PROGRAMACI\u00d3N DE CURSOS:<\/strong><\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"auto\" style=\"text-align: left;\"><img decoding=\"async\" class=\" wp-image-78397 aligncenter\" src=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/01\/patri-manes-curso-bulerias-fiesta-festival-2025-240x300.webp\" alt=\"\" width=\"273\" height=\"341\" srcset=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/01\/patri-manes-curso-bulerias-fiesta-festival-2025-240x300.webp 240w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/01\/patri-manes-curso-bulerias-fiesta-festival-2025.webp 400w\" sizes=\"(max-width: 273px) 100vw, 273px\" \/>CURSO DE BULERIAS DE FIESTA &#8211;<br \/>\ncon la Bailaora Patri Manes<\/h3>\n<h4 dir=\"auto\" style=\"text-align: left;\">(28, 01 y 02 marzo)<\/h4>\n<div dir=\"auto\">\n<div dir=\"auto\" style=\"text-align: left;\">\n<div dir=\"auto\">\n<div>CURSO DE BULERIAS DE FIESTA<\/div>\n<div><\/div>\n<p>El objetivo de este taller es introducir a los participantes en el lenguaje de las bulerias de Fiesta.\u00a0 Proporcionando una base s\u00f3lida en los movimientos, ritmos y expresiones. Al final del taller, los participantes habr\u00e1n adquirido las habilidades b\u00e1sicas para improvisar y entender los c\u00f3digos de la buleria. Al final haremos una fiesta por bulerias<br \/>\n<strong>Fecha:<\/strong>\u00a028, 01 y 02<\/p>\n<p><strong>Horario:<\/strong> 10:30h a 12:30h<br \/>\n<strong>Precio:<\/strong>\u00a0100 euros<br \/>\n<strong>Minimo:<\/strong>\u00a05 alumnos<br \/>\n<strong>M\u00e1ximo:<\/strong>\u00a015 alumnos<br \/>\n<strong>Nivel:<\/strong>\u00a0Principiantes \/Medio-bajo<br \/>\n<strong>Idioma:<\/strong>\u00a0Espa\u00f1ol, ingl\u00e9s y portugu\u00e9s<br \/>\n<strong>Whatsapp: +34 605 11 57 81<br \/>\n<\/strong><strong>email:\u00a0<a href=\"mailto:patricia@expoflamenco.com\" target=\"_blank\" rel=\"noopener\">patricia@expoflamenco.com<\/a><br \/>\n<\/strong><\/p>\n<p><a href=\"https:\/\/expoflamenco.shop\/products\/curso-de-bulerias-patri-manes\">Reserva aqui tu plaza<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div dir=\"auto\">\n<hr \/>\n<\/div>\n<p><img decoding=\"async\" class=\"size-medium wp-image-78325 aligncenter\" style=\"font-weight: 600;\" src=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/2025-01-17-Cartel-Curso-instrumentos-de-cuerda-RRSS-240x300.webp\" alt=\"Festival Jerez 2025 Curso de Cuerdas\" width=\"240\" height=\"300\" srcset=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/2025-01-17-Cartel-Curso-instrumentos-de-cuerda-RRSS-240x300.webp 240w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/2025-01-17-Cartel-Curso-instrumentos-de-cuerda-RRSS-768x960.webp 768w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/2025-01-17-Cartel-Curso-instrumentos-de-cuerda-RRSS-750x938.webp 750w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/2025-01-17-Cartel-Curso-instrumentos-de-cuerda-RRSS.webp 800w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/><\/p>\n<h3 style=\"text-align: left;\">Masterclass \u2018El flamenco y los instrumentos de cuerda\u2019 por Graci del Saz (APLAZADO PARA VERANO)<\/h3>\n<h4 style=\"text-align: left;\">(4, 5 y 6 Marzo)<\/h4>\n<p style=\"text-align: left;\">Curso intensivo dedicado a todos aquellos instrumentistas de cuerda frotada (violinistas, violistas, cellistas y contrabajistas) que quieran acercarse al flamenco, a trav\u00e9s de t\u00e9cnicas que crean sonidos que evocan el estilo (el llamado\u00a0<i>quej\u00edo<\/i>, pellizco o duende), y poni\u00e9ndolas en pr\u00e1ctica mediante el aprendizaje de falsetas que ya son parte de la historia del flamenco. Adem\u00e1s se aprender\u00e1n las estructuras fundamentales del flamenco, con el objeto de saber diferenciar los diferentes compases y palos, para posteriormente darles forma a trav\u00e9s de las cuerdas del instrumento.<\/p>\n<p style=\"font-weight: 400; text-align: left;\"><strong>Sesiones de la masterclass<\/strong><\/p>\n<p style=\"font-weight: 400; text-align: left;\">El curso se desarrollar\u00e1 los d\u00edas 4, 5 y 6 de marzo 2025 en horario de 17.30 a 18.30 horas en la sede de Espacio expoflamenco Jerez.<br \/>\nSe dividir\u00e1 en tres niveles:<br \/>\n<strong>Martes 4 de marzo<\/strong>: iniciaci\u00f3n (corresponder\u00eda al nivel que abarca desde 1\u00ba a 4\u00ba de elemental del instrumento)<br \/>\n<strong>Mi\u00e9rcoles 5 de marzo<\/strong>: medio (corresponder\u00eda al nivel que abarca 1\u00ba, 2\u00ba y 3\u00ba de grado profesional del instrumento)<br \/>\nJ<strong>ueves 6 de marzo<\/strong>: avanzado \u00a0(corresponder\u00eda al nivel que abarca 4\u00ba, 5\u00ba y 6\u00ba de grado profesional del instrumento)<\/p>\n<p style=\"font-weight: 400; text-align: left;\">Nota: Aquellos m\u00fasicos autodidactas se pueden apuntar al nivel que consideren oportuno.<\/p>\n<p style=\"text-align: left;\"><strong><a href=\"https:\/\/expoflamenco.shop\/products\/masterclass-el-flamenco-y-los-instrumentos-de-cuerda?_pos=2&amp;_psq=cuerdas&amp;_ss=e&amp;_v=1.0\">Reserva tu plaza aqui\/Book here<\/a><\/strong><\/p>\n<hr \/>\n<hr \/>\n<h1 class=\"jeg_post_title\"><img decoding=\"async\" class=\"wp-image-78503 aligncenter\" src=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/Marga-1140-300x150.jpg\" alt=\"\" width=\"402\" height=\"201\" srcset=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/Marga-1140-300x150.jpg 300w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/Marga-1140-1024x512.jpg 1024w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/Marga-1140-768x384.jpg 768w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/Marga-1140-360x180.jpg 360w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/Marga-1140-750x375.jpg 750w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/Marga-1140.jpg 1140w\" sizes=\"(max-width: 402px) 100vw, 402px\" \/>Cursos de la academia de Marga Flores<\/h1>\n<p>-Primer turno (nivel medio):\u00a0<strong>Buler\u00edas por cupl\u00e9<\/strong>\u00a0de 12:00 a 13:00h, precio 70\u20ac.<\/p>\n<p>-Segundo turno (nivel avanzado):\u00a0<strong>Tangos \u00a0Flamencos<\/strong>\u00a0de 13:00- 14:00h, precio 70\u20ac.<\/p>\n<p>El \u00faltimo d\u00eda habr\u00e1 acompa\u00f1amiento de cante y guitarra en directo.<\/p>\n<p><strong>Direcci\u00f3n:<\/strong> Escuela Marga Flores en C\/ Guadalete n\u00famero 21 de Jerez.<\/p>\n<p><strong>\u00a0Informaci\u00f3n<\/strong>: +34 600 70 73 24<\/p>\n<hr \/>\n<hr \/>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-78548 size-medium\" src=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/masterclass-212x300.webp\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/masterclass-212x300.webp 212w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/masterclass-768x1087.webp 768w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/masterclass-724x1024.webp 724w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/masterclass-750x1061.webp 750w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2025\/02\/masterclass.webp 800w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/p>\n<h4>Curso de Baile con Maria del Mar Ramirez<\/h4>\n<p><strong>Fecha:<\/strong> 03 de marzo<br \/>\n<strong>Horario:<\/strong> 15h a 17h<\/p>\n<hr \/>\n<div class=\"modern-event-listing-wrap wpb_left-to-right wpb_animate_when_almost_visible wpb_start_animation\">\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<hr \/>\n<hr \/>\n<h1 style=\"text-align: center;\"><strong><a title=\"Patricia Ib\u00e1\u00f1ez \u2013 Sole\u00e1 por buler\u00edas\" href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/patricia-ibanez-solea-por-bulerias-3\/\"><img decoding=\"async\" class=\"attachment-thumb_360x240 wp-post-image aligncenter\" src=\"http:\/\/www.xn--patriciaibaez-skb.com\/wp-content\/uploads\/2022\/05\/patricia-iba%C3%B1ez-3-360x240.jpg\" alt=\"Patricia Ib\u00e1\u00f1ez \u2013 Sole\u00e1 por buler\u00edas\" width=\"360\" height=\"240\" \/><\/a>ESCUELA DE BAILE PATRICIA IBA\u00d1EZ<br \/>\n<\/strong><\/h1>\n<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/CDosHXqXARqBde267\">Como llegar: C\/ Merced, 9 (Barrio de Santiago)<\/a><br \/>\nTel\u00e9fono:\u00a0\u00a0\u00a0\u00a0(+34) 650 16 66 54<br \/>\nEmail: info@patriciaiba\u00f1ez.com<br \/>\nPrecios: desde 100\u20ac a 180\u20ac<\/p>\n<hr \/>\n<hr \/>\n<\/div>\n<hr \/>\n<div><\/div>\n<div><\/div>\n<div class=\"custom-pot-1\" style=\"text-align: left;\"><a title=\"Patricia Ib\u00e1\u00f1ez \u2013 Tangos\" href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/patricia-ibanez-tangos-2024\/\"><img decoding=\"async\" class=\"attachment-thumb_360x240 wp-post-image\" src=\"http:\/\/www.xn--patriciaibaez-skb.com\/wp-content\/uploads\/2022\/05\/patricia-iba%C3%B1ez-2-360x240.jpg\" alt=\"Patricia Ib\u00e1\u00f1ez \u2013 Tangos\" width=\"360\" height=\"240\" \/><\/a><\/div>\n<div class=\"custom-pot-1\" style=\"text-align: left;\">\n<h3 class=\"rt-article-title\"><a href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/introduccion-a-las-bulerias\/\">Patricia Ib\u00e1\u00f1ez &#8211; <\/a><a href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/introduccion-a-las-bulerias\/\">Introducci\u00f3n a las Buler\u00edas<\/a><\/h3>\n<p>\u2013 Fecha: del 24 al 28 de febrero de 2025. \u2013<br \/>\nHorario: De 9.30 a 10.30<br \/>\nNivel Iniciaci\u00f3n.<\/p>\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-item span4\" style=\"text-align: left;\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 imge\">\n<h3 class=\"rt-image\">\u00a0<a style=\"font-size: 1.563em;\" href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/patricia-ibanez-tangos-2024\/\">Patricia Ib\u00e1\u00f1ez \u2013 Tangos<\/a><\/h3>\n<\/div>\n<div class=\"span12 modern_style\">\n<div class=\"recentpost-content\">\u2013 Fecha: del 24 al 28 de febrero de 2025. \u2013<br \/>\nHorario: De 10.30 a 11.30<br \/>\nNivel Medio.<\/p>\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-item span4\" style=\"text-align: left;\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<h3 class=\"rt-article-title\"><a href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/patricia-ibanez-bulerias-2024\/\">Patricia Ib\u00e1\u00f1ez \u2013 Buler\u00edas de Jerez<\/a><\/h3>\n<\/div>\n<div class=\"recentpost-content\">\u2013 Fecha: del 24 al 28 de febrero de 2025. \u2013<br \/>\nHorario: De 11.30 a 12.30<br \/>\nNivel Medio.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"modern-event-listing-wrap wpb_left-to-right wpb_animate_when_almost_visible wpb_start_animation\" style=\"text-align: left;\">\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<hr \/>\n<h3 class=\"rt-article-title\"><a href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/patricia-ibanez-bamberas-con-bata-de-cola\/\">Patricia Iba\u00f1ez \u2013 Bamberas con bata de cola<\/a><\/h3>\n<\/div>\n<div class=\"recentpost-content\">PLAZAS LIMITADAS \u2013 Fecha: del 24 al 28 de febrero de 2025.<br \/>\nHorario: De 12.30 a 14.00 &#8211;<\/div>\n<\/div>\n<div class=\"clear\">\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"clear\">\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 imge\">\n<div><\/div>\n<div><\/div>\n<div class=\"rt-image\"><a title=\"Luc\u00eda La Pi\u00f1ona \u2013 Alegr\u00edas\" href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/lucia-la-pinona-alegrias\/\"><img decoding=\"async\" class=\"attachment-thumb_360x240 wp-post-image\" src=\"http:\/\/www.xn--patriciaibaez-skb.com\/wp-content\/uploads\/2022\/05\/lucia-la-pi%C3%B1ona-2-360x240.jpg\" alt=\"Luc\u00eda La Pi\u00f1ona \u2013 Alegr\u00edas\" width=\"360\" height=\"240\" \/><\/a><\/div>\n<\/div>\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<h3 class=\"rt-article-title\"><a href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/lucia-la-pinona-alegrias\/\">Luc\u00eda La Pi\u00f1ona \u2013 Alegr\u00edas<\/a><\/h3>\n<\/div>\n<div class=\"recentpost-content\">\u2013 Fecha: del 28 de febrero al 2 de marzo de 2025. \u2013<br \/>\nHorario: De 14.00 a 15.00<br \/>\nNivel Medio &#8211; 100\u20ac<\/p>\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<h3 class=\"rt-article-title\"><a href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/lucia-la-pinona-solea-por-bulerias\/\">Luc\u00eda La Pi\u00f1ona \u2013 Sole\u00e1 por buler\u00edas<\/a><\/h3>\n<\/div>\n<div class=\"recentpost-content\">\u2013 Fecha: del 28 de febrero al 2 de marzo de 2025. \u2013<br \/>\nHorario: De 15.00 a 16.00<\/p>\n<hr \/>\n<hr \/>\n<\/div>\n<\/div>\n<div class=\"clear\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"modern-event-listing-wrap wpb_left-to-right wpb_animate_when_almost_visible wpb_start_animation\" style=\"text-align: left;\">\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 imge\">\n<div><\/div>\n<div><\/div>\n<div class=\"rt-image\"><a title=\"Cristina Aguilera \u2013 Tientos\" href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/cristina-aguilera-tientos\/\"><img decoding=\"async\" class=\"attachment-thumb_360x240 wp-post-image\" src=\"http:\/\/www.xn--patriciaibaez-skb.com\/wp-content\/uploads\/2022\/05\/cristina-otero-2-360x240.jpg\" alt=\"Cristina Aguilera \u2013 Tientos\" width=\"360\" height=\"240\" \/><\/a><\/div>\n<\/div>\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<h3 class=\"rt-article-title\"><a href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/cristina-aguilera-tientos\/\">Cristina Aguilera \u2013 Tientos<\/a><\/h3>\n<\/div>\n<div class=\"recentpost-content\">\u2013 Fecha: 28 de febrero de 2025. \u2013<br \/>\nHorario: De 15.00 a 16.00<br \/>\nNivel Medio.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<hr \/>\n<h3 class=\"rt-article-title\"><a href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/cristina-aguilera-bulerias-marzo\/\">Cristina Aguilera \u2013 Buler\u00edas<\/a><\/h3>\n<\/div>\n<div class=\"recentpost-content\">\u2013 Fecha: 28 de febrero de 2025. \u2013<br \/>\nHorario: De 16.00 a 17.00 -&gt; Nivel Medio\/Alto<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<hr \/>\n<h3 class=\"rt-article-title\"><a href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/cristina-aguilera-tientos-marzo\/\">Cristina Aguilera \u2013 Tientos<\/a><\/h3>\n<\/div>\n<div class=\"recentpost-content\">\u2013 Fecha: 1 y 2 de marzo de 2025. \u2013<br \/>\nHorario: De 12.00 a 13.00<br \/>\nNivel Medio.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"modern-event-listing-wrap wpb_left-to-right wpb_animate_when_almost_visible wpb_start_animation\" style=\"text-align: left;\">\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<hr \/>\n<h3 class=\"rt-article-title\"><a href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/cristina-aguilera-bulerias\/\">Cristina Aguilera \u2013 Buler\u00edas<\/a><\/h3>\n<\/div>\n<div class=\"recentpost-content\">\u2013 Fecha: 1 y 2 de marzo de 2025. \u2013<br \/>\nHorario: De 13.00 a 14.00<br \/>\nNivel Medio\/Alto.<\/div>\n<\/div>\n<\/div>\n<div class=\"clear\">\n<hr \/>\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"clear\"><\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 imge\">\n<div class=\"rt-image\"><a title=\"Patricia Ib\u00e1\u00f1ez \u2013 Sole\u00e1 por buler\u00edas\" href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/patricia-ibanez-solea-por-bulerias-3\/\"><img decoding=\"async\" class=\"attachment-thumb_360x240 wp-post-image\" src=\"http:\/\/www.xn--patriciaibaez-skb.com\/wp-content\/uploads\/2022\/05\/patricia-iba%C3%B1ez-3-360x240.jpg\" alt=\"Patricia Ib\u00e1\u00f1ez \u2013 Sole\u00e1 por buler\u00edas\" width=\"360\" height=\"240\" \/><\/a><\/div>\n<\/div>\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<h3 class=\"rt-article-title\"><a href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/patricia-ibanez-tangos-2025\/\">Patricia Ib\u00e1\u00f1ez \u2013 Tangos<\/a><\/h3>\n<\/div>\n<div class=\"recentpost-content\">\u2013 Fecha: del 3 al 7 de marzo de 2025. \u2013<br \/>\nHorario: De 9.30 a 10.30<br \/>\nNivel Iniciaci\u00f3n. Curso<\/p>\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 imge\">\n<div class=\"rt-image\"><a style=\"font-size: 1.563em;\" href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/patricia-ibanez-solea-por-bulerias-3\/\">Patricia Ib\u00e1\u00f1ez \u2013 Sole\u00e1 por buler\u00edas<\/a><\/div>\n<\/div>\n<div class=\"span12 modern_style\">\n<div class=\"recentpost-content\">\u2013 Fecha: del 3 al 7 de marzo de 2025. \u2013<br \/>\nHorario: De 10.30 a 11.30<br \/>\nNivel Medio. Curso<\/p>\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"modern-event-listing-wrap wpb_left-to-right wpb_animate_when_almost_visible wpb_start_animation\" style=\"text-align: left;\">\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<h3 class=\"rt-article-title\"><a href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/patricia-ibanez-bulerias-de-jerez\/\">Patricia Ib\u00e1\u00f1ez \u2013 ESPECIAL Buler\u00edas de Jerez \u201cBailar al Cante\u201d<\/a><\/h3>\n<\/div>\n<div class=\"recentpost-content\">CON ACOMPA\u00d1AMIENTO DE GUITARRA Y CANTE. PLAZAS LIMITADAS. \u2013<br \/>\nFecha: del 3 al 7 de marzo de 2025.<br \/>\nHorario: De 11.30 a 13.00<br \/>\nNivel Medio<\/p>\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<h3 class=\"rt-article-title\"><a href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/patricia-ibanez-martinete\/\">Patricia Ib\u00e1\u00f1ez \u2013 Martinete<\/a><\/h3>\n<\/div>\n<div class=\"recentpost-content\">\u2013 Fecha: del 3 al 7 de marzo de 2025. \u2013<br \/>\nHorario: De 13.00 a 14.00<br \/>\nNivel Medio<\/div>\n<\/div>\n<div class=\"clear\">\n<hr \/>\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"clear\"><\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 imge\"><a title=\"Nazaret Reyes \u2013 Siguirilla\" href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/nazaret-reyes-siguirilla\/\"><img decoding=\"async\" class=\"attachment-thumb_360x240 wp-post-image\" src=\"http:\/\/www.xn--patriciaibaez-skb.com\/wp-content\/uploads\/2022\/05\/nazaret-reyes-1-360x240.jpg\" alt=\"Nazaret Reyes \u2013 Siguirilla\" width=\"360\" height=\"240\" \/><\/a><\/div>\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<h3 class=\"rt-article-title\"><a href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/nazaret-reyes-taranto\/\">Nazaret Reyes \u2013 Taranto<\/a><\/h3>\n<\/div>\n<div class=\"recentpost-content\">\u2013 Fecha: del 3 al 5 de marzo de 2025. \u2013<br \/>\nHorario: De 14.00 a 15.00<br \/>\nNivel Medio.<\/div>\n<\/div>\n<div class=\"clear\">\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"modern-event-listing-wrap wpb_left-to-right wpb_animate_when_almost_visible wpb_start_animation\" style=\"text-align: left;\">\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 imge\">\n<div class=\"rt-image\">\u00a0<a style=\"font-size: 1.563em;\" href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/nazaret-reyes-siguirilla\/\">Nazaret Reyes \u2013 Siguirilla<\/a><\/div>\n<\/div>\n<div class=\"span12 modern_style\">\n<div class=\"recentpost-content\">\u2013 Fecha: del 3 al 5 de marzo de 2025. \u2013<br \/>\nHorario: De 15.00 a 16.00<br \/>\nNivel Medio-Alto.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"rt-headline\">\n<hr \/>\n<hr \/>\n<h3 class=\"rt-article-title\"><a title=\"Raquel Heredia La Repompa \u2013 Sole\u00e1\" href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/raquel-heredia-la-repompa-solea\/\"><img decoding=\"async\" class=\"attachment-thumb_360x240 wp-post-image\" src=\"http:\/\/www.xn--patriciaibaez-skb.com\/wp-content\/uploads\/2024\/10\/raquel-la-repompa-1-360x240.jpg\" alt=\"Raquel Heredia La Repompa \u2013 Sole\u00e1\" width=\"360\" height=\"240\" \/><\/a><\/h3>\n<h3 class=\"rt-article-title\"><a href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/raquel-heredia-la-repompa-tangos\/\">Raquel Heredia La Repompa \u2013 Tangos<\/a><\/h3>\n<\/div>\n<div class=\"recentpost-content\">\u2013 Fecha: del 6 al 8 de marzo de 2025. \u2013<br \/>\nHorario: De 14.00 a 15.00<br \/>\nNivel Medio. Curso<\/div>\n<\/div>\n<div class=\"clear\">\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"recentpost-content\"><a style=\"font-size: 1.563em;\" href=\"https:\/\/www.xn--patriciaibaez-skb.com\/event\/raquel-heredia-la-repompa-solea\/\">Raquel Heredia La Repompa \u2013 Sole\u00e1<\/a><\/div>\n<div class=\"recentpost-content\">\u2013 Fecha: del 6 al 8 de marzo de 2025. \u2013<br \/>\nHorario: De 15.00 a 16.00<br \/>\nNivel Medio\/Alto<\/p>\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<hr \/>\n<hr \/>\n<h1 style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/chiqui-de-jere.png\" alt=\"Chiqui de Jerez\" width=\"215\" height=\"196\" \/>ESCUELA CHIQUI DE JER\u00c9<\/h1>\n<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/8kxd2JvPZNbQyDTt7\">Como llegar: Calle Empedrada, 32 (Barrio San Miguel)<\/a><br \/>\nTel. 0034 856 103 442 \u2013 0034 639 653 624<br \/>\ninfo@chiquidejere.com<\/p>\n<div class=\"modern-event-listing-wrap wpb_left-to-right wpb_animate_when_almost_visible wpb_start_animation\">\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\" style=\"text-align: left;\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"recentpost-content\" style=\"text-align: center;\">\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\" style=\"text-align: left;\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"recentpost-content\">\n<hr \/>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/tatiana-ruiz.png\" alt=\"Tatiana Ruiz\" width=\"200\" height=\"182\" \/><\/p>\n<p style=\"text-align: center;\"><strong><br \/>\nDel 22 al 27 de febrero de 9:30 a 10:30 horas<\/strong><\/p>\n<p style=\"text-align: center;\">Profesora: Tatiana Ruiz<\/p>\n<p style=\"text-align: center;\">CURSO DE TANGOS \/ NIVEL MEDIO-BAJO<br \/>\n130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/tatiana-ruiz.png\" alt=\"Tatiana Ruiz\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 22 al 27 de febrero de 10:30 a 11:30\u00a0<\/strong><strong>horas<\/strong><\/p>\n<p>Profesora: Tatiana Ruiz<\/p>\n<p>CURSO DE GARROT\u00cdN CON SOMBRERO \/ NIVEL PRINCIPIANTE<br \/>\n130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"modern-event-listing-wrap wpb_left-to-right wpb_animate_when_almost_visible wpb_start_animation\" style=\"text-align: center;\">\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\" style=\"text-align: left;\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"recentpost-content\">\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/juan-polvillo.png\" alt=\"Juan Polvillo\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 22 al 27 de febrero de 11:00 a 12:00 <\/strong><strong>horas<br \/>\n<\/strong>Profesor: Juan Polvillo<\/p>\n<p style=\"text-align: center;\">CURSO DE GUAJIRAS CON ABANICO \/ NIVEL MEDIO-BAJO<br \/>\n130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/david-romero.png\" alt=\"David Romero\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 22 al 27 de febrero de 11:30 a 12:30 horas<\/strong><\/p>\n<p>Profesor: David Romero<\/p>\n<p>CURSO DE T\u00c9CNICA Y RECURSOS \/<\/p>\n<p>MULTINIVEL<\/p>\n<p>130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/david-romero.png\" alt=\"David Romero\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 22 al 27 de febrero de 12:30 a 13:30 horas<\/strong><\/p>\n<p>Profesor: David Romero<\/p>\n<p>CURSO DE SOLE\u00c1 \/ NIVEL MEDIO<\/p>\n<p>130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/juan-polvillo.png\" alt=\"Juan Polvillo\" width=\"200\" height=\"182\" \/><strong>Del 22 al 27 de febrero de 13:30 a 14:30 horas<\/strong><\/p>\n<p>Profesor: Juan Polvillo<\/p>\n<p>CURSO DE TANGOS DE M\u00c1LAGA \/ NIVEL<\/p>\n<p>MEDIO-BAJO<\/p>\n<p>130\u20ac<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/juan-polvillo.png\" alt=\"Juan Polvillo\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 22 al 27 de febrero de 14:30 a 15:30 horas<\/strong><\/p>\n<p>Profesor: Juan Polvillo<\/p>\n<p>CURSO DE SOLE\u00c1 POR BULER\u00cdAS \/ NIVEL MEDIO-ALTO<\/p>\n<p>130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/chiqui-de-jere.png\" alt=\"Chiqui de Jerez\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 22 al 27 de febrero de 9:30 a 10:30 horas<\/strong><\/p>\n<p>Profesora:\u00a0Chiqui de Jerez<\/p>\n<p>CURSO DE FANDANGOS DE HUELVA \/ NIVEL PRINCIPIANTE<\/p>\n<p>140\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/chiqui-de-jere.png\" alt=\"Chiqui de Jerez\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 22 al 27 de febrero de 10:30 a 12:00 horas<\/strong><\/p>\n<p>Profesora:\u00a0Chiqui de Jerez<\/p>\n<p>CURSO DE CA\u00d1AS \/ NIVEL MEDIO<\/p>\n<p>180\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/chiqui-de-jere.png\" alt=\"Chiqui de Jerez\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 22 al 27 de febrero de 12:00 a 13:00 horas<\/strong><\/p>\n<p style=\"text-align: center;\">Profesora:\u00a0Chiqui de Jerez<\/p>\n<p style=\"text-align: center;\">CURSO DE BULER\u00cdAS DE JEREZ \/ MULTINIVEL<\/p>\n<p style=\"text-align: center;\">100\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/la-lupi.png\" alt=\"La Lupi\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 22 <\/strong><strong>al 27 de febrero de 13:00 a 14:30\u00a0<\/strong><strong>horas<\/strong><\/p>\n<p>Profesora: La Lupi<\/p>\n<p>CURSO DE TANGOS DEL PIYAYO CON SOMBRERO \/ NIVEL MEDIO-BAJO<\/p>\n<p>180\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p><strong>\u00a0<\/strong><\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/la-lupi.png\" alt=\"La Lupi\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 22 al 27 de febrero de 14:30 a 16:00 horas<\/strong><\/p>\n<p>Profesora: La Lupi<br \/>\nCURSO DE SERRANAS \/ NIVEL MEDIO-ALTO<\/p>\n<p>180\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/miguel-angel-heredia.png\" alt=\"Miguel \u00c1ngel Heredia\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 22 a<\/strong><strong>l 27 de febrero de 16:00 a 17:30\u00a0<\/strong><strong>horas<\/strong><\/p>\n<p>Profesor:\u00a0Miguel \u00c1ngel Heredia<\/p>\n<p>CURSO DE SOLE\u00c1 POR BULER\u00cdAS \/ NIVEL MEDIO-BAJO<\/p>\n<p>180\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/miguel-angel-heredia.png\" alt=\"Miguel \u00c1ngel Heredia\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 22 al 27 de febrero de 17:30 a 19:00 horas<\/strong><\/p>\n<p>Profesor:\u00a0Miguel \u00c1ngel Heredia<\/p>\n<p>CURSO DE BULER\u00cdAS ARROMANZ\u00c1S \/ NIVEL MEDIO-ALTO<\/p>\n<p>180\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/la-truco.png\" alt=\"La Truco\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 22 al 27 de febrero de 9:00 a 10:00\u00a0<\/strong><strong>horas<\/strong><\/p>\n<p>Profesora:\u00a0La Truco<\/p>\n<p>CURSO DE T\u00c9CNICA CORPORAL \/ MULTINIVEL<\/p>\n<p class=\"azul\"><strong><a href=\"https:\/\/www.google.es\/maps\/place\/Asociaci%C3%B3n+cultural+La+Guarida+del+%C3%81ngel,+Espect%C3%A1culos+flamencos+y+musica+en+vivo\/@36.6804343,-6.1352003,17z\/data=!3m2!4b1!5s0xd0dc692de9e6625:0x68d9650942e71d2b!4m6!3m5!1s0xd0dc692db0567c9:0x98cd2d18166bda49!8m2!3d36.68043!4d-6.13262!16s%2Fg%2F11ckxyqmtz?entry=ttu&amp;g_ep=EgoyMDI0MDkxMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\">SE IMPARTE EN LA GUARIDA DEL \u00c1NGEL<\/a><\/strong><\/p>\n<p>130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/la-truco.png\" alt=\"La Truco\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 22 al 27 de febrero de 10:00 a 11:00 horas<\/strong><\/p>\n<p>Profesora:\u00a0La Truco<\/p>\n<p>CURSO DE ALEGR\u00cdAS DE C\u00d3RDOBA \/ NIVEL MEDIO<\/p>\n<p class=\"azul\"><strong><a href=\"https:\/\/www.google.es\/maps\/place\/Asociaci%C3%B3n+cultural+La+Guarida+del+%C3%81ngel,+Espect%C3%A1culos+flamencos+y+musica+en+vivo\/@36.6804343,-6.1352003,17z\/data=!3m2!4b1!5s0xd0dc692de9e6625:0x68d9650942e71d2b!4m6!3m5!1s0xd0dc692db0567c9:0x98cd2d18166bda49!8m2!3d36.68043!4d-6.13262!16s%2Fg%2F11ckxyqmtz?entry=ttu&amp;g_ep=EgoyMDI0MDkxMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\">SE IMPARTE EN LA GUARIDA DEL \u00c1NGEL<\/a><\/strong><\/p>\n<p>130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/juan-tomas-de-la-molia.png\" alt=\"Juan Tom\u00e1s de la Mol\u00eda\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 22 al 27 de febrero de 11:00 a 12:30 horas<\/strong><\/p>\n<p>Profesor: Juan Tom\u00e1s de la Mol\u00eda<\/p>\n<p>CURSO DE ALEGR\u00cdAS \/ NIVEL MEDIO-BAJO<\/p>\n<p>180\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/juan-tomas-de-la-molia.png\" alt=\"Juan Tom\u00e1s de la Mol\u00eda\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 22 al 27 de febrero de 12:30 a 14:00 horas<\/strong><\/p>\n<p>Profesor: Juan Tom\u00e1s de la Mol\u00eda<\/p>\n<p>CURSO DE BULER\u00cdAS \/ NIVEL MEDIO-ALTO<\/p>\n<p>180\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/10\/miguel-angel-heredia.png\" alt=\"Miguel \u00c1ngel Heredia\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong>Del 22 al 27 de febrero de 12:00 a 13:30 horas<\/strong><\/p>\n<p class=\"azul\">\u2605 Clases de Cante Flamenco con Miguel \u00c1ngel Heredia<\/p>\n<p>180\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/10\/ezequiel-benitez.png\" alt=\"Ezequiel Ben\u00edtez\" width=\"200\" height=\"182\" \/><strong>Del 23 al 26 de febrero de 16:00 a 17:30 horas<\/strong><\/p>\n<p class=\"azul\">\u2605 Clases de Cante Flamenco con Ezequiel Ben\u00edtez<\/p>\n<p>150\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"modern-event-listing-wrap wpb_left-to-right wpb_animate_when_almost_visible wpb_start_animation\">\n<div class=\"modern-event-listing blog-listing blog-listing-modern event-listing-modern\">\n<div class=\"wrap-item span4\">\n<div class=\"item\">\n<div class=\"article\">\n<div class=\"article-bg\" style=\"text-align: center;\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"recentpost-content\">\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/juan-fernandez.png\" alt=\"Juan Fern\u00e1ndez\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 25 al 27 de febrero de 15:30 a 16:30 horas<\/strong><\/p>\n<p>Profesor: Juan Fern\u00e1ndez<\/p>\n<p>CURSO DE TANGOS \/ NIVEL MEDIO-BAJO<\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/juan-fernandez.png\" alt=\"Juan Fern\u00e1ndez\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 25 al 27 de febrero de 16:30 a 17:30\u00a0<\/strong><\/p>\n<p><strong>horas<\/strong><\/p>\n<p>Profesor: Juan Fern\u00e1ndez<\/p>\n<p>CURSO DE ROMANCE \/ NIVEL MEDIO-ALTO<\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/jesus-fernandez.png\" alt=\"Jes\u00fas Fern\u00e1ndez\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 28 de febrero al 2 de marzo de 9:30 a 10:30 horas<\/strong><\/p>\n<p>Profesor: Jes\u00fas Fern\u00e1ndez<\/p>\n<p>CURSO DE JALEOS EXTREME\u00d1OS \/ NIVEL MEDIO-BAJO<\/p>\n<p class=\"azul\"><strong><a href=\"https:\/\/www.google.es\/maps\/place\/Asociaci%C3%B3n+cultural+La+Guarida+del+%C3%81ngel,+Espect%C3%A1culos+flamencos+y+musica+en+vivo\/@36.6804343,-6.1352003,17z\/data=!3m2!4b1!5s0xd0dc692de9e6625:0x68d9650942e71d2b!4m6!3m5!1s0xd0dc692db0567c9:0x98cd2d18166bda49!8m2!3d36.68043!4d-6.13262!16s%2Fg%2F11ckxyqmtz?entry=ttu&amp;g_ep=EgoyMDI0MDkxMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\">SE IMPARTE EN LA GUARIDA DEL \u00c1NGEL<\/a><\/strong>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/jesus-fernandez.png\" alt=\"Jes\u00fas Fern\u00e1ndez\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 28 de febrero al 2 de marzo de 10:30 a\u00a0<\/strong><strong>11:30 horas<\/strong><\/p>\n<p>Profesor: Jes\u00fas Fern\u00e1ndez<\/p>\n<p>CURSO DE BULER\u00cdAS POR SOLE\u00c1 \/ NIVEL MEDIO-ALTO<\/p>\n<p class=\"azul\"><strong><a href=\"https:\/\/www.google.es\/maps\/place\/Asociaci%C3%B3n+cultural+La+Guarida+del+%C3%81ngel,+Espect%C3%A1culos+flamencos+y+musica+en+vivo\/@36.6804343,-6.1352003,17z\/data=!3m2!4b1!5s0xd0dc692de9e6625:0x68d9650942e71d2b!4m6!3m5!1s0xd0dc692db0567c9:0x98cd2d18166bda49!8m2!3d36.68043!4d-6.13262!16s%2Fg%2F11ckxyqmtz?entry=ttu&amp;g_ep=EgoyMDI0MDkxMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\">SE IMPARTE EN LA GUARIDA DEL \u00c1NGEL<\/a><\/strong><\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/maria-moreno.png\" alt=\"Mar\u00eda Moreno\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 28 de febrero al 2 de marzo de 11:30 a\u00a0<\/strong><strong>12:30 horas<\/strong><\/p>\n<p>Profesora: Mar\u00eda Moreno<\/p>\n<p>CURSO DE ALEGR\u00cdAS \/ NIVEL MEDIO-BAJO<\/p>\n<p class=\"azul\"><strong><a href=\"https:\/\/www.google.es\/maps\/place\/Asociaci%C3%B3n+cultural+La+Guarida+del+%C3%81ngel,+Espect%C3%A1culos+flamencos+y+musica+en+vivo\/@36.6804343,-6.1352003,17z\/data=!3m2!4b1!5s0xd0dc692de9e6625:0x68d9650942e71d2b!4m6!3m5!1s0xd0dc692db0567c9:0x98cd2d18166bda49!8m2!3d36.68043!4d-6.13262!16s%2Fg%2F11ckxyqmtz?entry=ttu&amp;g_ep=EgoyMDI0MDkxMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\">SE IMPARTE EN LA GUARIDA DEL \u00c1NGEL<\/a><\/strong><\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/maria-moreno.png\" alt=\"Mar\u00eda Moreno\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 28 de febrero al 2 de marzo de 12:30 a 13:30 horas<\/strong><\/p>\n<p>Profesora: Mar\u00eda Moreno<\/p>\n<p>CURSO DE ALEGR\u00cdAS \/ NIVEL MEDIO-ALTO<\/p>\n<p class=\"azul\"><strong><a href=\"https:\/\/www.google.es\/maps\/place\/Asociaci%C3%B3n+cultural+La+Guarida+del+%C3%81ngel,+Espect%C3%A1culos+flamencos+y+musica+en+vivo\/@36.6804343,-6.1352003,17z\/data=!3m2!4b1!5s0xd0dc692de9e6625:0x68d9650942e71d2b!4m6!3m5!1s0xd0dc692db0567c9:0x98cd2d18166bda49!8m2!3d36.68043!4d-6.13262!16s%2Fg%2F11ckxyqmtz?entry=ttu&amp;g_ep=EgoyMDI0MDkxMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\">SE IMPARTE EN LA GUARIDA DEL \u00c1NGEL<\/a><\/strong><\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/miguel-angel-heredia.png\" alt=\"Miguel \u00c1ngel Heredia\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 28 de febrero al 3 de marzo de 10:00 a\u00a0<\/strong><strong>11:30 horas<\/strong><\/p>\n<p>Profesor:\u00a0Miguel \u00c1ngel Heredia<\/p>\n<p>CURSO DE ALEGR\u00cdAS \/ NIVEL MEDIO-BAJO<\/p>\n<p>150\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/miguel-angel-heredia.png\" alt=\"Miguel \u00c1ngel Heredia\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 28 de febrero al 3 de marzo de 11:30 a 13:00 horas<\/strong><\/p>\n<p>Profesor:\u00a0Miguel \u00c1ngel Heredia<\/p>\n<p>CURSO DE BULER\u00cdAS AL GOLPE \/ NIVEL MEDIO-ALTO<\/p>\n<p>150\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/la-lupi.png\" alt=\"La Lupi\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 28 de febrero al 5 de marzo de 13:00 a\u00a0<\/strong><\/p>\n<p><strong>14:30 horas<\/strong>Profesora: La Lupi<\/p>\n<p>CURSO DE CANTI\u00d1AS CON ABANICO \/ NIVEL MEDIO-BAJO<\/p>\n<p>180\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/la-lupi.png\" alt=\"La Lupi\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 28 de febrero al 5 de marzo de 14:30 a 16:00 horas<\/strong><\/p>\n<p>Profesora: La Lupi<\/p>\n<p>CURSO DE ABANDOLAOS \/ NIVEL MEDIO-ALTO<\/p>\n<p>180\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/alfonso-losa.png\" alt=\"Alfonso Losa\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 28 de febrero al 2 de marzo de 16:00 a\u00a0<\/strong><\/p>\n<p><strong>17:30 horas<\/strong><\/p>\n<p>Profesor: Alfonso Losa<\/p>\n<p>CURSO DE TANGOS \/ NIVEL MEDIO-BAJO<\/p>\n<p>110\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/alfonso-losa.png\" alt=\"Alfonso Losa\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 28 de febrero al 2 de marzo de 17:30 a 19:00 horas<\/strong><\/p>\n<p>Profesor: Alfonso Losa<\/p>\n<p>CURSO DE BULER\u00cdAS \/ NIVEL MEDIO-ALTO<\/p>\n<p>110\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/tatiana-ruiz.png\" alt=\"Tatiana Ruiz\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 28 de febrero al 5 de marzo de 9:30 a 10:30 horas<\/strong><\/p>\n<p>Profesora: Tatiana Ruiz<\/p>\n<p>CURSO DE ALEGR\u00cdAS CON ABANICO \/ NIVEL MEDIO-BAJO<\/p>\n<p>130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/tatiana-ruiz.png\" alt=\"Tatiana Ruiz\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 28 de febrero al 5 de marzo de 10:30 a\u00a0<\/strong><\/p>\n<p><strong>11:30 horas<\/strong><\/p>\n<p>Profesora: Tatiana Ruiz<\/p>\n<p>CURSO DE BULER\u00cdAS AL GOLPE \/ NIVEL PRINCIPIANTE<\/p>\n<p>130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/tatiana-ruiz.png\" alt=\"Tatiana Ruiz\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 28 de febrero al 5 de marzo de 11:30 a 12:30 horas<\/strong><\/p>\n<p>Profesora: Tatiana Ruiz<\/p>\n<p>CURSO DE BULER\u00cdAS IMPROVISACI\u00d3N \/ MULTINIVEL<\/p>\n<p>130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/tatiana-ruiz.png\" alt=\"Tatiana Ruiz\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 28 de febrero al 5 de marzo de 12:30 a\u00a0<\/strong><\/p>\n<p><strong>13:30 horas<\/strong><\/p>\n<p>Profesora: Tatiana Ruiz<\/p>\n<p>CURSO DE BAMBERAS \/ NIVEL MEDIO<\/p>\n<p>130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/david-romero.png\" alt=\"David Romero\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 28 de febrero al 5 de marzo de 13:30 a 14:30 horas<\/strong><\/p>\n<p>Profesor: David Romero<\/p>\n<p>CURSO DE T\u00c9CNICA Y RECURSOS \/ NIVEL PRINCIPIANTE<\/p>\n<p>130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/david-romero.png\" alt=\"David Romero\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 28 de febrero al 5 de marzo de 14:30 a 15:30 horas<\/strong><\/p>\n<p>Profesor: David Romero<\/p>\n<p>CURSO DE TANGOS DE M\u00c1LAGA \/ NIVEL MEDIO-BAJO<\/p>\n<p>130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/vanessa-coloma.png\" alt=\"Vanessa Coloma\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 28 de febrero al 2 de marzo de 15:30 a 16:30 horas<\/strong><\/p>\n<p>Profesora: Vanessa Coloma<\/p>\n<p>CURSO DE TIENTOS \/ NIVEL MEDIO<\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/vanessa-coloma.png\" alt=\"Vanessa Coloma\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 28 de febrero al 2 de marzo de 16:30 a\u00a0<\/strong><\/p>\n<p><strong>17:30 horas<\/strong><\/p>\n<p>Profesora: Vanessa Coloma<\/p>\n<p>CURSO DE TANGOS \/ NIVEL MEDIO<\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/la-truco.png\" alt=\"La Truco\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 28 de febrero al 5 de marzo de 17:30 a 18:30 horas<\/strong><\/p>\n<p>Profesora: La Truco<\/p>\n<p>CURSO DE T\u00c9CNICA CORPORAL \/ MULTINIVEL<\/p>\n<p>130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/la-truco.png\" alt=\"La Truco\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 28 de febrero al 5 de marzo de 18:30 a\u00a0<\/strong><\/p>\n<p><strong>19:30 horas<\/strong><\/p>\n<p>Profesora: La Truco<\/p>\n<p>CURSO DE TIENTOS \/ NIVEL MEDIO<\/p>\n<p>130\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/guadalupe-torres.png\" alt=\"Guadalupe Torres\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 3 al 5 de marzo de 9:30 a 11:00 horas<\/strong><\/p>\n<p>Profesora: Guadalupe Torres<\/p>\n<p>CURSO DE TANGOS \/ NIVEL MEDIO-BAJO<\/p>\n<p>120\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/guadalupe-torres.png\" alt=\"Guadalupe Torres\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 3 al 5 de marzo de 11:00 a 12:30 horas<\/strong><\/p>\n<p>Profesora: Guadalupe Torres<\/p>\n<p>CURSO DE SOLE\u00c1 POR BULER\u00cdAS \/ NIVEL MEDIO-ALTO<\/p>\n<p>120\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/chiqui-de-jere.png\" alt=\"Chiqui de Jerez\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 3 al 5 de marzo de 16:00 a 17:00 horas<\/strong><\/p>\n<p>Profesora:\u00a0Chiqui de Jerez<\/p>\n<p>CURSO DE BULER\u00cdAS \/ MULTINIVEL<\/p>\n<p>70\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/chiqui-de-jere.png\" alt=\"Chiqui de Jerez\" width=\"200\" height=\"182\" \/><\/p>\n<p class=\"azul\"><strong><br \/>\nMasterclass 4 y 5 de marzo de 12:00 a 13:00\u00a0<\/strong><strong>horas<\/strong><\/p>\n<p>Profesora:\u00a0Chiqui de Jerez<\/p>\n<p>CURSO DE BULER\u00cdAS DE JEREZ \/ MULTINIVEL<\/p>\n<p>50\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/antonio-canales.png\" alt=\"Antonio Canales\" width=\"200\" height=\"182\" \/><\/p>\n<p><strong><br \/>\nDel 6 al 8 de marzo de 12:00 a 13:30 horas<\/strong><\/p>\n<p>Profesor:\u00a0Antonio Canales<\/p>\n<p>CURSO DE JALEOS EXTREME\u00d1OS \/ MULTINIVEL<\/p>\n<p>120\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/moises-navarro.png\" alt=\"Mois\u00e9s Navarro\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 6 al 8 de marzo de 13:30 a 14:30 horas<\/strong><\/p>\n<p>Profesor:\u00a0Mois\u00e9s Navarro<\/p>\n<p>CURSO DE BULER\u00cdAS \/ NIVEL MEDIO-BAJO<\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"article-bg\">\n<div class=\"article-content\">\n<div class=\"span12 modern_style\">\n<div class=\"recentpost-content\">\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/moises-navarro.png\" alt=\"Mois\u00e9s Navarro\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 6 al 8 de marzo de\u00a0<\/strong><\/p>\n<p><strong>14:30 a 15:30 horas<\/strong><\/p>\n<p>Profesor:\u00a0Mois\u00e9s Navarro<\/p>\n<p>CURSO DE MARTINETE \/ NIVEL MEDIO<\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/carmen-la-talegona.png\" alt=\"Carmen La Talegona\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 6 al 8 de marzo de 9:00 a 10:30 horas<\/strong><\/p>\n<p>Profesora: Carmen La Talegona<\/p>\n<p>CURSO DE GUAJIRA CON ABANICO \/ NIVEL MEDIO-BAJO<\/p>\n<p>120\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/carmen-la-talegona.png\" alt=\"Carmen La Talegona\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 6 al 8 de marzo de 10:30 a 12:00 horas<\/strong><\/p>\n<p>Profesora: Carmen La Talegona<\/p>\n<p>CURSO DE SEGUIRILLAS (optativo con casta\u00f1uelas) \/ NIVEL MEDIO<\/p>\n<p>120\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/fabiola-barba.png\" alt=\"Fabiola Barba\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 6 al 8 de marzo de 10:00 a 11:00 horas<\/strong><\/p>\n<p>Profesora: Fabiola Barba<\/p>\n<p>CURSO DE BULER\u00cdAS \/ NIVEL MEDIO-BAJO<\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/fabiola-barba.png\" alt=\"Fabiola Barba\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 6 al 8 de marzo de 11:00 a 12:00 horas<\/strong><\/p>\n<p>Profesora: Fabiola Barba<\/p>\n<p>CURSO DE ALEGR\u00cdAS \/ NIVEL MEDIO<\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/rocio-romero.png\" alt=\"Roc\u00edo Romero\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 6 al 8 de marzo de<br \/>\n<\/strong><strong>12:00 a 13:00 horas<\/strong><\/p>\n<p>Profesora: Roc\u00edo Romero<\/p>\n<p>CURSO DE TANGOS \/ NIVEL MEDIO-BAJO<\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/rocio-romero.png\" alt=\"Roc\u00edo Romero\" width=\"200\" height=\"182\" \/><strong><br \/>\nDel 6 al 8 de marzo de 13:00 a 14:00 horas<\/strong><\/p>\n<p>Profesora: Roc\u00edo Romero<\/p>\n<p>CURSO DE BULER\u00cdAS \/ NIVEL MEDIO-BAJO<\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<figure style=\"width: 200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/carlos-carbonell.png\" alt=\"Carlos Carbonell\" width=\"200\" height=\"182\" \/><figcaption class=\"wp-caption-text\">Carlos Carbonell<\/figcaption><\/figure>\n<p><strong><br \/>\nDel 6 al 8 de marzo de 14:00 a <\/strong><strong>15:00 horas<\/strong><\/p>\n<p>Profesor: Carlos Carbonell<\/p>\n<p>CURSO DE BULER\u00cdAS \/ NIVEL MEDIO-BAJO<\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<figure style=\"width: 200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/carlos-carbonell.png\" alt=\"Carlos Carbonell\" width=\"200\" height=\"182\" \/><figcaption class=\"wp-caption-text\">Carlos Carbonell<\/figcaption><\/figure>\n<p><strong><br \/>\nDel 6 al 8 de marzo de 15:00 a 16:00 horas<\/strong><\/p>\n<p>Profesor: Carlos Carbonell<\/p>\n<p>CURSO DE CA\u00d1AS \/ NIVEL MEDIO-ALTO<\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_span12 wpb_column column_container\" style=\"text-align: center;\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<figure style=\"width: 200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/salome-ramirez.png\" alt=\"Salom\u00e9 Ram\u00edrez\" width=\"200\" height=\"182\" \/><figcaption class=\"wp-caption-text\">Salom\u00e9 Ram\u00edrez<\/figcaption><\/figure>\n<p><strong><br \/>\nDel 6 al 8 de marzo de 16:00 a\u00a0<\/strong><\/p>\n<p><strong>17:00 horas<\/strong><\/p>\n<p>Profesor: Salom\u00e9 Ram\u00edrez<\/p>\n<p>CURSO DE ALEGR\u00cdAS \/ NIVEL MEDIO-BAJO<\/p>\n<p>90\u20ac<\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"wpb_row vc_row-fluid\">\n<div class=\"vc_span12 wpb_column column_container\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \" style=\"text-align: left;\">\n<div class=\"wpb_wrapper\">\n<figure style=\"width: 200px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.chiquidejere.com\/wp-content\/uploads\/2024\/09\/salome-ramirez.png\" alt=\"Salom\u00e9 Ram\u00edrez\" width=\"200\" height=\"182\" \/><figcaption class=\"wp-caption-text\">Salom\u00e9 Ram\u00edrez<\/figcaption><\/figure>\n<p style=\"text-align: center;\"><strong><br \/>\nDel 6 al 8 de marzo de 17:00 a 18:00 horas<\/strong><\/p>\n<p style=\"text-align: center;\">Profesor: Salom\u00e9 Ram\u00edrez<\/p>\n<p style=\"text-align: center;\">CURSO DE BULER\u00cdAS DE C\u00c1DIZ \/ NIVEL MEDIO<\/p>\n<p style=\"text-align: center;\">90\u20ac<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<hr \/>\n<hr \/>\n<hr \/>\n<figure id=\"attachment_78074\" aria-describedby=\"caption-attachment-78074\" style=\"width: 213px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-medium wp-image-78074\" src=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/jerez-centro-danza-cursos-festival-de-jerez-2025-213x300.webp\" alt=\"jerez-centro-danza-cursos-festival-de-jerez-2025.\" width=\"213\" height=\"300\" srcset=\"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/jerez-centro-danza-cursos-festival-de-jerez-2025-213x300.webp 213w, https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/jerez-centro-danza-cursos-festival-de-jerez-2025.webp 400w\" sizes=\"(max-width: 213px) 100vw, 213px\" \/><figcaption id=\"caption-attachment-78074\" class=\"wp-caption-text\">Centro de Baile Jerez . Festival 2025<\/figcaption><\/figure>\n<h1 style=\"text-align: center;\">Centro de Baile Jerez<\/h1>\n<p dir=\"auto\" style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/S8g3kDqo3xfUNYT37\">Como Llegar: C\/Velazquez, num. 24 &#8211; San Gines (Plg. San Benito)<\/a><br \/>\n<a href=\"tel:+34661722958\">Tel\u00e9fono y Fax: 0034 661 722 958<\/a><a title=\"Direcci\u00f3n de email para solicitar m\u00e1s informaci\u00f3n\" href=\"mailto:info@academiadebailejerez.com\"><br \/>\ninfo@academiadebailejerez.com<\/a><\/p>\n<p dir=\"auto\" style=\"text-align: center;\"><strong>TODOS LOS PARTICIPANTES TENDR\u00c1N ACCESO A LOS V\u00cdDEOS DE LAS CLASES DURANTE UN MES Y PODR\u00c1N REPETIR LAS CLASES GRABADAS CU\u00c1NTAS VECES QUIERAN.<\/strong><\/p>\n<hr \/>\n<h3 style=\"text-align: left;\"><strong>Especial Fin de Semana \u2013 Especial 22 y 23 de Febrero de 2025<\/strong><\/h3>\n<ul style=\"text-align: left;\">\n<li>\n<h4>Luisa Palicio<\/h4>\n<\/li>\n<\/ul>\n<p style=\"text-align: left;\"><strong>Curso de T\u00e9cnica pura<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:\u00a0<\/strong>Medio y Medio\/Alto<\/p>\n<p style=\"text-align: left;\"><strong>Horario:\u00a0<\/strong>10:00 \u2013 12:00<\/p>\n<p style=\"text-align: left;\"><strong>Precio:\u00a0<\/strong>100\u20ac presencial \/ 75\u20ac online<\/p>\n<p style=\"text-align: left;\"><strong>Curso de T\u00e9cnica de mant\u00f3n y abanico<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:\u00a0<\/strong>Medio y Medio\/Alto<\/p>\n<p style=\"text-align: left;\"><strong>Horario:\u00a0<\/strong>12:00 \u2013 13:00<\/p>\n<p style=\"text-align: left;\"><strong>Precio:\u00a0<\/strong>50\u20ac presencial \/ 40\u20ac online<\/p>\n<p style=\"text-align: left;\"><strong>Curso de Casta\u00f1uelas<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:\u00a0<\/strong>Medio y Medio\/Alto<\/p>\n<p style=\"text-align: left;\"><strong>Horario:\u00a0<\/strong>13:00 \u2013 14:00<\/p>\n<p style=\"text-align: left;\"><strong>Precio:\u00a0<\/strong>50\u20ac presencial \/ 40\u20ac online<\/p>\n<h4><strong>\u00a1Aprovecha nuestra oferta especial!<br \/>\n<\/strong><strong>Tres cursos con Luisa Palicio:\u00a0<\/strong>150\u20ac presencial \/ 110\u20ac online<\/h4>\n<ul style=\"text-align: left;\">\n<li>\n<h4>Cristina Otero<\/h4>\n<\/li>\n<\/ul>\n<p style=\"text-align: left;\"><strong>Curso de T\u00e9cnica pura<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:\u00a0<\/strong>Elemental e Intermedio<\/p>\n<p style=\"text-align: left;\"><strong>Horario:\u00a0<\/strong>10:00 \u2013 13:00<\/p>\n<p style=\"text-align: left;\"><strong>Precio:\u00a0<\/strong>130\u20ac presencial \/ 100\u20ac online<\/p>\n<p style=\"text-align: left;\"><strong>Curso de Casta\u00f1uelas<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:\u00a0<\/strong>Elemental<\/p>\n<p style=\"text-align: left;\"><strong>Horario:\u00a0<\/strong>13:00 \u2013 14:00<\/p>\n<p style=\"text-align: left;\"><strong>Precio:\u00a0<\/strong>50\u20ac presencial \/ 40\u20ac online<\/p>\n<hr \/>\n<h3 class=\"entry-title\" style=\"text-align: left;\">Del 24 al 28 de febrero del 2025<\/h3>\n<ul style=\"text-align: left;\">\n<li>\n<h4>Adela Campallo<\/h4>\n<\/li>\n<\/ul>\n<p style=\"text-align: left;\"><strong>Curso de Coreograf\u00eda por Romance<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:<\/strong>\u00a0Medio<\/p>\n<p style=\"text-align: left;\"><strong>Horario:<\/strong>\u00a010:00 \u2013 11:30<\/p>\n<p style=\"text-align: left;\"><strong>Precio:<\/strong>\u00a0160\u20ac presencial \/ 120\u20ac online<\/p>\n<p style=\"text-align: left;\"><strong>Curso de Coreograf\u00eda por Seguiriyas<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:<\/strong>\u00a0Medio\/Alto<\/p>\n<p style=\"text-align: left;\"><strong>Horario:<\/strong>\u00a011:45 \u2013 13:15<\/p>\n<p style=\"text-align: left;\"><strong>Precio:<\/strong>\u00a0160\u20ac presencial \/ 120\u20ac online<\/p>\n<h4><strong>\u00a1Aprovecha nuestra oferta especial!<br \/>\n<\/strong><strong>Dos cursos con Adela Campallo:<\/strong>\u00a0260\u20ac presencial \/ 220\u20ac online<\/h4>\n<ul style=\"text-align: left;\">\n<li>\n<h4>Marta de Troya<\/h4>\n<\/li>\n<\/ul>\n<p style=\"text-align: left;\"><strong>Curso de Coreograf\u00eda y T\u00e9cnica por Alegrias con Bata de Cola y Mant\u00f3n<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:<\/strong>\u00a0Medio\/Alto<\/p>\n<p style=\"text-align: left;\"><strong>Horario:<\/strong>\u00a013:15 \u2013 14:15<\/p>\n<p style=\"text-align: left;\"><strong>Precio:<\/strong>\u00a0160\u20ac presencial \/ 120\u20ac online<\/p>\n<p style=\"text-align: left;\"><strong>Curso de Coreograf\u00eda por Solea por Bulerias<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:<\/strong>\u00a0Medio<\/p>\n<p style=\"text-align: left;\"><strong>Horario:<\/strong>\u00a014:15 \u2013 15:45<\/p>\n<p style=\"text-align: left;\"><strong>Precio:<\/strong>\u00a0160\u20ac presencial \/ 120\u20ac online<\/p>\n<h4><strong>\u00a1Aprovecha nuestra oferta especial!<\/strong><br \/>\n<strong>Dos cursos con Marta de Troya:<\/strong>\u00a0260\u20ac presencial \/ 220\u20ac online<\/h4>\n<h4 dir=\"LTR\">\u00a0<b><\/b>OFERTA MUY ESPECIAL<br \/>\n<b><span lang=\"es\">Tres cursos durante la semana del 24 al 28 de febrero:\u00a0<\/span><\/b><b><\/b><b><\/b><b><\/b><b><span lang=\"es\">340\u20ac presencial \/ 300\u20ac online<\/span><\/b><\/h4>\n<hr \/>\n<ul style=\"text-align: left;\">\n<li>\n<h4>Cristina Otero<\/h4>\n<\/li>\n<\/ul>\n<p style=\"text-align: left;\"><strong>Curso de Coreograf\u00eda y T\u00e9cnica por Solea por Buler\u00edas y Buler\u00edas de Jerez<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:<\/strong>\u00a0Elemental<\/p>\n<p style=\"text-align: left;\"><strong>Horario:<\/strong>\u00a013:00 \u2013 14:30<\/p>\n<p style=\"text-align: left;\"><strong>Precio:<\/strong>\u00a0160\u20ac presencial \/ 120\u20ac online<\/p>\n<hr \/>\n<h3 class=\"entry-title\" style=\"text-align: left;\">Especial 1 y 2 de Marzo<\/h3>\n<ul style=\"text-align: left;\">\n<li>\n<h4>Mar\u00eda Juncal<\/h4>\n<\/li>\n<\/ul>\n<p style=\"text-align: left;\"><strong>Curso de T\u00e9cnica pura<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:\u00a0<\/strong>Medio y Medio\/Alto<\/p>\n<p style=\"text-align: left;\"><strong>Horario:\u00a0<\/strong>10:00 \u2013 13:00<\/p>\n<p style=\"text-align: left;\"><strong>Precio:\u00a0<\/strong>130\u20ac presencial \/ 100\u20ac online<\/p>\n<ul style=\"text-align: left;\">\n<li>\n<h4>Cristina Otero<\/h4>\n<\/li>\n<\/ul>\n<p style=\"text-align: left;\"><strong>Curso de T\u00e9cnica pura<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:\u00a0<\/strong>Elemental e Intermedio<\/p>\n<p style=\"text-align: left;\"><strong>Horario:\u00a0<\/strong>10:00 \u2013 13:00<\/p>\n<p style=\"text-align: left;\"><strong>Precio:\u00a0<\/strong>130\u20ac presencial \/ 100\u20ac online<\/p>\n<p style=\"text-align: left;\"><strong>Curso de Casta\u00f1uelas<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:\u00a0<\/strong>Elemental<\/p>\n<p style=\"text-align: left;\"><strong>Horario:\u00a0<\/strong>13:00 \u2013 14:00<\/p>\n<p style=\"text-align: left;\"><strong>Precio:\u00a0<\/strong>50\u20ac presencial \/ 40\u20ac online<\/p>\n<h4><strong>\u00a1Aprovecha nuestra oferta especial!<br \/>\n<\/strong><strong>Dos cursos con Cristina Otero:\u00a0<\/strong>140\u20ac presencial \/ 110\u20ac online<\/h4>\n<hr \/>\n<h3 style=\"text-align: left;\"><strong>Del 3 al 7 de marzo del 2025<\/strong><\/h3>\n<ul style=\"text-align: left;\">\n<li>\n<h4>Karime Amaya<\/h4>\n<\/li>\n<\/ul>\n<p style=\"text-align: left;\"><strong>Curso de Coreograf\u00eda por Alegr\u00edas<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:\u00a0<\/strong>Medio<\/p>\n<p style=\"text-align: left;\"><strong>Horario:\u00a0<\/strong>9:30 \u2013 11:00<\/p>\n<p style=\"text-align: left;\"><strong>Precio:\u00a0<\/strong>160\u20ac presencial \/ 120\u20ac online<\/p>\n<p style=\"text-align: left;\"><strong>Curso de Coreograf\u00eda por Solea<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:\u00a0<\/strong>Medio\/Alto<\/p>\n<p style=\"text-align: left;\"><strong>Horario:\u00a0<\/strong>11:15 \u2013 12:45<\/p>\n<p style=\"text-align: left;\"><strong>Precio:\u00a0<\/strong>160\u20ac presencial \/ 120\u20ac online<\/p>\n<p style=\"text-align: left;\"><strong>\u00a1Aprovecha nuestra oferta especial!<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Dos cursos con Karime Amaya:\u00a0<\/strong>260\u20ac presencial \/ 220\u20ac online<\/p>\n<ul style=\"text-align: left;\">\n<li>\n<h4>Marta de Troya<\/h4>\n<\/li>\n<\/ul>\n<p style=\"text-align: left;\"><strong>Curso de Coreograf\u00eda y T\u00e9cnica por Ca\u00f1a con Bata de Cola y Mant\u00f3n<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:\u00a0<\/strong>Medio<\/p>\n<p style=\"text-align: left;\"><strong>Horario:\u00a0<\/strong>12:45 \u2013 13:45<\/p>\n<p style=\"text-align: left;\"><strong>Precio:\u00a0<\/strong>160\u20ac presencial \/ 120\u20ac online<\/p>\n<p style=\"text-align: left;\"><strong>Curso de Coreograf\u00eda por Tientos<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:\u00a0<\/strong>Medio<\/p>\n<p style=\"text-align: left;\"><strong>Horario:\u00a0<\/strong>14:00 \u2013 15:30<\/p>\n<p style=\"text-align: left;\"><strong>Precio:\u00a0<\/strong>160\u20ac presencial \/ 120\u20ac online<\/p>\n<p style=\"text-align: left;\"><strong>\u00a1<\/strong><strong>Aprovecha nuestra oferta especial!<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Dos cursos con Marta de Troya:\u00a0<\/strong>260\u20ac presencial \/ 220\u20ac online<\/p>\n<h4>OFERTA MUY ESPECIAL<\/h4>\n<h4><strong>Tres cursos durante la semana del 3 al 7 de marzo:\u00a0<\/strong><strong>340\u20ac presencial \/ 300\u20ac online<\/strong><\/h4>\n<ul style=\"text-align: left;\">\n<li>\n<h4>Cristina Otero<\/h4>\n<\/li>\n<\/ul>\n<p style=\"text-align: left;\"><strong>Curso de Coreograf\u00eda y T\u00e9cnica por Garrotin y Buler\u00edas de Jerez<\/strong><\/p>\n<p style=\"text-align: left;\"><strong>Nivel:\u00a0<\/strong>Elemental<\/p>\n<p style=\"text-align: left;\"><strong>Horario:\u00a0<\/strong>13:00 \u2013 14:30<\/p>\n<p style=\"text-align: left;\"><strong>Precio:\u00a0<\/strong>160\u20ac presencial \/ 120\u20ac online<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfTe has quedado sin plaza en la programaci\u00f3n oficial del Festival de Jerez 2025?<br \/>\nAqu\u00ed tienes todo el listado de cursos durante el Festival de Jerez.  Mas de 100 cursos y talleres. Desde 50\u20ac. <\/p>\n","protected":false},"author":56,"featured_media":78334,"comment_status":"open","ping_status":"closed","template":"","tags":[1102,1100,1052,1101],"mec_category":[477,472,1090],"mec_sponsor":[],"class_list":["post-78050","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-chiqui-de-jere","tag-cursos-festival-de-jerez-2025","tag-festival-de-jerez-2025","tag-patricia-ibanez","mec_category-baile","mec_category-festival","mec_category-festival-de-jerez-2025","pmpro-has-access"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u00bfTe has quedado sin plaza en la programaci\u00f3n oficial del Festival de Jerez 2025? Aqu\u00ed tienes todo el listado de cursos durante el Festival de Jerez. Mas de 100 cursos y talleres. Desde 50\u20ac.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Patri Manes\"\/>\n\t<meta name=\"google-site-verification\" content=\"qp99EvZ7gDO9YjsGQX1WTdzaSSjVeGG9OIkeeRYaZAU\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/expoflamenco.com\/agenda\/eventos\/cursos-durante-festival-de-jerez\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/cursos-durante-festival-de-jerez\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/#listItem\",\"name\":\"Eventos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/#listItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/festival-de-jerez-2025\\\/#listItem\",\"name\":\"festival-de-jerez-2025\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/festival-de-jerez-2025\\\/#listItem\",\"position\":3,\"name\":\"festival-de-jerez-2025\",\"item\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/festival-de-jerez-2025\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/cursos-durante-festival-de-jerez\\\/#listItem\",\"name\":\"Cursos durante Festival de Jerez\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/#listItem\",\"name\":\"Eventos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/cursos-durante-festival-de-jerez\\\/#listItem\",\"position\":4,\"name\":\"Cursos durante Festival de Jerez\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/tag\\\/festival-de-jerez-2025\\\/#listItem\",\"name\":\"festival-de-jerez-2025\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#organization\",\"name\":\"Agenda ExpoFlamenco\",\"description\":\"Agenda Flamenca\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/expoflamenco\\\/\",\"https:\\\/\\\/x.com\\\/expo_flamenco\",\"https:\\\/\\\/www.instagram.com\\\/expoflamenco\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@expoflamenco\",\"https:\\\/\\\/www.youtube.com\\\/expoflamenco\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/expoflamenco\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/#author\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/\",\"name\":\"Patri Manes\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/cursos-durante-festival-de-jerez\\\/#authorImage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Imagen-de-WhatsApp-2024-09-12-a-las-12.38.47_89f61861-150x150.jpg\",\"width\":96,\"height\":96,\"caption\":\"Patri Manes\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/cursos-durante-festival-de-jerez\\\/#webpage\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/cursos-durante-festival-de-jerez\\\/\",\"name\":\"Cursos durante Festival de Jerez - Agenda ExpoFlamenco\",\"description\":\"\\u00bfTe has quedado sin plaza en la programaci\\u00f3n oficial del Festival de Jerez 2025? Aqu\\u00ed tienes todo el listado de cursos durante el Festival de Jerez. Mas de 100 cursos y talleres. Desde 50\\u20ac.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/cursos-durante-festival-de-jerez\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/author\\\/patriciamanes\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2024\\\/12\\\/CABECERA-festival-2025-cursos-1.webp\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/cursos-durante-festival-de-jerez\\\/#mainImage\",\"width\":800,\"height\":400,\"caption\":\"Festival de Jerez 2025 -Cursos en Jerez\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/eventos\\\/cursos-durante-festival-de-jerez\\\/#mainImage\"},\"datePublished\":\"2025-02-20T09:10:52+01:00\",\"dateModified\":\"2025-03-03T18:40:58+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#website\",\"url\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/\",\"name\":\"Agenda ExpoFlamenco\",\"description\":\"Agenda Flamenca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/expoflamenco.com\\\/agenda\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<script>(function(w,d,s,l,i){w[l]=w[l]||[];w[l].push({'gtm.start': new Date().getTime(),event:'gtm.js'});var f=d.getElementsByTagName(s)[0], j=d.createElement(s),dl=l!='dataLayer'?'&l='+l:'';j.async=true;j.src='https:\/\/www.googletagmanager.com\/gtm.js?id='+i+dl;f.parentNode.insertBefore(j,f);})(window,document,'script','dataLayer',\"GTM-N28N9JJ\");<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Cursos durante Festival de Jerez - Agenda ExpoFlamenco<\/title>\n\n","aioseo_head_json":{"title":"Cursos durante Festival de Jerez - Agenda ExpoFlamenco","description":"\u00bfTe has quedado sin plaza en la programaci\u00f3n oficial del Festival de Jerez 2025? Aqu\u00ed tienes todo el listado de cursos durante el Festival de Jerez. Mas de 100 cursos y talleres. Desde 50\u20ac.","canonical_url":"https:\/\/expoflamenco.com\/agenda\/eventos\/cursos-durante-festival-de-jerez\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"qp99EvZ7gDO9YjsGQX1WTdzaSSjVeGG9OIkeeRYaZAU","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/cursos-durante-festival-de-jerez\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda#listItem","position":1,"name":"Home","item":"https:\/\/expoflamenco.com\/agenda","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/#listItem","name":"Eventos"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/#listItem","position":2,"name":"Eventos","item":"https:\/\/expoflamenco.com\/agenda\/eventos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/tag\/festival-de-jerez-2025\/#listItem","name":"festival-de-jerez-2025"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/tag\/festival-de-jerez-2025\/#listItem","position":3,"name":"festival-de-jerez-2025","item":"https:\/\/expoflamenco.com\/agenda\/tag\/festival-de-jerez-2025\/","nextItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/cursos-durante-festival-de-jerez\/#listItem","name":"Cursos durante Festival de Jerez"},"previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/#listItem","name":"Eventos"}},{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/cursos-durante-festival-de-jerez\/#listItem","position":4,"name":"Cursos durante Festival de Jerez","previousItem":{"@type":"ListItem","@id":"https:\/\/expoflamenco.com\/agenda\/tag\/festival-de-jerez-2025\/#listItem","name":"festival-de-jerez-2025"}}]},{"@type":"Organization","@id":"https:\/\/expoflamenco.com\/agenda\/#organization","name":"Agenda ExpoFlamenco","description":"Agenda Flamenca","url":"https:\/\/expoflamenco.com\/agenda\/","sameAs":["https:\/\/www.facebook.com\/expoflamenco\/","https:\/\/x.com\/expo_flamenco","https:\/\/www.instagram.com\/expoflamenco\/","https:\/\/www.tiktok.com\/@expoflamenco","https:\/\/www.youtube.com\/expoflamenco","https:\/\/www.linkedin.com\/company\/expoflamenco"]},{"@type":"Person","@id":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/#author","url":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/","name":"Patri Manes","image":{"@type":"ImageObject","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/cursos-durante-festival-de-jerez\/#authorImage","url":"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/2024\/09\/Imagen-de-WhatsApp-2024-09-12-a-las-12.38.47_89f61861-150x150.jpg","width":96,"height":96,"caption":"Patri Manes"}},{"@type":"WebPage","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/cursos-durante-festival-de-jerez\/#webpage","url":"https:\/\/expoflamenco.com\/agenda\/eventos\/cursos-durante-festival-de-jerez\/","name":"Cursos durante Festival de Jerez - Agenda ExpoFlamenco","description":"\u00bfTe has quedado sin plaza en la programaci\u00f3n oficial del Festival de Jerez 2025? Aqu\u00ed tienes todo el listado de cursos durante el Festival de Jerez. Mas de 100 cursos y talleres. Desde 50\u20ac.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/expoflamenco.com\/agenda\/#website"},"breadcrumb":{"@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/cursos-durante-festival-de-jerez\/#breadcrumblist"},"author":{"@id":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/#author"},"creator":{"@id":"https:\/\/expoflamenco.com\/agenda\/author\/patriciamanes\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/expoflamenco.com\/agenda\/wp-content\/uploads\/sites\/22\/2024\/12\/CABECERA-festival-2025-cursos-1.webp","@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/cursos-durante-festival-de-jerez\/#mainImage","width":800,"height":400,"caption":"Festival de Jerez 2025 -Cursos en Jerez"},"primaryImageOfPage":{"@id":"https:\/\/expoflamenco.com\/agenda\/eventos\/cursos-durante-festival-de-jerez\/#mainImage"},"datePublished":"2025-02-20T09:10:52+01:00","dateModified":"2025-03-03T18:40:58+01:00"},{"@type":"WebSite","@id":"https:\/\/expoflamenco.com\/agenda\/#website","url":"https:\/\/expoflamenco.com\/agenda\/","name":"Agenda ExpoFlamenco","description":"Agenda Flamenca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/expoflamenco.com\/agenda\/#organization"}}]}},"aioseo_meta_data":{"post_id":"78050","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-10-09 01:51:06","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2025-05-07 11:47:36","updated":"2025-11-26 22:39:29"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/agenda\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/agenda\/eventos\/\" title=\"Eventos\">Eventos<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/expoflamenco.com\/agenda\/tag\/festival-de-jerez-2025\/\" title=\"festival-de-jerez-2025\">festival-de-jerez-2025<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tCursos durante Festival de Jerez\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/expoflamenco.com\/agenda"},{"label":"Eventos","link":"https:\/\/expoflamenco.com\/agenda\/eventos\/"},{"label":"festival-de-jerez-2025","link":"https:\/\/expoflamenco.com\/agenda\/tag\/festival-de-jerez-2025\/"},{"label":"Cursos durante Festival de Jerez","link":"https:\/\/expoflamenco.com\/agenda\/eventos\/cursos-durante-festival-de-jerez\/"}],"_links":{"self":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec-events\/78050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/comments?post=78050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/media\/78334"}],"wp:attachment":[{"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/media?parent=78050"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/tags?post=78050"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec_category?post=78050"},{"taxonomy":"mec_sponsor","embeddable":true,"href":"https:\/\/expoflamenco.com\/agenda\/wp-json\/wp\/v2\/mec_sponsor?post=78050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}